{"id":1823,"date":"2020-06-08T11:51:16","date_gmt":"2020-06-08T09:51:16","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1823"},"modified":"2020-06-08T11:51:16","modified_gmt":"2020-06-08T09:51:16","slug":"arriva-lacqua-al-parco-di-vigna-grande","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/","title":{"rendered":"ARRIVA L&#8217;ACQUA AL PARCO DI VIGNA GRANDE"},"content":{"rendered":"<p>Sono in corso i lavori per il posizionamento di una condotta utile a portare l&#8217;acqua, dal pozzo realizzato nell&#8217;area del Cimitero Comunale, al Parco di Vigna Grande.<br \/>\n&#8220;Questo intervento finalmente permetter\u00e0 di poter irrigare adeguatamente l&#8217;area del Parco pubblico&#8221; dichiara il Consigliere incaricato all&#8217;Ambiente Domenico Cagnucci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono in corso i lavori per il posizionamento di una condotta utile a portare l&#8217;acqua, dal pozzo realizzato nell&#8217;area del Cimitero Comunale, al Parco di Vigna Grande. &#8220;Questo intervento finalmente [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":1824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARRIVA L&#039;ACQUA AL PARCO DI VIGNA GRANDE - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARRIVA L&#039;ACQUA AL PARCO DI VIGNA GRANDE - Formello\" \/>\n<meta property=\"og:description\" content=\"Sono in corso i lavori per il posizionamento di una condotta utile a portare l&#8217;acqua, dal pozzo realizzato nell&#8217;area del Cimitero Comunale, al Parco di Vigna Grande. &#8220;Questo intervento finalmente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T09:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"ARRIVA L&#8217;ACQUA AL PARCO DI VIGNA GRANDE\",\"datePublished\":\"2020-06-08T09:51:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/\"},\"wordCount\":53,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/\",\"name\":\"ARRIVA L'ACQUA AL PARCO DI VIGNA GRANDE - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg\",\"datePublished\":\"2020-06-08T09:51:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/08\\\/arriva-lacqua-al-parco-di-vigna-grande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ARRIVA L&#8217;ACQUA AL PARCO DI VIGNA GRANDE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARRIVA L'ACQUA AL PARCO DI VIGNA GRANDE - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/","og_locale":"it_IT","og_type":"article","og_title":"ARRIVA L'ACQUA AL PARCO DI VIGNA GRANDE - Formello","og_description":"Sono in corso i lavori per il posizionamento di una condotta utile a portare l&#8217;acqua, dal pozzo realizzato nell&#8217;area del Cimitero Comunale, al Parco di Vigna Grande. &#8220;Questo intervento finalmente [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-08T09:51:16+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"ARRIVA L&#8217;ACQUA AL PARCO DI VIGNA GRANDE","datePublished":"2020-06-08T09:51:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/"},"wordCount":53,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/","url":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/","name":"ARRIVA L'ACQUA AL PARCO DI VIGNA GRANDE - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg","datePublished":"2020-06-08T09:51:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-06-06-at-10.48.50-copia-2.jpeg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/08\/arriva-lacqua-al-parco-di-vigna-grande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"ARRIVA L&#8217;ACQUA AL PARCO DI VIGNA GRANDE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1823"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1823\/revisions"}],"predecessor-version":[{"id":1825,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1823\/revisions\/1825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1824"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}