{"id":1845,"date":"2020-06-16T13:31:25","date_gmt":"2020-06-16T11:31:25","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1845"},"modified":"2020-06-16T13:31:25","modified_gmt":"2020-06-16T11:31:25","slug":"emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/","title":{"rendered":"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#8217; BISOGNOSI &#8211; OPERAZIONE UNA GOCCIA NELL&#8217;OCEANO"},"content":{"rendered":"<p>Il Sindaco <strong>Gian Filippo Santi<\/strong> comunica che da ieri ripresa la consegna di pacchi con generi alimentari ai cittadini di Formello pi\u00f9 bisognosi. I nuclei familiari beneficiari dell&#8217;iniziativa sono stati individuati dall&#8217;ufficio Politiche sociali.<br \/>\nL\u2019operazione \u2013 coordinata dall\u2019Assessore alla Protezione civile <strong>Giancarlo Zuccheri<\/strong> e dal Consigliere delegato al Sociale <strong>Domenico Cagnucci<\/strong> \u00e8 coordinata dalla Protezione civile di Formello, mentre i pacchi vengono consegnati a nome del Comune dalla Cooperativa Alicenova.<br \/>\n&#8220;Prosegue l&#8217;intervento dell&#8217;Amministrazione &#8221; comunica il Sindaco &#8220;per far fronte alle esigenze delle fasce pi\u00f9 deboli della nostra popolazione.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sindaco Gian Filippo Santi comunica che da ieri ripresa la consegna di pacchi con generi alimentari ai cittadini di Formello pi\u00f9 bisognosi. I nuclei familiari beneficiari dell&#8217;iniziativa sono stati [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":1846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-1845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#039; BISOGNOSI - OPERAZIONE UNA GOCCIA NELL&#039;OCEANO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#039; BISOGNOSI - OPERAZIONE UNA GOCCIA NELL&#039;OCEANO - Formello\" \/>\n<meta property=\"og:description\" content=\"Il Sindaco Gian Filippo Santi comunica che da ieri ripresa la consegna di pacchi con generi alimentari ai cittadini di Formello pi\u00f9 bisognosi. I nuclei familiari beneficiari dell&#8217;iniziativa sono stati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-16T11:31:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#8217; BISOGNOSI &#8211; OPERAZIONE UNA GOCCIA NELL&#8217;OCEANO\",\"datePublished\":\"2020-06-16T11:31:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/\"},\"wordCount\":104,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/\",\"name\":\"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU' BISOGNOSI - OPERAZIONE UNA GOCCIA NELL'OCEANO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg\",\"datePublished\":\"2020-06-16T11:31:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/06\\\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/06\\\/16\\\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#8217; BISOGNOSI &#8211; OPERAZIONE UNA GOCCIA NELL&#8217;OCEANO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU' BISOGNOSI - OPERAZIONE UNA GOCCIA NELL'OCEANO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/","og_locale":"it_IT","og_type":"article","og_title":"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU' BISOGNOSI - OPERAZIONE UNA GOCCIA NELL'OCEANO - Formello","og_description":"Il Sindaco Gian Filippo Santi comunica che da ieri ripresa la consegna di pacchi con generi alimentari ai cittadini di Formello pi\u00f9 bisognosi. I nuclei familiari beneficiari dell&#8217;iniziativa sono stati [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-16T11:31:25+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#8217; BISOGNOSI &#8211; OPERAZIONE UNA GOCCIA NELL&#8217;OCEANO","datePublished":"2020-06-16T11:31:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/"},"wordCount":104,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/","url":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/","name":"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU' BISOGNOSI - OPERAZIONE UNA GOCCIA NELL'OCEANO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg","datePublished":"2020-06-16T11:31:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/06\/WhatsApp-Image-2020-03-17-at-12.22.44-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/06\/16\/emergenza-coronavirus-prosegue-la-consegna-di-generi-alimentari-ai-piu-bisognosi-operazione-una-goccia-nelloceano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"EMERGENZA CORONAVIRUS -PROSEGUE LA CONSEGNA DI GENERI ALIMENTARI AI PIU&#8217; BISOGNOSI &#8211; OPERAZIONE UNA GOCCIA NELL&#8217;OCEANO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1845"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1845\/revisions"}],"predecessor-version":[{"id":1847,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1845\/revisions\/1847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1846"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}