{"id":18613,"date":"2021-09-17T09:50:11","date_gmt":"2021-09-17T07:50:11","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=18613"},"modified":"2021-09-17T09:50:11","modified_gmt":"2021-09-17T07:50:11","slug":"il-mav-di-formello-alla-fiera-della-piccola-editoria","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/","title":{"rendered":"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA"},"content":{"rendered":"<p>Da oggi, venerd\u00ec 17, fino al 19 settembre il Museo dell\u2019Agro Veientano di Formello partecipa, con il Sistema Mussale MANEAT, alla Fiera della Piccola Editoria dei Beni Culturali, II Edizione, che si svolge ad Albano Laziale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da oggi, venerd\u00ec 17, fino al 19 settembre il Museo dell\u2019Agro Veientano di Formello partecipa, con il Sistema Mussale MANEAT, alla Fiera della Piccola Editoria dei Beni Culturali, II Edizione, [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":18614,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-18613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA - Formello\" \/>\n<meta property=\"og:description\" content=\"Da oggi, venerd\u00ec 17, fino al 19 settembre il Museo dell\u2019Agro Veientano di Formello partecipa, con il Sistema Mussale MANEAT, alla Fiera della Piccola Editoria dei Beni Culturali, II Edizione, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T07:50:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/09\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA\",\"datePublished\":\"2021-09-17T07:50:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/\"},\"wordCount\":44,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/09\\\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/\",\"name\":\"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/09\\\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg\",\"datePublished\":\"2021-09-17T07:50:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/09\\\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/09\\\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg\",\"width\":1080,\"height\":1542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/09\\\/17\\\/il-mav-di-formello-alla-fiera-della-piccola-editoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/","og_locale":"it_IT","og_type":"article","og_title":"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA - Formello","og_description":"Da oggi, venerd\u00ec 17, fino al 19 settembre il Museo dell\u2019Agro Veientano di Formello partecipa, con il Sistema Mussale MANEAT, alla Fiera della Piccola Editoria dei Beni Culturali, II Edizione, [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-09-17T07:50:11+00:00","og_image":[{"width":1080,"height":1542,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/09\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA","datePublished":"2021-09-17T07:50:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/"},"wordCount":44,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/09\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/","url":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/","name":"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/09\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg","datePublished":"2021-09-17T07:50:11+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/09\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/09\/WhatsApp-Image-2021-09-17-at-06.23.15.jpeg","width":1080,"height":1542},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2021\/09\/17\/il-mav-di-formello-alla-fiera-della-piccola-editoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"IL MAV DI FORMELLO ALLA FIERA DELLA PICCOLA EDITORIA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=18613"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18613\/revisions"}],"predecessor-version":[{"id":18615,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18613\/revisions\/18615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/18614"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=18613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=18613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=18613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}