{"id":18743,"date":"2021-11-22T13:34:14","date_gmt":"2021-11-22T12:34:14","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=18743"},"modified":"2021-11-22T13:40:55","modified_gmt":"2021-11-22T12:40:55","slug":"giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/","title":{"rendered":"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE &#8211; TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO"},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Il <strong>Comune di Formello<\/strong> aderisce come ogni anno al <strong>25 novembre \u2013 Giornata Internazionale per l\u2019Eliminazione della Violenza contro le Donne<\/strong>, attraverso una serie di iniziative di sensibilizzazione sulle Pari Opportunit\u00e0.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Il Sindaco<strong> Gian Filippo Santi<\/strong> e l\u2019Assessore alle Pari opportunit\u00e0 <strong>Roberta Bellotti<\/strong> sottolineano l\u2019impegno quotidiano del Comune sulla tematica, ricordando la presenza del Centro Antiviolenza Galassia, il Piano delle Azioni Positive all\u2019interno dell\u2019amministrazione comunale contro le discriminazioni di genere sul luogo di lavoro, il progetto Difesa a scuola indirizzato ai giovani della scuola secondaria di primo grado, la redazione del foglio informativo \u201cNoi siamo pari\u201d per la diffusione della cultura della parit\u00e0 di genere.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">L\u2019invito delle Istituzioni alla cittadinanza \u00e8 anche quello di aderire alle iniziative previste per la Giornata, perch\u00e9 FORMELLO DICE NO ALLA VIOLENZA CONTRO LE DONNE!<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><strong>25 novembre<\/strong><\/div>\n<div dir=\"auto\"><strong>Tingiamo Formello di Rosso<\/strong><\/div>\n<div dir=\"auto\">In Piazza San Lorenzo verr\u00e0 allestita la simbolica panchina rossa per commemorare le donne vittime di violenza. I cittadini sono inoltre invitati a mettere un semplice nastro rosso, sulle porte, sulle finestre e sui balconi di abitazioni, nelle vetrine dei negozi e degli esercizi commerciali.<\/div>\n<div dir=\"auto\">Palazzo Chigi sar\u00e0 illuminato in occasione dell&#8217;evento.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><strong>Bibliomelograno &#8211; Centro Civico Le Rughe<\/strong><\/div>\n<div dir=\"auto\">Alle ore 16, 30 convegno con Lucia Goracci in collegamento da Istanbul ed altri relatori in presenza con reading da &#8220;Donne di sabbia&#8221; di Laura Cappellazzo.<\/div>\n<div dir=\"auto\">Modera Giovan Battista Brunori<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><strong>28 novembre<\/strong><\/div>\n<div dir=\"auto\"><strong>Convegno Dalla Violenza sulle donne al femminicidio dalle ore 10 alle 17, presso il Teatro Comunale J. P. Velly.<\/strong><\/div>\n<div dir=\"auto\">Organizzato dal Lions Club Sacrofano-Formello, in collaborazione con il Comune<\/div>\n<div dir=\"auto\">Oltre ai saluti istituzionali da parte del Sindaco e dell\u2019Assessore Roberta Bellotti, ci saranno numerosi interventi (riportati in dettaglio nella locandina allegata) di scrittori ed esperti, impegnati sul tema della lotta e prevenzione della violenza sulle donne.<\/div>\n<div dir=\"auto\">Modera il dibattito la giornalista RAI Roberta Ammendola.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Le iniziative si svolgono con il<strong> Patrocinio dell&#8217; <a class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl q66pz984 gpro0wi8 b1v8xokw\" role=\"link\" href=\"https:\/\/www.facebook.com\/ancilazio\/?__cft__[0]=AZXNU1WLoabTi3cErbe13Gle7HkTkoH3LoY7DxN_206QTrNYsFvI4zKCXIzcNqNINdIRo2cQkkGHgzA7MY8WbHnseoEk3iL7f51vQtmfUBkCHlZyYSH-0B_YuROhZj_z4tC7VU1rJqg2CfmWEUEr0Nrez7ixfVAA3szqy2DurNdVUg&amp;__tn__=kK-R\"><span class=\"nc684nl6\">ANCI Lazio<\/span><\/a> e la Consulta delle Donne Amministratrici.<\/strong><\/div>\n<\/div>\n\t\t\t<h4>Inizio<\/h4>\n<p>25\/11\/2021 00:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>28\/11\/2021 00:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Formello, Roma Capitale, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.082521,12.400273&z=6&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18750\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/25novembre2021.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/25novembre2021.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>25novembre2021<\/a><\/li>\n<li><a id=\"wpba_attachment_list_18751\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/melograno.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/melograno.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>melograno<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Formello aderisce come ogni anno al 25 novembre \u2013 Giornata Internazionale per l\u2019Eliminazione della Violenza contro le Donne, attraverso una serie di iniziative di sensibilizzazione sulle Pari [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":18744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-18743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE - TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE - TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO - Formello\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Formello aderisce come ogni anno al 25 novembre \u2013 Giornata Internazionale per l\u2019Eliminazione della Violenza contro le Donne, attraverso una serie di iniziative di sensibilizzazione sulle Pari [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-22T12:34:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-22T12:40:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/locandina-25novembre-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE &#8211; TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO\",\"datePublished\":\"2021-11-22T12:34:14+00:00\",\"dateModified\":\"2021-11-22T12:40:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/\"},\"wordCount\":335,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/11\\\/locandina-25novembre-scaled.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/\",\"name\":\"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE - TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/11\\\/locandina-25novembre-scaled.jpeg\",\"datePublished\":\"2021-11-22T12:34:14+00:00\",\"dateModified\":\"2021-11-22T12:40:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/11\\\/locandina-25novembre-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2021\\\/11\\\/locandina-25novembre-scaled.jpeg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2021\\\/11\\\/22\\\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE &#8211; TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE - TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/","og_locale":"it_IT","og_type":"article","og_title":"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE - TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO - Formello","og_description":"Il Comune di Formello aderisce come ogni anno al 25 novembre \u2013 Giornata Internazionale per l\u2019Eliminazione della Violenza contro le Donne, attraverso una serie di iniziative di sensibilizzazione sulle Pari [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-11-22T12:34:14+00:00","article_modified_time":"2021-11-22T12:40:55+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/locandina-25novembre-scaled.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE &#8211; TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO","datePublished":"2021-11-22T12:34:14+00:00","dateModified":"2021-11-22T12:40:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/"},"wordCount":335,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/locandina-25novembre-scaled.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/","url":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/","name":"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE - TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/locandina-25novembre-scaled.jpeg","datePublished":"2021-11-22T12:34:14+00:00","dateModified":"2021-11-22T12:40:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/locandina-25novembre-scaled.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2021\/11\/locandina-25novembre-scaled.jpeg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2021\/11\/22\/giornata-per-leliminazione-della-violenza-contro-le-donne-tutti-gli-appuntamenti-per-le-pari-opportunita-del-comune-di-formello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"GIORNATA PER L\u2019ELIMINAZIONE DELLA VIOLENZA CONTRO LE DONNE &#8211; TUTTI GLI APPUNTAMENTI PER LE PARI OPPORTUNIT\u00c0 DEL COMUNE DI FORMELLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"25\/11\/2021 00:00","cc4_eve_data_fine":"28\/11\/2021 00:00","cc4_eve_indirizzo":"Formello, Roma Capitale, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.082521","longitude":"12.400273","zoom":"6"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=18743"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18743\/revisions"}],"predecessor-version":[{"id":18747,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18743\/revisions\/18747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/18744"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=18743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=18743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=18743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}