{"id":18839,"date":"2022-02-01T12:19:29","date_gmt":"2022-02-01T11:19:29","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=18839"},"modified":"2022-02-01T12:19:29","modified_gmt":"2022-02-01T11:19:29","slug":"giorno-del-ricordo-2022-il-dramma-delle-foibe","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/","title":{"rendered":"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE"},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\"><strong>Venerd\u00ec 4 Febbraio 2022 h. 17.30<\/strong>, il <strong>Bibliomelograno<\/strong>, presso Centro Civico Le Rughe Viale America Le Rughe, in collaborazione con la Societ\u00e0 di Studi Fiumani-Archivio Museo storico di Fiume e il Patrocinio del Comune di Formello<\/div>\n<div dir=\"auto\">invita alla conferenza su :<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\"><strong>L\u2019esodo dei giuliano-dalmat<\/strong>i e le vicende complesse del confine orientale nel Novecento<\/div>\n<div dir=\"auto\">&#8211; Saluti istituzionali del Sindaco <strong>Gian Filippo Santi<\/strong><\/div>\n<div dir=\"auto\">&#8211; Relatore: <strong>Marino Micich<\/strong> &#8211; Universit\u00e0 Nicol\u00f2 Cusano-Direttore Archivio Museo storico di Fiume<\/div>\n<div dir=\"auto\">&#8211; Modera: <strong>Giovan Battista Brunori<\/strong> &#8211; Giornalista RAI Tg2 e Presidente del Il Melograno Solidariet\u00e0 Ambiente\u00a0Cultura<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">La \u00abSociet\u00e0 di Studi Fiumani-Archivio Museo storico di Fiume\u00bb sono enti riconosciuti dalla legge 92\/2004 \u201cIstituzione del Giorno del Ricordo\u201d<\/div>\n<div dir=\"auto\">e monitorati nonch\u00e9 finanziati dal Ministero per i Beni Culturali. La Societ\u00e0 di Studi Fiumani ha stipulato anche due convenzioni per la diffusione della storia e della cultura giuliano-dalmata con la Regione Lazio e il Comune di Roma. Promuove dal 1991 un dialogo culturale<\/div>\n<div dir=\"auto\">europeo con le terre di origine oggi appartenenti alla Croazia.<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\"><strong>Super green-pass e FFP2 obbligatori &#8211; info: 335 6609162 bibliomelograno@gmail.<\/strong><\/div>\n<\/div>\n\t\t\t<h4>Inizio<\/h4>\n<p>04\/02\/2022 17:30<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>04\/02\/2022 20:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Viale America, Le Rughe, Formello, Roma Capitale, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.0605271,12.3734638&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 4 Febbraio 2022 h. 17.30, il Bibliomelograno, presso Centro Civico Le Rughe Viale America Le Rughe, in collaborazione con la Societ\u00e0 di Studi Fiumani-Archivio Museo storico di Fiume e [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":18840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-18839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE - Formello\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 4 Febbraio 2022 h. 17.30, il Bibliomelograno, presso Centro Civico Le Rughe Viale America Le Rughe, in collaborazione con la Societ\u00e0 di Studi Fiumani-Archivio Museo storico di Fiume e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-01T11:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/02\/foibe1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1061\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE\",\"datePublished\":\"2022-02-01T11:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/\"},\"wordCount\":176,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/02\\\/foibe1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/\",\"name\":\"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/02\\\/foibe1.jpg\",\"datePublished\":\"2022-02-01T11:19:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/02\\\/foibe1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/02\\\/foibe1.jpg\",\"width\":1061,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/02\\\/01\\\/giorno-del-ricordo-2022-il-dramma-delle-foibe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/","og_locale":"it_IT","og_type":"article","og_title":"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE - Formello","og_description":"Venerd\u00ec 4 Febbraio 2022 h. 17.30, il Bibliomelograno, presso Centro Civico Le Rughe Viale America Le Rughe, in collaborazione con la Societ\u00e0 di Studi Fiumani-Archivio Museo storico di Fiume e [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-02-01T11:19:29+00:00","og_image":[{"width":1061,"height":555,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/02\/foibe1.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE","datePublished":"2022-02-01T11:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/"},"wordCount":176,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/02\/foibe1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/","url":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/","name":"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/02\/foibe1.jpg","datePublished":"2022-02-01T11:19:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/02\/foibe1.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/02\/foibe1.jpg","width":1061,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2022\/02\/01\/giorno-del-ricordo-2022-il-dramma-delle-foibe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"GIORNO DEL RICORDO 2022 : IL DRAMMA DELLE FOIBE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"04\/02\/2022 17:30","cc4_eve_data_fine":"04\/02\/2022 20:00","cc4_eve_indirizzo":"Viale America, Le Rughe, Formello, Roma Capitale, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.0605271","longitude":"12.3734638","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=18839"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18839\/revisions"}],"predecessor-version":[{"id":18841,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/18839\/revisions\/18841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/18840"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=18839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=18839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=18839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}