{"id":1896,"date":"2020-07-09T13:34:22","date_gmt":"2020-07-09T11:34:22","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1896"},"modified":"2020-07-09T13:34:22","modified_gmt":"2020-07-09T11:34:22","slug":"pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/","title":{"rendered":"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO"},"content":{"rendered":"<p>Domani mattina, alle ore 9 circa, a Piazza San Lorenzo, l&#8217;Assessore allo Sport Roberta Bellotti, a nome del Comune di Formello, saluter\u00e0 Roberto e Riccardo, padre abile e figlio &#8220;super abile&#8221;, fondatori dell&#8217;associazione PedalAbile, partiti dalla loro citt\u00e0 Passirano (Bs) in tandem per raggiungere Roma a bordo di un tandem tedesco, ribattezzato &#8220;Pino&#8221; e realizzato con una seduta comoda per consentire al ragazzo di pedalare.<br \/>\nUn Giro d\u2019Italia in tandem in 13 tappe, voluto quali ambasciatori delle persone speciali, per dimostrare che tutte le barriere devono essere superate. L&#8217;arrivo a Roma \u00e8 previsto sempre per domani 10 luglio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani mattina, alle ore 9 circa, a Piazza San Lorenzo, l&#8217;Assessore allo Sport Roberta Bellotti, a nome del Comune di Formello, saluter\u00e0 Roberto e Riccardo, padre abile e figlio &#8220;super [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":1897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO - Formello\" \/>\n<meta property=\"og:description\" content=\"Domani mattina, alle ore 9 circa, a Piazza San Lorenzo, l&#8217;Assessore allo Sport Roberta Bellotti, a nome del Comune di Formello, saluter\u00e0 Roberto e Riccardo, padre abile e figlio &#8220;super [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-09T11:34:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/pedalando.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO\",\"datePublished\":\"2020-07-09T11:34:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/\"},\"wordCount\":108,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/pedalando.jpeg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/\",\"name\":\"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/pedalando.jpeg\",\"datePublished\":\"2020-07-09T11:34:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/pedalando.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/pedalando.jpeg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/09\\\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/","og_locale":"it_IT","og_type":"article","og_title":"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO - Formello","og_description":"Domani mattina, alle ore 9 circa, a Piazza San Lorenzo, l&#8217;Assessore allo Sport Roberta Bellotti, a nome del Comune di Formello, saluter\u00e0 Roberto e Riccardo, padre abile e figlio &#8220;super [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-07-09T11:34:22+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/pedalando.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO","datePublished":"2020-07-09T11:34:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/"},"wordCount":108,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/pedalando.jpeg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/","url":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/","name":"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/pedalando.jpeg","datePublished":"2020-07-09T11:34:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/pedalando.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/pedalando.jpeg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/09\/pedalando-verso-roma-roberto-e-riccardo-accolti-in-piazza-san-lorenzo-a-formello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"PEDALANDO VERSO ROMA: ROBERTO E RICCARDO ACCOLTI IN PIAZZA SAN LORENZO A FORMELLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1896"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1896\/revisions"}],"predecessor-version":[{"id":1898,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1896\/revisions\/1898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1897"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}