{"id":19015,"date":"2022-04-29T12:51:56","date_gmt":"2022-04-29T10:51:56","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19015"},"modified":"2022-04-29T12:51:56","modified_gmt":"2022-04-29T10:51:56","slug":"mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/","title":{"rendered":"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO  UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG"},"content":{"rendered":"<div dir=\"auto\">L\u2019evento patrocinato dal Comune di Formello, si \u00e8 svolto con grande partecipazione di pubblico all\u2019interno dello storico Palazzo Chigi.<\/div>\n<div dir=\"auto\">Si \u00e8 trattato di una idea del Consigliere incaricato alla Cultura e Tradizioni <strong>Patrizia Callar\u00e0<\/strong> con la collaborazione dell\u2019<strong>Associazione Riflessi<\/strong> di Formello ispirandosi alla comunicazione non violenta di Marshall Rosenberg.<\/div>\n<div dir=\"auto\">La comunicazione empatica \u00e8 un linguaggio che va al di l\u00e0 delle convinzioni di giusto o sbagliato, al di l\u00e0 dei giudizi e ci accomuna tutti come esseri umani. E\u2019 una comunicazione profonda, attenta alle emozioni e ai bisogni di ognuno. Un linguaggio di pace.<\/div>\n<div dir=\"auto\">Relatori della serata sono stati il giornalista <strong>Alvaro Vatri<\/strong>, la Dottoressa <strong>Anna Maria Carboni<\/strong> e il Sindaco di Formello <strong>Gian Filippo Santi<\/strong>.<\/div>\n<div dir=\"auto\">Grazie alla cooperazione con l\u2019Assessore alla Scuola <strong>Daniela Angelici<\/strong> ed il Dirigente dell\u2019 I.C. \u201cBarbara Rizzo\u201d Dott.ssa <strong>Filomena Barbato<\/strong> hanno partecipato al seminario un nutrito gruppo di alunni della scuola.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019evento patrocinato dal Comune di Formello, si \u00e8 svolto con grande partecipazione di pubblico all\u2019interno dello storico Palazzo Chigi. Si \u00e8 trattato di una idea del Consigliere incaricato alla Cultura [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-19015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG - Formello\" \/>\n<meta property=\"og:description\" content=\"L\u2019evento patrocinato dal Comune di Formello, si \u00e8 svolto con grande partecipazione di pubblico all\u2019interno dello storico Palazzo Chigi. Si \u00e8 trattato di una idea del Consigliere incaricato alla Cultura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-29T10:51:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/04\/Senza-nome.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"622\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG\",\"datePublished\":\"2022-04-29T10:51:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/\"},\"wordCount\":163,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/04\\\/Senza-nome.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/\",\"name\":\"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/04\\\/Senza-nome.jpg\",\"datePublished\":\"2022-04-29T10:51:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/04\\\/Senza-nome.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/04\\\/Senza-nome.jpg\",\"width\":622,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/04\\\/29\\\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/","og_locale":"it_IT","og_type":"article","og_title":"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG - Formello","og_description":"L\u2019evento patrocinato dal Comune di Formello, si \u00e8 svolto con grande partecipazione di pubblico all\u2019interno dello storico Palazzo Chigi. Si \u00e8 trattato di una idea del Consigliere incaricato alla Cultura [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-04-29T10:51:56+00:00","og_image":[{"width":622,"height":423,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/04\/Senza-nome.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG","datePublished":"2022-04-29T10:51:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/"},"wordCount":163,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/04\/Senza-nome.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/","url":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/","name":"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/04\/Senza-nome.jpg","datePublished":"2022-04-29T10:51:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/04\/Senza-nome.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/04\/Senza-nome.jpg","width":622,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2022\/04\/29\/mercoledi-27-aprile-si-e-svolto-a-formello-un-primo-seminario-sulla-cnv-di-marshall-rosenberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"MERCOLED\u00cc 27 APRILE SI \u00c8 SVOLTO A FORMELLO UN PRIMO SEMINARIO SULLA CNV DI MARSHALL ROSENBERG"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19015"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19015\/revisions"}],"predecessor-version":[{"id":19017,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19015\/revisions\/19017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19016"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}