{"id":19023,"date":"2022-05-02T11:33:33","date_gmt":"2022-05-02T09:33:33","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19023"},"modified":"2022-05-02T11:33:33","modified_gmt":"2022-05-02T09:33:33","slug":"open-day-fomello-in-un-click","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/","title":{"rendered":"OPEN DAY FOMELLO IN UN CLICK"},"content":{"rendered":"<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">\u00b7 I cittadini di Formello al centro della della trasformazione digitale con il Comune: come navigare nei servizi digitali con un click.<\/div>\n<div dir=\"auto\">\u00b7 Rendere i servizi semplici e accessibili con le tecnologie digitali \u00e8 il nostro obiettivo. Vieni a provare!<\/div>\n<div dir=\"auto\">Ti aspettiamo il giorno 4 maggio a Palazzo Chigi 9.30 &#8211; 13.00 &#8211; 15.00 18.00<\/div>\n<div dir=\"auto\">Troverai negli stand operatori comunali che ti guideranno con un click nell\u2019attivazione dei servizi digitali, dello Spis, del domicilio digitale e delle APP per comunicare con gli uffici comunali ed essere sempre informato sulle iniziative promosse dal comune<\/div>\n<div dir=\"auto\">Ti aspettiamo!<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">\u00b7 Pec, domicilio digitale, pagamenti on line: tutto a portata di un click. I cittadini di Formello protagonisti della trasformazione digitale.<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">Dalle parole del Sindaco di Formello Avv. <strong>Gian Filippo Santi<\/strong>:<\/div>\n<div dir=\"auto\">\u201cIl Comune di Formello ha intrapreso il processo di digitalizzazione dei servizi, di innovazione organizzativa e di trasformazione della modalit\u00e0 di comunicazione utilizzando le nuove tecnologie. Questo processo sta impegnando tutto il sistema pubblico e rappresenta un importante cambiamento nelle relazioni e nella comunicazione tra i cittadini e la Pubblica Amministrazione.<\/div>\n<div dir=\"auto\">Noi ci stiamo impegnando in prima persona per l\u2019attuazione a livello locale di questa priorit\u00e0 a livello nazionale. L\u2019Open Day Formello in un Click rappresenta un importante momento di confronto e dialogo con i cittadini su questo tema.\u201d<\/div>\n<\/div>\n\t\t\t<h4>Inizio<\/h4>\n<p>04\/05\/2022 09:30<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>04\/05\/2022 18:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Piazza San Lorenzo, Formello, Roma Capitale, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.079977,12.400639902435&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>\u00b7 I cittadini di Formello al centro della della trasformazione digitale con il Comune: come navigare nei servizi digitali con un click. \u00b7 Rendere i servizi semplici e accessibili con [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-19023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPEN DAY FOMELLO IN UN CLICK - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPEN DAY FOMELLO IN UN CLICK - Formello\" \/>\n<meta property=\"og:description\" content=\"\u00b7 I cittadini di Formello al centro della della trasformazione digitale con il Comune: come navigare nei servizi digitali con un click. \u00b7 Rendere i servizi semplici e accessibili con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-02T09:33:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/05\/locandina-open-day-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"842\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"OPEN DAY FOMELLO IN UN CLICK\",\"datePublished\":\"2022-05-02T09:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/\"},\"wordCount\":215,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/05\\\/locandina-open-day-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/\",\"name\":\"OPEN DAY FOMELLO IN UN CLICK - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/05\\\/locandina-open-day-1.jpg\",\"datePublished\":\"2022-05-02T09:33:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/05\\\/locandina-open-day-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/05\\\/locandina-open-day-1.jpg\",\"width\":595,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/05\\\/02\\\/open-day-fomello-in-un-click\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPEN DAY FOMELLO IN UN CLICK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPEN DAY FOMELLO IN UN CLICK - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/","og_locale":"it_IT","og_type":"article","og_title":"OPEN DAY FOMELLO IN UN CLICK - Formello","og_description":"\u00b7 I cittadini di Formello al centro della della trasformazione digitale con il Comune: come navigare nei servizi digitali con un click. \u00b7 Rendere i servizi semplici e accessibili con [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-05-02T09:33:33+00:00","og_image":[{"width":595,"height":842,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/05\/locandina-open-day-1.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"OPEN DAY FOMELLO IN UN CLICK","datePublished":"2022-05-02T09:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/"},"wordCount":215,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/05\/locandina-open-day-1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/","url":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/","name":"OPEN DAY FOMELLO IN UN CLICK - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/05\/locandina-open-day-1.jpg","datePublished":"2022-05-02T09:33:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/05\/locandina-open-day-1.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/05\/locandina-open-day-1.jpg","width":595,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2022\/05\/02\/open-day-fomello-in-un-click\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"OPEN DAY FOMELLO IN UN CLICK"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"04\/05\/2022 09:30","cc4_eve_data_fine":"04\/05\/2022 18:00","cc4_eve_indirizzo":"Piazza San Lorenzo, Formello, Roma Capitale, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.079977","longitude":"12.400639902435","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19023"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19023\/revisions"}],"predecessor-version":[{"id":19025,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19023\/revisions\/19025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19024"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}