{"id":19149,"date":"2022-07-27T13:40:22","date_gmt":"2022-07-27T11:40:22","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19149"},"modified":"2022-07-27T13:40:22","modified_gmt":"2022-07-27T11:40:22","slug":"formello-estate-2022-cinema-allaperto-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/","title":{"rendered":"FORMELLO ESTATE 2022 &#8211; CINEMA ALL&#8217;APERTO"},"content":{"rendered":"<div dir=\"auto\">Venerd\u00ec 29 luglio, presso il Centro Civico Le Rughe in Viale America, l&#8217;Associazione Viviamo Le Rughe, con il Patrocinio del <a class=\"oajrlxb2 g5ia77u1 qu0x051f esr5mh6w e9989ue4 r7d6kgcz rq0escxv nhd2j8a9 nc684nl6 p7hjln8o kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x jb3vyjys rz4wbd8a qt6c0cv9 a8nywdso i1ao9s8h esuyzwwr f1sip0of lzcic4wl gpro0wi8 q66pz984 b1v8xokw\" role=\"link\" href=\"https:\/\/www.facebook.com\/comuneformello?__cft__[0]=AZVxOEEBimEYUiqYHskCKVYNqRBmBdVKOGDguOECgb_9mLfmIRgRMhKIQ_dOBUWLWHQBp61ptnsXnjygDcfo8zl4hAbMHCracirBR3OYgpHWSYXnsw9R2_YVoRXhBx4u37Q&amp;__tn__=-]K-R\"><span class=\"nc684nl6\">Comune di Formello<\/span><\/a> e della BCC della Provincia Romana, prosegue la rassegna cinematografica con la proiezione di &#8220;Cry Macho &#8211; Ritorno a casa&#8221;, un film di Clint Eastwood.<\/div>\n<div dir=\"auto\">Stand, gastronomia e musica dalle ore 19:00.<\/div>\n\t\t\t<h4>Inizio<\/h4>\n<p>29\/07\/2022 19:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>29\/07\/2022 23:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\t\t\t<h4>Indirizzo<\/h4>\n\t\t\t<p>Le Rughe, Formello, Roma Capitale, Lazio, Italia\t\t\t\t\t\t\t<iframe \n                                    style=\"max-width: 100%;\"\n\t\t\t\twidth=\"500\" \n\t\t\t\theight=\"200\" \n\t\t\t\tframeborder=\"0\" \n\t\t\t\tscrolling=\"no\" \n\t\t\t\tmarginheight=\"0\" \n\t\t\t\tmarginwidth=\"0\" \n\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=42.0660309,12.3745859&z=14&amp;output=embed\"\n\t\t\t >\n\t\t\t\t<\/iframe><\/p>\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 29 luglio, presso il Centro Civico Le Rughe in Viale America, l&#8217;Associazione Viviamo Le Rughe, con il Patrocinio del Comune di Formello e della BCC della Provincia Romana, prosegue [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-19149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FORMELLO ESTATE 2022 - CINEMA ALL&#039;APERTO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FORMELLO ESTATE 2022 - CINEMA ALL&#039;APERTO - Formello\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 29 luglio, presso il Centro Civico Le Rughe in Viale America, l&#8217;Associazione Viviamo Le Rughe, con il Patrocinio del Comune di Formello e della BCC della Provincia Romana, prosegue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-27T11:40:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/07\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1364\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"FORMELLO ESTATE 2022 &#8211; CINEMA ALL&#8217;APERTO\",\"datePublished\":\"2022-07-27T11:40:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/\"},\"wordCount\":58,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/\",\"name\":\"FORMELLO ESTATE 2022 - CINEMA ALL'APERTO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg\",\"datePublished\":\"2022-07-27T11:40:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/07\\\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg\",\"width\":1364,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/07\\\/27\\\/formello-estate-2022-cinema-allaperto-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FORMELLO ESTATE 2022 &#8211; CINEMA ALL&#8217;APERTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FORMELLO ESTATE 2022 - CINEMA ALL'APERTO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/","og_locale":"it_IT","og_type":"article","og_title":"FORMELLO ESTATE 2022 - CINEMA ALL'APERTO - Formello","og_description":"Venerd\u00ec 29 luglio, presso il Centro Civico Le Rughe in Viale America, l&#8217;Associazione Viviamo Le Rughe, con il Patrocinio del Comune di Formello e della BCC della Provincia Romana, prosegue [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-27T11:40:22+00:00","og_image":[{"width":1364,"height":2048,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/07\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"FORMELLO ESTATE 2022 &#8211; CINEMA ALL&#8217;APERTO","datePublished":"2022-07-27T11:40:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/"},"wordCount":58,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/07\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/","url":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/","name":"FORMELLO ESTATE 2022 - CINEMA ALL'APERTO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/07\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg","datePublished":"2022-07-27T11:40:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/07\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/07\/WhatsApp-Image-2022-07-26-at-23.25.56.jpeg","width":1364,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2022\/07\/27\/formello-estate-2022-cinema-allaperto-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"FORMELLO ESTATE 2022 &#8211; CINEMA ALL&#8217;APERTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"29\/07\/2022 19:00","cc4_eve_data_fine":"29\/07\/2022 23:00","cc4_eve_indirizzo":"Le Rughe, Formello, Roma Capitale, Lazio, Italia","cc4_eve_posizione":{"latitude":"42.0660309","longitude":"12.3745859","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19149"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19149\/revisions"}],"predecessor-version":[{"id":19151,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19149\/revisions\/19151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19150"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}