{"id":19160,"date":"2022-08-02T11:41:03","date_gmt":"2022-08-02T09:41:03","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19160"},"modified":"2022-08-02T11:41:03","modified_gmt":"2022-08-02T09:41:03","slug":"richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/","title":{"rendered":"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS"},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">La richiesta per l&#8217;esonero o la riduzione del pagamento della mensa scolastica o dello scuolabus, ai sensi del Regolamento comunale per la realizzazione degli interventi nell\u2019ambito dei servizi comunali a domanda individuale, servizi sociali e scolastici, approvato con Deliberazione del C.C. n. 19 del 23.06.2009 e in ultimo modificato con Deliberazione del C.C. n. 4 del 28.03.2011, si pu\u00f2 presentare dal 1 al 30 settembre 2022, in modalit\u00e0 digitale, utilizzando il modello allegato.<\/div>\n<div dir=\"auto\">Per il trasporto e la mensa scolastica pu\u00f2 essere disposto:<\/div>\n<div dir=\"auto\">&#8211; esonero totale per gli utenti segnalati con dettagliata relazione dell&#8217;Assistente sociale comunale che evidenzi le disagiate condizioni socio-economiche del nucleo familiare, nonch\u00e9 per ogni minore portatore di handicap con certificazione L. 104\/1992, appartenente a nucleo familiare con ISEE non superiore a \u20ac 30.000,00;<\/div>\n<div dir=\"auto\">&#8211; esonero parziale del 50% per gli utenti con ISEE non superiore a \u20ac 6.000,00, le cui condizioni sociali siano accertate da relazione dell&#8217;Assistente sociale comunale.<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">Entro il 15 novembre p.v. verr\u00e0 comunicata per iscritto l&#8217;eventuale accettazione dell&#8217;istanza a cura dell&#8217;Ufficio competente.<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">La richiesta va inviata via Pec a: protocollocomunediformello@pec.it.<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">Qualora non si fosse in possesso di una mail pec, la richiesta pu\u00f2 essere inviata alla Peo: protocollo@comune.formello.rm.it<\/div>\n<div dir=\"auto\">Si informa l&#8217;utenza che non saranno prese in considerazione le domande prive degli allegati obbligatori richiesti (attestazione ISEE in corso di validit\u00e0 e copie di documenti d&#8217;identit\u00e0).<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">Allegato: modello di richiesta<\/div>\n<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19162\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/modello-richiesta-prestazioni-sociali.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/modello-richiesta-prestazioni-sociali.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>modello-richiesta-prestazioni-sociali<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La richiesta per l&#8217;esonero o la riduzione del pagamento della mensa scolastica o dello scuolabus, ai sensi del Regolamento comunale per la realizzazione degli interventi nell\u2019ambito dei servizi comunali a [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-19160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS - Formello\" \/>\n<meta property=\"og:description\" content=\"La richiesta per l&#8217;esonero o la riduzione del pagamento della mensa scolastica o dello scuolabus, ai sensi del Regolamento comunale per la realizzazione degli interventi nell\u2019ambito dei servizi comunali a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-02T09:41:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/Prestazioni-Sociali-Agevolate.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1330\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\\\/SCUOLABUS\",\"datePublished\":\"2022-08-02T09:41:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/\"},\"wordCount\":231,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/08\\\/Prestazioni-Sociali-Agevolate.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/\",\"name\":\"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\\\/SCUOLABUS - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/08\\\/Prestazioni-Sociali-Agevolate.jpg\",\"datePublished\":\"2022-08-02T09:41:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/08\\\/Prestazioni-Sociali-Agevolate.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/08\\\/Prestazioni-Sociali-Agevolate.jpg\",\"width\":1330,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/08\\\/02\\\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\\\/SCUOLABUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/","og_locale":"it_IT","og_type":"article","og_title":"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS - Formello","og_description":"La richiesta per l&#8217;esonero o la riduzione del pagamento della mensa scolastica o dello scuolabus, ai sensi del Regolamento comunale per la realizzazione degli interventi nell\u2019ambito dei servizi comunali a [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-08-02T09:41:03+00:00","og_image":[{"width":1330,"height":768,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/Prestazioni-Sociali-Agevolate.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS","datePublished":"2022-08-02T09:41:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/"},"wordCount":231,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/Prestazioni-Sociali-Agevolate.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/","url":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/","name":"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/Prestazioni-Sociali-Agevolate.jpg","datePublished":"2022-08-02T09:41:03+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/Prestazioni-Sociali-Agevolate.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/08\/Prestazioni-Sociali-Agevolate.jpg","width":1330,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2022\/08\/02\/richiesta-prestazioni-sociali-riduzione-o-esonero-pagamento-mensa-scuolabus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"RICHIESTA PRESTAZIONI SOCIALI: RIDUZIONE O ESONERO PAGAMENTO MENSA\/SCUOLABUS"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19160"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19160\/revisions"}],"predecessor-version":[{"id":19163,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19160\/revisions\/19163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19161"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}