{"id":1931,"date":"2020-07-30T12:00:27","date_gmt":"2020-07-30T10:00:27","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1931"},"modified":"2020-07-30T12:00:27","modified_gmt":"2020-07-30T10:00:27","slug":"comune-di-formello-asl-roma-4-prevenzione-itinerante","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/","title":{"rendered":"COMUNE DI FORMELLO &#8211; ASL ROMA 4: PREVENZIONE ITINERANTE"},"content":{"rendered":"<p>Lo screening riservato alle donne fra i 50 e i 69 (estendibile fino ai 74 anni) ,effettuato presso gli spazi della Scuola Primaria de Le Rughe, in collaborazione con la ASL RM4, ha raggiunto un ottimo risultato con 600 mammografie eseguite nel nostro territorio.<br \/>\n\u201cSiamo estremamente soddisfatti del risultato raggiunto e della grande partecipazione delle donne di Formello a questo progetto di prevenzione itinerante organi<span class=\"text_exposed_show\">zzata dal Comune in collaborazione con la ASL RM4.\u201d commenta il Sindaco <strong>Gian Filippo Santi<\/strong><br \/>\n\u201cDa donna comprendo l\u2019importanza e la necessit\u00e0 della prevenzione e, proprio per questo, considerando le tante richieste pervenute a cui non si \u00e8 potuto dare seguito, abbiamo deciso di farla proseguire. Le donne appartenenti alla fascia di et\u00e0 dai 50 \/74 che per un qualsiasi motivo non si siano potute prenotare per lo screening a Formello, dal mese di settembre potr\u00e0 chiamare numero verde 800-539-762 dalle 9.00 alle 13.00, dal luned\u00ec al venerd\u00ec, e prenotare l\u2019esame che verr\u00e0 effettuato presso il Camper nella vicina Campagnano di Roma.\u201d dichiara l\u2019Assessore alle Pari Opportunit\u00e0 <strong>Roberta Bellotti<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo screening riservato alle donne fra i 50 e i 69 (estendibile fino ai 74 anni) ,effettuato presso gli spazi della Scuola Primaria de Le Rughe, in collaborazione con la [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":1932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMUNE DI FORMELLO - ASL ROMA 4: PREVENZIONE ITINERANTE - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMUNE DI FORMELLO - ASL ROMA 4: PREVENZIONE ITINERANTE - Formello\" \/>\n<meta property=\"og:description\" content=\"Lo screening riservato alle donne fra i 50 e i 69 (estendibile fino ai 74 anni) ,effettuato presso gli spazi della Scuola Primaria de Le Rughe, in collaborazione con la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-30T10:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/bellotti.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"COMUNE DI FORMELLO &#8211; ASL ROMA 4: PREVENZIONE ITINERANTE\",\"datePublished\":\"2020-07-30T10:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/\"},\"wordCount\":176,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/bellotti.jpeg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/\",\"name\":\"COMUNE DI FORMELLO - ASL ROMA 4: PREVENZIONE ITINERANTE - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/bellotti.jpeg\",\"datePublished\":\"2020-07-30T10:00:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/bellotti.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/07\\\/bellotti.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/07\\\/30\\\/comune-di-formello-asl-roma-4-prevenzione-itinerante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMUNE DI FORMELLO &#8211; ASL ROMA 4: PREVENZIONE ITINERANTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMUNE DI FORMELLO - ASL ROMA 4: PREVENZIONE ITINERANTE - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/","og_locale":"it_IT","og_type":"article","og_title":"COMUNE DI FORMELLO - ASL ROMA 4: PREVENZIONE ITINERANTE - Formello","og_description":"Lo screening riservato alle donne fra i 50 e i 69 (estendibile fino ai 74 anni) ,effettuato presso gli spazi della Scuola Primaria de Le Rughe, in collaborazione con la [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-07-30T10:00:27+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/bellotti.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"COMUNE DI FORMELLO &#8211; ASL ROMA 4: PREVENZIONE ITINERANTE","datePublished":"2020-07-30T10:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/"},"wordCount":176,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/bellotti.jpeg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/","url":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/","name":"COMUNE DI FORMELLO - ASL ROMA 4: PREVENZIONE ITINERANTE - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/bellotti.jpeg","datePublished":"2020-07-30T10:00:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/bellotti.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/07\/bellotti.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/07\/30\/comune-di-formello-asl-roma-4-prevenzione-itinerante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"COMUNE DI FORMELLO &#8211; ASL ROMA 4: PREVENZIONE ITINERANTE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1931"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1931\/revisions"}],"predecessor-version":[{"id":1933,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1931\/revisions\/1933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1932"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}