{"id":19445,"date":"2022-12-24T20:10:14","date_gmt":"2022-12-24T19:10:14","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19445"},"modified":"2022-12-24T20:10:14","modified_gmt":"2022-12-24T19:10:14","slug":"banda-musicale-di-formello-in-concerto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/","title":{"rendered":"BANDA MUSICALE DI FORMELLO IN CONCERTO"},"content":{"rendered":"<div dir=\"auto\"><strong>Luned\u00ec 26 dicembre<\/strong> alle <strong>ore 19:00<\/strong>, presso la <strong>Chiesa di San Lorenzo Martire<\/strong>, l&#8217;Associazione Musicale e Culturale &#8220;Maestro Alberto Bernabei&#8221; presenta la <strong>Banda Comunale di Formello<\/strong> nel &#8220;<strong>Concerto di Natale 2022&#8243;<\/strong>, con il Patrocinio del <strong>Comune di Formello Assessorato alla Cultura e Tradizioni<\/strong> e il contributo della <strong>BCC della Provincia Romana<\/strong>.<\/div>\n<div dir=\"auto\">Maestro Concertatore direttore d&#8217;orchestra il <strong>Prof. Pietro Picone<\/strong>, Direttore <strong>Nicol\u00f2 Nori<\/strong>, presentatrice <strong>Sveva Piacenti<\/strong>.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 26 dicembre alle ore 19:00, presso la Chiesa di San Lorenzo Martire, l&#8217;Associazione Musicale e Culturale &#8220;Maestro Alberto Bernabei&#8221; presenta la Banda Comunale di Formello nel &#8220;Concerto di Natale [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-19445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BANDA MUSICALE DI FORMELLO IN CONCERTO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BANDA MUSICALE DI FORMELLO IN CONCERTO - Formello\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 26 dicembre alle ore 19:00, presso la Chiesa di San Lorenzo Martire, l&#8217;Associazione Musicale e Culturale &#8220;Maestro Alberto Bernabei&#8221; presenta la Banda Comunale di Formello nel &#8220;Concerto di Natale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-24T19:10:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/12\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"473\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"BANDA MUSICALE DI FORMELLO IN CONCERTO\",\"datePublished\":\"2022-12-24T19:10:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/\"},\"wordCount\":68,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/\",\"name\":\"BANDA MUSICALE DI FORMELLO IN CONCERTO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg\",\"datePublished\":\"2022-12-24T19:10:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2022\\\/12\\\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg\",\"width\":473,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2022\\\/12\\\/24\\\/banda-musicale-di-formello-in-concerto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BANDA MUSICALE DI FORMELLO IN CONCERTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BANDA MUSICALE DI FORMELLO IN CONCERTO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/","og_locale":"it_IT","og_type":"article","og_title":"BANDA MUSICALE DI FORMELLO IN CONCERTO - Formello","og_description":"Luned\u00ec 26 dicembre alle ore 19:00, presso la Chiesa di San Lorenzo Martire, l&#8217;Associazione Musicale e Culturale &#8220;Maestro Alberto Bernabei&#8221; presenta la Banda Comunale di Formello nel &#8220;Concerto di Natale [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-12-24T19:10:14+00:00","og_image":[{"width":473,"height":1024,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/12\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"BANDA MUSICALE DI FORMELLO IN CONCERTO","datePublished":"2022-12-24T19:10:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/"},"wordCount":68,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/12\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/","url":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/","name":"BANDA MUSICALE DI FORMELLO IN CONCERTO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/12\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg","datePublished":"2022-12-24T19:10:14+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/12\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2022\/12\/WhatsApp-Image-2022-12-24-at-09.57.49.jpeg","width":473,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2022\/12\/24\/banda-musicale-di-formello-in-concerto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"BANDA MUSICALE DI FORMELLO IN CONCERTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19445"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19445\/revisions"}],"predecessor-version":[{"id":19447,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19445\/revisions\/19447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19446"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}