{"id":1946,"date":"2020-08-14T17:26:58","date_gmt":"2020-08-14T15:26:58","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=1946"},"modified":"2020-08-14T17:26:58","modified_gmt":"2020-08-14T15:26:58","slug":"emergenza-coronavirus-aggiornamenti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/","title":{"rendered":"EMERGENZA CORONAVIRUS &#8211; AGGIORNAMENTI"},"content":{"rendered":"<p>Un nuovo caso di positivit\u00e0 al Covid-19 nel nostro Comune. Anche in questo caso la positivit\u00e0 \u00e8 stata riscontrata al rientro da un viaggio all\u2019estero, dalla Croazia nello specifico, dove presumibilmente ha contratto il virus.<br \/>\nLa ASL Roma4 ha avviato, come da protocollo, l\u2019indagine epidemiologica ed \u00e8 al lavoro per il tracciamento dei contatti stretti.<br \/>\n\u201cCon il sopraggiungere della stagione estiva sono ripresi i viaggi internazionali, anche in paesi considerati ad alto rischio epidemiologico. Il ministero della Salute ha firmato il 12 agosto 2020 un&#8217;ordinanza che prevede l\u2019obbligo di presentare un test molecolare o antigenico, con risultato negativo, effettuato per mezzo di tampone nelle 72 ore antecedenti l&#8217;ingresso in Italia, oppure l&#8217;obbligo di sottoporsi al tampone al momento dell&#8217;arrivo (con test rapidi che saranno sperimentalmente adottati nei principali aeroporti) o nelle 48 ore dal rientro in Italia per chi arriva da Croazia, Grecia, Malta e Spagna. Anche se tali destinazioni sono a tutt\u2019oggi consentite la mia preghiera \u00e8 quella di prestare la massima attenzione nei viaggi in tali localit\u00e0. Attenzione che non deve mancare neanche nelle vacanze sul nostro territorio nonch\u00e9 nella vita sociale di tutti i giorni. E\u2019 stato un anno difficile per tutti ma non dobbiamo abbassare la guardia, specialmente in questo periodo di vacanze. Continuiamo a monitorare la situazione e vi terremo aggiornati degli sviluppi\u201d<br \/>\nComunica il Sindaco<strong> Gian Filippo Santi<\/strong><br \/>\nLa Regione Lazio ha comunicato 4 casi positivi riscontrati nel territorio della Asl Roma 4. Si tratta di una ragazza di Formello di ritorno dalla Croazia, di una donna di 90 anni di Riano della Comunit\u00e0 alloggio anziani Villa Ada, e di un uomo e una donna di Civitavecchia.<br \/>\nDall inizio dell&#8217;epidemia sono guarite 770<br \/>\npersone e sono stati effettuati<br \/>\n18.526 tamponi. Al personale sanitario della intera Asl \u00e8 stata effettuata la percentuale del 90,24 % di tamponi sul totale del personale sanitario.<br \/>\nIndagine di sieroprevalenza al 13 agosto:<br \/>\n3457 test eseguiti<br \/>\n3375 test negativi<br \/>\n82 test positivi<br \/>\nSi riporta qui di seguito il totale complessivo per Comuni: ( si riportano solo quelli che hanno attualmente casi positivi)<br \/>\nAllumiere: 1 positivo<br \/>\nBracciano: 1 positivo<br \/>\nCampagnano: 1 positivo<br \/>\nCapena: 2 positivi<br \/>\nCastelnuovo di Porto : 1 positivo (un positivo riscontrato sulla nave \u00e8 stato trasferito alla struttura convenzionata)<br \/>\nCerveteri: 4 positivi<br \/>\nCivitavecchia: 4 positivi<br \/>\nFiano R. : 2 positivi<br \/>\nFormello: 2 positivi<br \/>\nLadispoli : 1 positivo<br \/>\nRiano: 2 positivi<br \/>\nSi fa presente che eventuale disallineamento dei dati pu\u00f2 essere dato da molteplici fattori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo caso di positivit\u00e0 al Covid-19 nel nostro Comune. Anche in questo caso la positivit\u00e0 \u00e8 stata riscontrata al rientro da un viaggio all\u2019estero, dalla Croazia nello specifico, dove [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1946","post","type-post","status-publish","format-standard","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EMERGENZA CORONAVIRUS - AGGIORNAMENTI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMERGENZA CORONAVIRUS - AGGIORNAMENTI - Formello\" \/>\n<meta property=\"og:description\" content=\"Un nuovo caso di positivit\u00e0 al Covid-19 nel nostro Comune. Anche in questo caso la positivit\u00e0 \u00e8 stata riscontrata al rientro da un viaggio all\u2019estero, dalla Croazia nello specifico, dove [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-14T15:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/sanita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"EMERGENZA CORONAVIRUS &#8211; AGGIORNAMENTI\",\"datePublished\":\"2020-08-14T15:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/\"},\"wordCount\":379,\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/\",\"name\":\"EMERGENZA CORONAVIRUS - AGGIORNAMENTI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"datePublished\":\"2020-08-14T15:26:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/08\\\/14\\\/emergenza-coronavirus-aggiornamenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMERGENZA CORONAVIRUS &#8211; AGGIORNAMENTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMERGENZA CORONAVIRUS - AGGIORNAMENTI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/","og_locale":"it_IT","og_type":"article","og_title":"EMERGENZA CORONAVIRUS - AGGIORNAMENTI - Formello","og_description":"Un nuovo caso di positivit\u00e0 al Covid-19 nel nostro Comune. Anche in questo caso la positivit\u00e0 \u00e8 stata riscontrata al rientro da un viaggio all\u2019estero, dalla Croazia nello specifico, dove [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-08-14T15:26:58+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/formello\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/sanita.png","height":600,"width":1200,"type":""}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"EMERGENZA CORONAVIRUS &#8211; AGGIORNAMENTI","datePublished":"2020-08-14T15:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/"},"wordCount":379,"articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/","url":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/","name":"EMERGENZA CORONAVIRUS - AGGIORNAMENTI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"datePublished":"2020-08-14T15:26:58+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/08\/14\/emergenza-coronavirus-aggiornamenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"EMERGENZA CORONAVIRUS &#8211; AGGIORNAMENTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=1946"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1946\/revisions"}],"predecessor-version":[{"id":1947,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/1946\/revisions\/1947"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=1946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=1946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}