{"id":19534,"date":"2023-01-27T12:19:42","date_gmt":"2023-01-27T11:19:42","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19534"},"modified":"2023-01-27T12:19:42","modified_gmt":"2023-01-27T11:19:42","slug":"divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/","title":{"rendered":"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI"},"content":{"rendered":"<div dir=\"auto\">In allegato l&#8217;Ord. N. 10 DEL 26.01.2023 avente per oggetto la<\/div>\n<div dir=\"auto\">chiusura temporanea della circolazione veicolare su<\/div>\n<div dir=\"auto\">Via del Sorbo nel tratto compreso tra via di Monte Madonna e via delle Porcineta.<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19536\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza n. 10<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In allegato l&#8217;Ord. N. 10 DEL 26.01.2023 avente per oggetto la chiusura temporanea della circolazione veicolare su Via del Sorbo nel tratto compreso tra via di Monte Madonna e via [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-19534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI - Formello\" \/>\n<meta property=\"og:description\" content=\"In allegato l&#8217;Ord. N. 10 DEL 26.01.2023 avente per oggetto la chiusura temporanea della circolazione veicolare su Via del Sorbo nel tratto compreso tra via di Monte Madonna e via [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-27T11:19:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI\",\"datePublished\":\"2023-01-27T11:19:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/\"},\"wordCount\":65,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/01\\\/ordinanza-n.-10.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/\",\"name\":\"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/01\\\/ordinanza-n.-10.jpg\",\"datePublished\":\"2023-01-27T11:19:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/01\\\/ordinanza-n.-10.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/01\\\/ordinanza-n.-10.jpg\",\"width\":612,\"height\":792},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/01\\\/27\\\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/","og_locale":"it_IT","og_type":"article","og_title":"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI - Formello","og_description":"In allegato l&#8217;Ord. N. 10 DEL 26.01.2023 avente per oggetto la chiusura temporanea della circolazione veicolare su Via del Sorbo nel tratto compreso tra via di Monte Madonna e via [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-01-27T11:19:42+00:00","og_image":[{"width":612,"height":792,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI","datePublished":"2023-01-27T11:19:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/"},"wordCount":65,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/","url":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/","name":"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.jpg","datePublished":"2023-01-27T11:19:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/01\/ordinanza-n.-10.jpg","width":612,"height":792},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2023\/01\/27\/divieto-di-transito-veicolare-e-pedonale-con-immediata-chiusura-totale-e-temporanea-in-via-del-sorbo-nel-tratto-compreso-tra-via-monte-madonna-e-via-delle-porcineta-dal-giorno-27-01-2023-dalle-ore-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"DIVIETO DI TRANSITO VEICOLARE E PEDONALE CON IMMEDIATA CHIUSURA TOTALE E TEMPORANEA IN VIA DEL SORBO NEL TRATTO COMPRESO TRA VIA MONTE MADONNA E VIA DELLE PORCINETA DAL GIORNO 27.01.2023 DALLE ORE 08.00 FINO A FINE LAVORI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19534"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19534\/revisions"}],"predecessor-version":[{"id":19537,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19534\/revisions\/19537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19535"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}