{"id":19586,"date":"2023-03-02T12:59:48","date_gmt":"2023-03-02T11:59:48","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19586"},"modified":"2023-03-02T12:59:48","modified_gmt":"2023-03-02T11:59:48","slug":"avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/","title":{"rendered":"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO"},"content":{"rendered":"<div dir=\"auto\"><strong>Riapertura dei termini di scadenza<\/strong> per la presentazione delle istanze relative all&#8217;avviso pubblico per la programmazione e realizzazione delle attivit\u00e0 cultura, sportive e del tempo libero annualit\u00e0 2023.<\/div>\n<div dir=\"auto\">Il nuovo termine di presentazione delle istanze \u00e8 fissato in data <strong>06.03.2023 alle ore 12:00<\/strong>.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Riapertura dei termini di scadenza per la presentazione delle istanze relative all&#8217;avviso pubblico per la programmazione e realizzazione delle attivit\u00e0 cultura, sportive e del tempo libero annualit\u00e0 2023. Il nuovo [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-19586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO - Formello\" \/>\n<meta property=\"og:description\" content=\"Riapertura dei termini di scadenza per la presentazione delle istanze relative all&#8217;avviso pubblico per la programmazione e realizzazione delle attivit\u00e0 cultura, sportive e del tempo libero annualit\u00e0 2023. Il nuovo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T11:59:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/03\/riapertura-termini-avviso-contributi-associazioni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"841\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO\",\"datePublished\":\"2023-03-02T11:59:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/\"},\"wordCount\":49,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/03\\\/riapertura-termini-avviso-contributi-associazioni.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/\",\"name\":\"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/03\\\/riapertura-termini-avviso-contributi-associazioni.jpg\",\"datePublished\":\"2023-03-02T11:59:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/03\\\/riapertura-termini-avviso-contributi-associazioni.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/03\\\/riapertura-termini-avviso-contributi-associazioni.jpg\",\"width\":595,\"height\":841},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/03\\\/02\\\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO - Formello","og_description":"Riapertura dei termini di scadenza per la presentazione delle istanze relative all&#8217;avviso pubblico per la programmazione e realizzazione delle attivit\u00e0 cultura, sportive e del tempo libero annualit\u00e0 2023. Il nuovo [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-03-02T11:59:48+00:00","og_image":[{"width":595,"height":841,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/03\/riapertura-termini-avviso-contributi-associazioni.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO","datePublished":"2023-03-02T11:59:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/"},"wordCount":49,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/03\/riapertura-termini-avviso-contributi-associazioni.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/","url":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/","name":"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/03\/riapertura-termini-avviso-contributi-associazioni.jpg","datePublished":"2023-03-02T11:59:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/03\/riapertura-termini-avviso-contributi-associazioni.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/03\/riapertura-termini-avviso-contributi-associazioni.jpg","width":595,"height":841},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2023\/03\/02\/avviso-alle-associazioni-culturali-e-sportive-del-comune-di-formello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"AVVISO ALLE ASSOCIAZIONI CULTURALI E SPORTIVE DEL COMUNE DI FORMELLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19586"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19586\/revisions"}],"predecessor-version":[{"id":19588,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19586\/revisions\/19588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19587"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}