{"id":19651,"date":"2023-04-14T12:30:14","date_gmt":"2023-04-14T10:30:14","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19651"},"modified":"2023-04-14T12:30:14","modified_gmt":"2023-04-14T10:30:14","slug":"avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/","title":{"rendered":"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#8217;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#8217;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L&#8217;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023"},"content":{"rendered":"<div dir=\"auto\">Il Comune di Formello , proceder\u00e0 all&#8217;espletamento di diverse procedure negoziate ai sensi dell&#8217;articolo 36, comma 2, lettere a) e b) del D. Lgs. 50\/2016 e s.m.i., con il criterio del minor prezzo (considerando che saranno aggiunti \u20ac 1,28 \/t per ogni km in pi\u00f9 non compresi nel canone di appalto di gestione di distanza dai confini comunali e cio\u00e8 se superano i 300 km per il rifiuto CER 200108 e 250 Km per il resto dei rifiuti , andata e ritorno) ai sensi dell&#8217;articolo 95, comma 4, del D. Lgs. 50\/2016, per l&#8217;appalto di servizio di recupero e\/o smaltimento dei rifiuti per mesi 12.<\/div>\n<div dir=\"auto\">Le Imprese interessate sono invitate a manifestare il proprio interesse e partecipare alla procedura per l\u2019affidamento dei servizi di che trattasi entro e non oltre le ore 23,00 del giorno 7 Maggio 2023 , pena la non ammissione.<\/div>\n<div dir=\"auto\">Di seguito gli allegati<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19653\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/manifestazione-interesse-anno-2023.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/manifestazione-interesse-anno-2023.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>manifestazione interesse anno 2023<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Formello , proceder\u00e0 all&#8217;espletamento di diverse procedure negoziate ai sensi dell&#8217;articolo 36, comma 2, lettere a) e b) del D. Lgs. 50\/2016 e s.m.i., con il criterio [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#039;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#039;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L&#039;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023 - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#039;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#039;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L&#039;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023 - Formello\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Formello , proceder\u00e0 all&#8217;espletamento di diverse procedure negoziate ai sensi dell&#8217;articolo 36, comma 2, lettere a) e b) del D. Lgs. 50\/2016 e s.m.i., con il criterio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-14T10:30:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/smaltimento-rifiuti-speciali-300x295-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#8217;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#8217;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\\\/2016 E S.M.I. PER L&#8217;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\\\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023\",\"datePublished\":\"2023-04-14T10:30:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/\"},\"wordCount\":173,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/04\\\/smaltimento-rifiuti-speciali-300x295-1.png\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/\",\"name\":\"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL'INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL'ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\\\/2016 E S.M.I. PER L'AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\\\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023 - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/04\\\/smaltimento-rifiuti-speciali-300x295-1.png\",\"datePublished\":\"2023-04-14T10:30:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/04\\\/smaltimento-rifiuti-speciali-300x295-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/04\\\/smaltimento-rifiuti-speciali-300x295-1.png\",\"width\":300,\"height\":295},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/04\\\/14\\\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#8217;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#8217;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\\\/2016 E S.M.I. PER L&#8217;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\\\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL'INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL'ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L'AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023 - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL'INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL'ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L'AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023 - Formello","og_description":"Il Comune di Formello , proceder\u00e0 all&#8217;espletamento di diverse procedure negoziate ai sensi dell&#8217;articolo 36, comma 2, lettere a) e b) del D. Lgs. 50\/2016 e s.m.i., con il criterio [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-04-14T10:30:14+00:00","og_image":[{"width":300,"height":295,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/smaltimento-rifiuti-speciali-300x295-1.png","type":"image\/png"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#8217;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#8217;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L&#8217;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023","datePublished":"2023-04-14T10:30:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/"},"wordCount":173,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/smaltimento-rifiuti-speciali-300x295-1.png","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/","url":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/","name":"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL'INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL'ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L'AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023 - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/smaltimento-rifiuti-speciali-300x295-1.png","datePublished":"2023-04-14T10:30:14+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/smaltimento-rifiuti-speciali-300x295-1.png","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/04\/smaltimento-rifiuti-speciali-300x295-1.png","width":300,"height":295},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2023\/04\/14\/avviso-pubblico-per-manifestazione-di-interesse-finalizzata-allindizione-della-procedura-negoziata-ai-sensi-dellart-36-comma-2-lettere-a-e-b-del-d-lgs-50-2016-e-s-m-i-per-laffidamento-del-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"AVVISO PUBBLICO PER MANIFESTAZIONE DI INTERESSE FINALIZZATA ALL&#8217;INDIZIONE DELLA PROCEDURA NEGOZIATA AI SENSI DELL&#8217;ART.36 COMMA 2 LETTERE A) e B) DEL D. LGS. 50\/2016 E S.M.I. PER L&#8217;AFFIDAMENTO DEL SERVIZIO DI RECUPERO E\/O SMALTIMENTO DEI RIFIUTI PER MESI 12 SCADENZA 07.05.2023"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19651"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19651\/revisions"}],"predecessor-version":[{"id":19654,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19651\/revisions\/19654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19652"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}