{"id":19714,"date":"2023-05-19T12:25:19","date_gmt":"2023-05-19T10:25:19","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=19714"},"modified":"2023-05-19T12:25:19","modified_gmt":"2023-05-19T10:25:19","slug":"dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/","title":{"rendered":"DINO GIZZI \u201cIL VENTO IN TASCA\u201d &#8211; MOSTRA FOTOGRAFICA DI EMANUELA GIZZI"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">La Mostra fotografica <strong>\u201cDino Gizzi &#8211; Il vento in tasca\u201d<\/strong> \u00e8 un evento, organizzato con il Patrocinio del Comune di Formello, per ricordare le prodezze del ciclista formellese in sella alla sua amata bicicletta.<\/div>\n<div dir=\"auto\">Le fotografie, i cimeli, le medaglie, i trofei, le coppe, le biciclette, alcuni ritagli di giornale e alcuni pensieri da parte di amici saranno esposti in <strong>Sala Orsini a Formello<\/strong> dal<strong> 21<\/strong> al <strong>28<\/strong> <strong>maggio<\/strong>.<\/div>\n<div dir=\"auto\">L\u2019inaugurazione si terr\u00e0 domenica 21 maggio alle 18 e con l\u2019occasione ci saranno alcuni interventi da parte delle autorit\u00e0, di amici ciclisti che hanno condiviso pezzi di strada con Dino Gizzi, e della famiglia.<\/div>\n<div dir=\"auto\">La mostra rimarr\u00e0 aperta tutta la settimana nei seguenti orari:<\/div>\n<div dir=\"auto\"><strong>Luned\u00ec &#8211; Mercoled\u00ec &#8211; Gioved\u00ec &#8211; Venerd\u00ec: dalla 17.30 alle 19.30<\/strong><\/div>\n<div dir=\"auto\">Sabato &#8211; Domenica: dalle 10.00 alle 12.30<\/div>\n<div dir=\"auto\">Marted\u00ec: chiuso<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Referente mostra: <strong>Emanuela Gizzi<\/strong><\/div>\n<div dir=\"auto\">Mobile: 327 2144167<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Mostra fotografica \u201cDino Gizzi &#8211; Il vento in tasca\u201d \u00e8 un evento, organizzato con il Patrocinio del Comune di Formello, per ricordare le prodezze del ciclista formellese in sella [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":19715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DINO GIZZI \u201cIL VENTO IN TASCA\u201d - MOSTRA FOTOGRAFICA DI EMANUELA GIZZI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DINO GIZZI \u201cIL VENTO IN TASCA\u201d - MOSTRA FOTOGRAFICA DI EMANUELA GIZZI - Formello\" \/>\n<meta property=\"og:description\" content=\"La Mostra fotografica \u201cDino Gizzi &#8211; Il vento in tasca\u201d \u00e8 un evento, organizzato con il Patrocinio del Comune di Formello, per ricordare le prodezze del ciclista formellese in sella [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-19T10:25:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/05\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"DINO GIZZI \u201cIL VENTO IN TASCA\u201d &#8211; MOSTRA FOTOGRAFICA DI EMANUELA GIZZI\",\"datePublished\":\"2023-05-19T10:25:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/\"},\"wordCount\":143,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/05\\\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/\",\"name\":\"DINO GIZZI \u201cIL VENTO IN TASCA\u201d - MOSTRA FOTOGRAFICA DI EMANUELA GIZZI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/05\\\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg\",\"datePublished\":\"2023-05-19T10:25:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/05\\\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2023\\\/05\\\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg\",\"width\":1792,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2023\\\/05\\\/19\\\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DINO GIZZI \u201cIL VENTO IN TASCA\u201d &#8211; MOSTRA FOTOGRAFICA DI EMANUELA GIZZI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DINO GIZZI \u201cIL VENTO IN TASCA\u201d - MOSTRA FOTOGRAFICA DI EMANUELA GIZZI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/","og_locale":"it_IT","og_type":"article","og_title":"DINO GIZZI \u201cIL VENTO IN TASCA\u201d - MOSTRA FOTOGRAFICA DI EMANUELA GIZZI - Formello","og_description":"La Mostra fotografica \u201cDino Gizzi &#8211; Il vento in tasca\u201d \u00e8 un evento, organizzato con il Patrocinio del Comune di Formello, per ricordare le prodezze del ciclista formellese in sella [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-05-19T10:25:19+00:00","og_image":[{"width":1792,"height":2560,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/05\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"DINO GIZZI \u201cIL VENTO IN TASCA\u201d &#8211; MOSTRA FOTOGRAFICA DI EMANUELA GIZZI","datePublished":"2023-05-19T10:25:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/"},"wordCount":143,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/05\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/","url":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/","name":"DINO GIZZI \u201cIL VENTO IN TASCA\u201d - MOSTRA FOTOGRAFICA DI EMANUELA GIZZI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/05\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg","datePublished":"2023-05-19T10:25:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/05\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2023\/05\/locandina-mostra-fotografica-memorial-gizzi-dino-scaled.jpg","width":1792,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2023\/05\/19\/dino-gizzi-il-vento-in-tasca-mostra-fotografica-di-emanuela-gizzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"DINO GIZZI \u201cIL VENTO IN TASCA\u201d &#8211; MOSTRA FOTOGRAFICA DI EMANUELA GIZZI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=19714"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19714\/revisions"}],"predecessor-version":[{"id":19716,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/19714\/revisions\/19716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/19715"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=19714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=19714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=19714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}