{"id":2354,"date":"2020-11-12T19:10:13","date_gmt":"2020-11-12T18:10:13","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=2354"},"modified":"2020-11-12T19:10:13","modified_gmt":"2020-11-12T18:10:13","slug":"coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/","title":{"rendered":"#CORONAVIRUS &#8211; ASL ROMA 4 &#8211; 1 GUARITO E NESSUN NUOVO CASO A FORMELLO"},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">La Regione Lazio ha comunicato 103 casi positivi riscontrati nel territorio della Asl Roma 4 :<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">1 ad Allumiere<\/div>\n<div dir=\"auto\">28 a Civitavecchia di cui 16 sintomatici<\/div>\n<div dir=\"auto\">5 a Santa Marinella di cui tre sintomatici<\/div>\n<div dir=\"auto\">1 a Nazzano<\/div>\n<div dir=\"auto\">1 a Magliano<\/div>\n<div dir=\"auto\">3 a Mazzano Romano di cui due sintomatici<\/div>\n<div dir=\"auto\">1 a Campagnano<\/div>\n<div dir=\"auto\">3 a Castelnuovo di cui due sintomatici<\/div>\n<div dir=\"auto\">2 a Sacrofano di cui uno sintomatico<\/div>\n<div dir=\"auto\">3 a Riano sintomatici<\/div>\n<div dir=\"auto\">4 a Fiano Romano di cui due sintomatici<\/div>\n<div dir=\"auto\">2 a Torrita Tiberina di cui uno asintomatico<\/div>\n<div dir=\"auto\">2 a Riano sintomatici<\/div>\n<div dir=\"auto\">2 a Rignano di cui uno asintomatico<\/div>\n<div dir=\"auto\">1 a Capena sintomatico<\/div>\n<div dir=\"auto\">2 a Morlupo di cui uno sintomatico<\/div>\n<div dir=\"auto\">3 ad Anguillara di cui tre sintomatici<\/div>\n<div dir=\"auto\">15 a Cerveteri di cui 9 sintomatici<\/div>\n<div dir=\"auto\">2 a Bracciano sintomatici<\/div>\n<div dir=\"auto\">21 a Ladispoli di cui 13 sintomatici<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Sono avvenuti 6 decessi nel territorio della Asl Roma 4<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Sono guarite 45 persone<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">7 a Civitavecchia<\/div>\n<div dir=\"auto\">6 a Ladispoli<\/div>\n<div dir=\"auto\">4 ad Allumiere<\/div>\n<div dir=\"auto\">6 a Campagnano<\/div>\n<div dir=\"auto\">3 a Mazzano<\/div>\n<div dir=\"auto\">2 a Riano<\/div>\n<div dir=\"auto\">1 a Formello<\/div>\n<div dir=\"auto\">1 a Morlupo<\/div>\n<div dir=\"auto\">5 a Fiano<\/div>\n<div dir=\"auto\">1 ad Anguillara<\/div>\n<div dir=\"auto\">7 a Tolfa<\/div>\n<div dir=\"auto\">2 a Bracciano<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Dall inizio dell&#8217;epidemia sono guarite 2260<\/div>\n<div dir=\"auto\">persone e sono stati effettuati<\/div>\n<div dir=\"auto\">55022 tamponi. Al personale sanitario della intera Asl \u00e8 stata effettuata la percentuale del 90,24 % di tamponi sul totale del personale sanitario.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Il totale di tamponi rapidi effettuati alla data del 9 novembre \u00e8 66622<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Si riporta qui di seguito il totale complessivo per Comuni: ( si riportano solo quelli che hanno attualmente casi positivi)<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Allumiere: 16<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Anguillara: 158<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Bracciano: 107<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Campagnano: 143<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Canale monterano : 21<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Capena: 74<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Castelnuovo di Porto : 95<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Cerveteri: 254<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Civitavecchia: 257<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Civitella San Paolo: 7<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Fiano: 94<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Filacciano: 3<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Formello: 95<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Ladispoli : 345<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Magliano: 7<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Manziana: 38<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Mazzano : 53<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Morlupo: 103<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Nazzano: 10<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Ponzano: 9<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Riano: 70<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Rignano: 54<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Sacrofano: 38<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Sant&#8217;Oreste: 10<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Santa Marinella: 58<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Tolfa: 10<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Torrita T : 15<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Trevignano: 18<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Si fa presente che nei comuni sotto indicati sono stati comunicati ulteriori positivi da laboratori esterni al territorio, gi\u00e0 conteggiati nel totale di cui sopra:<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Campagnano, Capena, Cerveteri, Civitavecchia, Civitella, Ladispoli, Magliano, Rignano, Santa Marinella, Tolfa.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Mentre per i seguenti comuni alcuni positivi sono domiciliati in altri comuni:<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Anguillara, Bracciano, Fiano Romano, Manziana, Riano.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Si fa presente che un eventuale disallineamento pu\u00f2 essere dato da molteplici fattori.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Lazio ha comunicato 103 casi positivi riscontrati nel territorio della Asl Roma 4 : 1 ad Allumiere 28 a Civitavecchia di cui 16 sintomatici 5 a Santa Marinella [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":1972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#CORONAVIRUS - ASL ROMA 4 - 1 GUARITO E NESSUN NUOVO CASO A FORMELLO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#CORONAVIRUS - ASL ROMA 4 - 1 GUARITO E NESSUN NUOVO CASO A FORMELLO - Formello\" \/>\n<meta property=\"og:description\" content=\"La Regione Lazio ha comunicato 103 casi positivi riscontrati nel territorio della Asl Roma 4 : 1 ad Allumiere 28 a Civitavecchia di cui 16 sintomatici 5 a Santa Marinella [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-12T18:10:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/08\/imba-red-coronavirus-ultimi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"#CORONAVIRUS &#8211; ASL ROMA 4 &#8211; 1 GUARITO E NESSUN NUOVO CASO A FORMELLO\",\"datePublished\":\"2020-11-12T18:10:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/\"},\"wordCount\":313,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/08\\\/imba-red-coronavirus-ultimi.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/\",\"name\":\"#CORONAVIRUS - ASL ROMA 4 - 1 GUARITO E NESSUN NUOVO CASO A FORMELLO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/08\\\/imba-red-coronavirus-ultimi.jpg\",\"datePublished\":\"2020-11-12T18:10:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/08\\\/imba-red-coronavirus-ultimi.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/08\\\/imba-red-coronavirus-ultimi.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/12\\\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#CORONAVIRUS &#8211; ASL ROMA 4 &#8211; 1 GUARITO E NESSUN NUOVO CASO A FORMELLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#CORONAVIRUS - ASL ROMA 4 - 1 GUARITO E NESSUN NUOVO CASO A FORMELLO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/","og_locale":"it_IT","og_type":"article","og_title":"#CORONAVIRUS - ASL ROMA 4 - 1 GUARITO E NESSUN NUOVO CASO A FORMELLO - Formello","og_description":"La Regione Lazio ha comunicato 103 casi positivi riscontrati nel territorio della Asl Roma 4 : 1 ad Allumiere 28 a Civitavecchia di cui 16 sintomatici 5 a Santa Marinella [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-11-12T18:10:13+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/08\/imba-red-coronavirus-ultimi.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"#CORONAVIRUS &#8211; ASL ROMA 4 &#8211; 1 GUARITO E NESSUN NUOVO CASO A FORMELLO","datePublished":"2020-11-12T18:10:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/"},"wordCount":313,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/08\/imba-red-coronavirus-ultimi.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/","url":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/","name":"#CORONAVIRUS - ASL ROMA 4 - 1 GUARITO E NESSUN NUOVO CASO A FORMELLO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/08\/imba-red-coronavirus-ultimi.jpg","datePublished":"2020-11-12T18:10:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/08\/imba-red-coronavirus-ultimi.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/08\/imba-red-coronavirus-ultimi.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/12\/coronavirus-asl-roma-4-1-guarito-e-nessun-nuovo-caso-a-formello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"#CORONAVIRUS &#8211; ASL ROMA 4 &#8211; 1 GUARITO E NESSUN NUOVO CASO A FORMELLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=2354"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2354\/revisions"}],"predecessor-version":[{"id":2355,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2354\/revisions\/2355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/1972"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=2354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=2354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=2354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}