{"id":2374,"date":"2020-11-15T22:06:51","date_gmt":"2020-11-15T21:06:51","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=2374"},"modified":"2020-11-15T22:06:51","modified_gmt":"2020-11-15T21:06:51","slug":"notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/","title":{"rendered":"NOTIZIE DALL&#8217;IC BARBARA RIZZO  COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A &#8211; SSIG R. ROSSELLINI"},"content":{"rendered":"<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Facendo seguito alle disposizioni odierne del Dipartimento di prevenzione della Asl RM4, si comunica che la convocazione di alunni e docenti della classe 3\u00b0A, prevista in data 16.11 per eseguire il test rapido di fine quarantena, <strong>\u00e8 stata rinviata a data da destinarsi<\/strong>. La classe <strong>rimane in quarantena<\/strong> fino a nuove disposizioni del Dipartimento.<\/div>\n<\/div>\n<div class=\"o9v6fnle cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">Dirigente scolastico<\/div>\n<div dir=\"auto\">Filomena Barbato<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Facendo seguito alle disposizioni odierne del Dipartimento di prevenzione della Asl RM4, si comunica che la convocazione di alunni e docenti della classe 3\u00b0A, prevista in data 16.11 per eseguire [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":2193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NOTIZIE DALL&#039;IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A - SSIG R. ROSSELLINI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOTIZIE DALL&#039;IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A - SSIG R. ROSSELLINI - Formello\" \/>\n<meta property=\"og:description\" content=\"Facendo seguito alle disposizioni odierne del Dipartimento di prevenzione della Asl RM4, si comunica che la convocazione di alunni e docenti della classe 3\u00b0A, prevista in data 16.11 per eseguire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-15T21:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1705\" \/>\n\t<meta property=\"og:image:height\" content=\"1222\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"NOTIZIE DALL&#8217;IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A &#8211; SSIG R. ROSSELLINI\",\"datePublished\":\"2020-11-15T21:06:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/\"},\"wordCount\":74,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/\",\"name\":\"NOTIZIE DALL'IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A - SSIG R. ROSSELLINI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"datePublished\":\"2020-11-15T21:06:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"width\":1705,\"height\":1222},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/15\\\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTIZIE DALL&#8217;IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A &#8211; SSIG R. ROSSELLINI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOTIZIE DALL'IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A - SSIG R. ROSSELLINI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/","og_locale":"it_IT","og_type":"article","og_title":"NOTIZIE DALL'IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A - SSIG R. ROSSELLINI - Formello","og_description":"Facendo seguito alle disposizioni odierne del Dipartimento di prevenzione della Asl RM4, si comunica che la convocazione di alunni e docenti della classe 3\u00b0A, prevista in data 16.11 per eseguire [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-11-15T21:06:51+00:00","og_image":[{"width":1705,"height":1222,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"NOTIZIE DALL&#8217;IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A &#8211; SSIG R. ROSSELLINI","datePublished":"2020-11-15T21:06:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/"},"wordCount":74,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/","url":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/","name":"NOTIZIE DALL'IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A - SSIG R. ROSSELLINI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","datePublished":"2020-11-15T21:06:51+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","width":1705,"height":1222},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/15\/notizie-dallic-barbara-rizzo-comunicazione-urgente-per-i-genitori-degli-alunni-della-classe-3a-ssig-r-rossellini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"NOTIZIE DALL&#8217;IC BARBARA RIZZO COMUNICAZIONE URGENTE PER I GENITORI DEGLI ALUNNI DELLA CLASSE 3\u00b0A &#8211; SSIG R. ROSSELLINI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=2374"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2374\/revisions"}],"predecessor-version":[{"id":2375,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2374\/revisions\/2375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/2193"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=2374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=2374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=2374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}