{"id":2459,"date":"2020-11-29T10:26:05","date_gmt":"2020-11-29T09:26:05","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=2459"},"modified":"2020-11-29T10:26:05","modified_gmt":"2020-11-29T09:26:05","slug":"notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/","title":{"rendered":"NOTIZIE DALL&#8217;IC BARBARA RIZZO &#8211; AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI"},"content":{"rendered":"<p>Si comunica che la <strong>quarantena<\/strong> per le classi sotto indicate, \u00e8 <strong>prorogata fino al 01\/12\/2020<\/strong>. Pertanto la giornata dedicata ai <strong>test antigenici rapidi di controllo<\/strong> \u00e8 prevista il <strong>01\/12\/2020<\/strong> presso il <strong>drive-in di Formello, situato in via degli Olmetti (zona industriale)<\/strong>. Gli orari per le classi sono i seguenti:<\/p>\n<p>-Sezione G Scuola dell&#8217;infanzia plesso Arcobaleno, fascia 8:00-9:00<\/p>\n<p>-Classe 3E, Scuola primaria plesso G. Rodari, fascia 9:00-10:00<\/p>\n<p>-Classe 5D Scuola primaria plesso G. Rodari, fascia 10:00-11:00<\/p>\n<p>-Classe 2C Scuola secondaria I grado plesso Rossellini, fascia 11:00-12:00<\/p>\n<p>-Classe 2B Scuola secondaria I grado plesso Rossellini, fascia 12:00-13:00<\/p>\n<p>Si precisa che gli operatori della tenda avranno gli elenchi dei nominativi di ogni classe, pertanto baster\u00e0 comunicare loro solamente nome, cognome e classe di appartenenza.<\/p>\n<p>Per i docenti non viene indicato un orario preciso, in quanto potranno recarsi al drive-in secondo le loro possibilit\u00e0 e necessit\u00e0.<\/p>\n<p>Dirigente scolastico<br \/>\nFilomena Barbato<\/p>\n<p><a href=\"https:\/\/www.icbarbararizzo.edu.it\/avvisi\/1411-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\">https:\/\/www.icbarbararizzo.edu.it\/avvisi\/1411-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che la quarantena per le classi sotto indicate, \u00e8 prorogata fino al 01\/12\/2020. Pertanto la giornata dedicata ai test antigenici rapidi di controllo \u00e8 prevista il 01\/12\/2020 presso [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":2193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NOTIZIE DALL&#039;IC BARBARA RIZZO - AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOTIZIE DALL&#039;IC BARBARA RIZZO - AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI - Formello\" \/>\n<meta property=\"og:description\" content=\"Si comunica che la quarantena per le classi sotto indicate, \u00e8 prorogata fino al 01\/12\/2020. Pertanto la giornata dedicata ai test antigenici rapidi di controllo \u00e8 prevista il 01\/12\/2020 presso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-29T09:26:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1705\" \/>\n\t<meta property=\"og:image:height\" content=\"1222\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"NOTIZIE DALL&#8217;IC BARBARA RIZZO &#8211; AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI\",\"datePublished\":\"2020-11-29T09:26:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/\"},\"wordCount\":163,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/\",\"name\":\"NOTIZIE DALL'IC BARBARA RIZZO - AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"datePublished\":\"2020-11-29T09:26:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/10\\\/banner2020-covid-scuola.jpg\",\"width\":1705,\"height\":1222},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/11\\\/29\\\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTIZIE DALL&#8217;IC BARBARA RIZZO &#8211; AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOTIZIE DALL'IC BARBARA RIZZO - AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/","og_locale":"it_IT","og_type":"article","og_title":"NOTIZIE DALL'IC BARBARA RIZZO - AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI - Formello","og_description":"Si comunica che la quarantena per le classi sotto indicate, \u00e8 prorogata fino al 01\/12\/2020. Pertanto la giornata dedicata ai test antigenici rapidi di controllo \u00e8 prevista il 01\/12\/2020 presso [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-11-29T09:26:05+00:00","og_image":[{"width":1705,"height":1222,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"NOTIZIE DALL&#8217;IC BARBARA RIZZO &#8211; AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI","datePublished":"2020-11-29T09:26:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/"},"wordCount":163,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/","url":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/","name":"NOTIZIE DALL'IC BARBARA RIZZO - AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","datePublished":"2020-11-29T09:26:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/10\/banner2020-covid-scuola.jpg","width":1705,"height":1222},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/11\/29\/notizie-dallic-barbara-rizzo-avviso-importante-proroga-quarantena-e-organizzazione-tamponi-rapidi-antigenici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"NOTIZIE DALL&#8217;IC BARBARA RIZZO &#8211; AVVISO IMPORTANTE: PROROGA QUARANTENA E ORGANIZZAZIONE TAMPONI RAPIDI ANTIGENICI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=2459"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2459\/revisions"}],"predecessor-version":[{"id":2460,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2459\/revisions\/2460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/2193"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=2459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=2459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=2459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}