{"id":2595,"date":"2020-12-22T10:25:49","date_gmt":"2020-12-22T09:25:49","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=2595"},"modified":"2020-12-22T10:25:49","modified_gmt":"2020-12-22T09:25:49","slug":"messaggio-di-auguri-dellassessore-alla-scuola-angelici","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/","title":{"rendered":"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI"},"content":{"rendered":"<div dir=\"auto\">Alla Dirigente, ai Docenti, agli alunni, a tutto il personale scolastico ed alle famiglie.<\/div>\n<div dir=\"auto\">Quest&#8217;anno sono mancate le recite, i concerti , i mercatini di Natale e tutte quelle attivit\u00e0 che aspettiamo con ansia e gioia elettrizzante, perch\u00e9 sono il coronamento di un grande lavoro, fatto di sforzi, amore, preoccupazioni e gioie condivise, di scambi di auguri fuori e dentro la scuola., tra bambini\/ ragazzi, insegnanti, famiglie e istituzioni. Con l\u2019avvicinarsi delle imminenti festivit\u00e0&#8217; Natalizie colgo l&#8217;occasione per esprimervi non solo la mia gratitudine ma la mia stima e la mia ammirazione perch\u00e9 pur avendo affrontato mille difficolt\u00e0, siete riusciti a mantenere saldo quel cordone emotivo tra alunni, docenti e genitori. Tutto ci\u00f2 \u00e8 stato possibile non solo grazie alle vostre capacit\u00e0 personali, ma anche grazie alla volont\u00e0, amore, dedizione e entusiasmo che non sono mai scontati. Ai bambini e ai ragazzi voglio dire che non dobbiamo mai arrenderci e rassegnarci alla tristezza, ma dobbiamo coltivare sempre una speranza di positivit\u00e0 nei nostri cuori e trasmetterla ai nostri compagni per sostenerci a vicenda. Abbiamo scoperto nuovi modi di stare insieme e voi siete stati dei grandi maestri. Questo \u00e8&#8217; il messaggio pi\u00f9 importante che la scuola possa trasmettere . Vi auguro di trascorrere un Natale in serenit\u00e0 \u00e8 un 2021 ricco di buoni propositi.<\/div>\n<div dir=\"auto\">L\u2019Assessore alla Scuola e Politiche di Inclusione <strong>Daniela Angelici<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alla Dirigente, ai Docenti, agli alunni, a tutto il personale scolastico ed alle famiglie. Quest&#8217;anno sono mancate le recite, i concerti , i mercatini di Natale e tutte quelle attivit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":2596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI - Formello\" \/>\n<meta property=\"og:description\" content=\"Alla Dirigente, ai Docenti, agli alunni, a tutto il personale scolastico ed alle famiglie. Quest&#8217;anno sono mancate le recite, i concerti , i mercatini di Natale e tutte quelle attivit\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-22T09:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/12\/buon-natale1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"235\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrapagnani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrapagnani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/\"},\"author\":{\"name\":\"mrapagnani\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"headline\":\"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI\",\"datePublished\":\"2020-12-22T09:25:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/\"},\"wordCount\":229,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/12\\\/buon-natale1.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/\",\"name\":\"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/12\\\/buon-natale1.jpg\",\"datePublished\":\"2020-12-22T09:25:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/12\\\/buon-natale1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2020\\\/12\\\/buon-natale1.jpg\",\"width\":400,\"height\":235},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2020\\\/12\\\/22\\\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/922bd198d459b713e12612a23472197c\",\"name\":\"mrapagnani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g\",\"caption\":\"mrapagnani\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/mrapagnani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/","og_locale":"it_IT","og_type":"article","og_title":"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI - Formello","og_description":"Alla Dirigente, ai Docenti, agli alunni, a tutto il personale scolastico ed alle famiglie. Quest&#8217;anno sono mancate le recite, i concerti , i mercatini di Natale e tutte quelle attivit\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-12-22T09:25:49+00:00","og_image":[{"width":400,"height":235,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/12\/buon-natale1.jpg","type":"image\/jpeg"}],"author":"mrapagnani","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"mrapagnani","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/"},"author":{"name":"mrapagnani","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"headline":"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI","datePublished":"2020-12-22T09:25:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/"},"wordCount":229,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/12\/buon-natale1.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/","url":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/","name":"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/12\/buon-natale1.jpg","datePublished":"2020-12-22T09:25:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/12\/buon-natale1.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2020\/12\/buon-natale1.jpg","width":400,"height":235},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2020\/12\/22\/messaggio-di-auguri-dellassessore-alla-scuola-angelici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"MESSAGGIO DI AUGURI DELL\u2019ASSESSORE ALLA SCUOLA ANGELICI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/922bd198d459b713e12612a23472197c","name":"mrapagnani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12358cb68e03a46bfac8c7ecf3047d24a3450ea6fb8af35f93210df333061757?s=96&d=mm&r=g","caption":"mrapagnani"},"url":"https:\/\/comunicacity.net\/formello\/author\/mrapagnani\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=2595"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2595\/revisions"}],"predecessor-version":[{"id":2597,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/2595\/revisions\/2597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/2596"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=2595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=2595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=2595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}