{"id":351,"date":"2018-12-12T09:55:54","date_gmt":"2018-12-12T08:55:54","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=351"},"modified":"2018-12-12T09:55:54","modified_gmt":"2018-12-12T08:55:54","slug":"concerto-di-natale-del-kol-rina","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/","title":{"rendered":"CONCERTO DI NATALE DEL KOL RINA&#8217;"},"content":{"rendered":"<div class=\"campoOggetto128\">\n<p>Il Kol Rin\u00e0 presenta il\u00a0<strong>Concerto di Natale<\/strong>\u00a0dal titolo\u00a0<strong>Chi fermer\u00e0 la musica.<\/strong>\u00a0L&#8217;appuntamento \u00e8\u00a0<strong>luned\u00ec 17 dicembre<\/strong>\u00a0alle 18,30 al teatro Velly.<\/p>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Kol Rin\u00e0 presenta il\u00a0Concerto di Natale\u00a0dal titolo\u00a0Chi fermer\u00e0 la musica.\u00a0L&#8217;appuntamento \u00e8\u00a0luned\u00ec 17 dicembre\u00a0alle 18,30 al teatro Velly.<\/p>\n","protected":false},"author":280,"featured_media":352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONCERTO DI NATALE DEL KOL RINA&#039; - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONCERTO DI NATALE DEL KOL RINA&#039; - Formello\" \/>\n<meta property=\"og:description\" content=\"Il Kol Rin\u00e0 presenta il\u00a0Concerto di Natale\u00a0dal titolo\u00a0Chi fermer\u00e0 la musica.\u00a0L&#8217;appuntamento \u00e8\u00a0luned\u00ec 17 dicembre\u00a0alle 18,30 al teatro Velly.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-12T08:55:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/kolrina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"659\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"CONCERTO DI NATALE DEL KOL RINA&#8217;\",\"datePublished\":\"2018-12-12T08:55:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/\"},\"wordCount\":27,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/kolrina.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/\",\"name\":\"CONCERTO DI NATALE DEL KOL RINA' - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/kolrina.jpg\",\"datePublished\":\"2018-12-12T08:55:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/kolrina.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/kolrina.jpg\",\"width\":659,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/12\\\/concerto-di-natale-del-kol-rina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONCERTO DI NATALE DEL KOL RINA&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONCERTO DI NATALE DEL KOL RINA' - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/","og_locale":"it_IT","og_type":"article","og_title":"CONCERTO DI NATALE DEL KOL RINA' - Formello","og_description":"Il Kol Rin\u00e0 presenta il\u00a0Concerto di Natale\u00a0dal titolo\u00a0Chi fermer\u00e0 la musica.\u00a0L&#8217;appuntamento \u00e8\u00a0luned\u00ec 17 dicembre\u00a0alle 18,30 al teatro Velly.","og_url":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-12-12T08:55:54+00:00","og_image":[{"width":659,"height":598,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/kolrina.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"CONCERTO DI NATALE DEL KOL RINA&#8217;","datePublished":"2018-12-12T08:55:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/"},"wordCount":27,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/kolrina.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/","url":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/","name":"CONCERTO DI NATALE DEL KOL RINA' - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/kolrina.jpg","datePublished":"2018-12-12T08:55:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/kolrina.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/kolrina.jpg","width":659,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/12\/concerto-di-natale-del-kol-rina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"CONCERTO DI NATALE DEL KOL RINA&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=351"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/351\/revisions"}],"predecessor-version":[{"id":353,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/351\/revisions\/353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/352"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}