{"id":369,"date":"2018-12-17T12:10:27","date_gmt":"2018-12-17T11:10:27","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=369"},"modified":"2018-12-17T12:10:27","modified_gmt":"2018-12-17T11:10:27","slug":"formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/","title":{"rendered":"FORMELLO, BORGO DELLA LUCE: VENERDI&#8217; 21 IL SOLSTIZIO D&#8217;INVERNO"},"content":{"rendered":"<div id=\"bodyFantasma\">\n<div id=\"contenitoreFantasma\">\n<div id=\"contenitore\">\n<div id=\"centroFantasma\">\n<table class=\"tabellaStruttura\" summary=\"\">\n<tbody>\n<tr>\n<td>\n<div id=\"centro\">\n<table class=\"tabellaStruttura\" summary=\"\">\n<tbody>\n<tr>\n<td>\n<div id=\"partecentrale\">\n<table class=\"tabellaStruttura\" summary=\"\">\n<tbody>\n<tr>\n<td>\n<div>\n<div id=\"regola_default\">\n<div id=\"contenuto_automatico\" class=\"contenuto_automatico42\">\n<div id=\"reviewOggetto\">\n<table class=\"tabellaStruttura\" summary=\"\">\n<tbody>\n<tr>\n<td>\n<div class=\"review36\">\n<table class=\"tabellaStruttura\" summary=\"\">\n<tbody>\n<tr>\n<td>\n<div>\n<div>\n<p>Formello, borgo della luce: <strong>venerd\u00ec\u00a021 dicembre<\/strong>, alle ore 10.30, il\u00a0<strong>Solstizio d&#8217;inverno<\/strong> nel Museo dell&#8217;Agro Veientano. Formae Srl vi invita al racconto dello speciale rapporto tra il Sole e Formello tra religione, arte e ispirazione. L&#8217;ingresso \u00e8 gratuito.<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Formello, borgo della luce: venerd\u00ec\u00a021 dicembre, alle ore 10.30, il\u00a0Solstizio d&#8217;inverno nel Museo dell&#8217;Agro Veientano. Formae Srl vi invita al racconto dello speciale rapporto tra il Sole e Formello tra [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FORMELLO, BORGO DELLA LUCE: VENERDI&#039; 21 IL SOLSTIZIO D&#039;INVERNO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FORMELLO, BORGO DELLA LUCE: VENERDI&#039; 21 IL SOLSTIZIO D&#039;INVERNO - Formello\" \/>\n<meta property=\"og:description\" content=\"Formello, borgo della luce: venerd\u00ec\u00a021 dicembre, alle ore 10.30, il\u00a0Solstizio d&#8217;inverno nel Museo dell&#8217;Agro Veientano. Formae Srl vi invita al racconto dello speciale rapporto tra il Sole e Formello tra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-17T11:10:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/solstizio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"982\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"FORMELLO, BORGO DELLA LUCE: VENERDI&#8217; 21 IL SOLSTIZIO D&#8217;INVERNO\",\"datePublished\":\"2018-12-17T11:10:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/\"},\"wordCount\":44,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/solstizio.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/\",\"name\":\"FORMELLO, BORGO DELLA LUCE: VENERDI' 21 IL SOLSTIZIO D'INVERNO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/solstizio.jpg\",\"datePublished\":\"2018-12-17T11:10:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/solstizio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/12\\\/solstizio.jpg\",\"width\":982,\"height\":501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2018\\\/12\\\/17\\\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FORMELLO, BORGO DELLA LUCE: VENERDI&#8217; 21 IL SOLSTIZIO D&#8217;INVERNO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FORMELLO, BORGO DELLA LUCE: VENERDI' 21 IL SOLSTIZIO D'INVERNO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/","og_locale":"it_IT","og_type":"article","og_title":"FORMELLO, BORGO DELLA LUCE: VENERDI' 21 IL SOLSTIZIO D'INVERNO - Formello","og_description":"Formello, borgo della luce: venerd\u00ec\u00a021 dicembre, alle ore 10.30, il\u00a0Solstizio d&#8217;inverno nel Museo dell&#8217;Agro Veientano. Formae Srl vi invita al racconto dello speciale rapporto tra il Sole e Formello tra [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-12-17T11:10:27+00:00","og_image":[{"width":982,"height":501,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/solstizio.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"FORMELLO, BORGO DELLA LUCE: VENERDI&#8217; 21 IL SOLSTIZIO D&#8217;INVERNO","datePublished":"2018-12-17T11:10:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/"},"wordCount":44,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/solstizio.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/","url":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/","name":"FORMELLO, BORGO DELLA LUCE: VENERDI' 21 IL SOLSTIZIO D'INVERNO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/solstizio.jpg","datePublished":"2018-12-17T11:10:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/solstizio.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/12\/solstizio.jpg","width":982,"height":501},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2018\/12\/17\/formello-borgo-della-luce-venerdi-21-il-solstizio-dinverno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"FORMELLO, BORGO DELLA LUCE: VENERDI&#8217; 21 IL SOLSTIZIO D&#8217;INVERNO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"predecessor-version":[{"id":371,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/369\/revisions\/371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/370"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}