{"id":495,"date":"2019-02-01T09:41:19","date_gmt":"2019-02-01T08:41:19","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=495"},"modified":"2019-02-01T09:41:19","modified_gmt":"2019-02-01T08:41:19","slug":"alle-rughe-le-arti-del-lunedi-con-tema-lamore-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/","title":{"rendered":"ALLE RUGHE &#8220;LE ARTI DEL LUNEDI'&#8221; CON TEMA L&#8217;AMORE"},"content":{"rendered":"<p>Tornano al circolo sociale Csa delle Rughe, presso il Centro civico in viale America,\u00a0<strong>Le Arti del luned\u00ec,<\/strong>\u00a0ciclo di appuntamenti culturali condotti da\u00a0<strong>Luciano Minerva<\/strong>\u00a0ed\u00a0<strong>Alvaro Vatri<\/strong>\u00a0con la loro associazione\u00a0<strong>Citt\u00e0 di Isaura.<\/strong>\u00a0<strong>Luned\u00ec 4 febbraio alle 18<\/strong> \u00e8 in programma il quinto dei sei appuntamenti previsti.\u00a0Dopo quelli dedicati ai saggi sul rispetto, la solidariet\u00e0, l&#8217;onest\u00e0, la sincerit\u00e0, arriviamo, per il primo incontro dell&#8217;anno 2019, a un tema che ci riguarda e ci coinvolge tutti sempre: l&#8217;amore.\u00a0Al centro dell&#8217;incontro un percorso attraverso il libro di Vito Mancuso &#8220;Io amo&#8221;, piccola filosofia dell&#8217;amore, pubblicato da Garzanti nel 2014.\u00a0Informazioni ai numeri telefonici 3346254764-3388993401.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tornano al circolo sociale Csa delle Rughe, presso il Centro civico in viale America,\u00a0Le Arti del luned\u00ec,\u00a0ciclo di appuntamenti culturali condotti da\u00a0Luciano Minerva\u00a0ed\u00a0Alvaro Vatri\u00a0con la loro associazione\u00a0Citt\u00e0 di Isaura.\u00a0Luned\u00ec 4 [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-495","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALLE RUGHE &quot;LE ARTI DEL LUNEDI&#039;&quot; CON TEMA L&#039;AMORE - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALLE RUGHE &quot;LE ARTI DEL LUNEDI&#039;&quot; CON TEMA L&#039;AMORE - Formello\" \/>\n<meta property=\"og:description\" content=\"Tornano al circolo sociale Csa delle Rughe, presso il Centro civico in viale America,\u00a0Le Arti del luned\u00ec,\u00a0ciclo di appuntamenti culturali condotti da\u00a0Luciano Minerva\u00a0ed\u00a0Alvaro Vatri\u00a0con la loro associazione\u00a0Citt\u00e0 di Isaura.\u00a0Luned\u00ec 4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-01T08:41:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"ALLE RUGHE &#8220;LE ARTI DEL LUNEDI'&#8221; CON TEMA L&#8217;AMORE\",\"datePublished\":\"2019-02-01T08:41:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/\"},\"wordCount\":112,\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/\",\"name\":\"ALLE RUGHE \\\"LE ARTI DEL LUNEDI'\\\" CON TEMA L'AMORE - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"datePublished\":\"2019-02-01T08:41:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/01\\\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLE RUGHE &#8220;LE ARTI DEL LUNEDI'&#8221; CON TEMA L&#8217;AMORE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALLE RUGHE \"LE ARTI DEL LUNEDI'\" CON TEMA L'AMORE - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/","og_locale":"it_IT","og_type":"article","og_title":"ALLE RUGHE \"LE ARTI DEL LUNEDI'\" CON TEMA L'AMORE - Formello","og_description":"Tornano al circolo sociale Csa delle Rughe, presso il Centro civico in viale America,\u00a0Le Arti del luned\u00ec,\u00a0ciclo di appuntamenti culturali condotti da\u00a0Luciano Minerva\u00a0ed\u00a0Alvaro Vatri\u00a0con la loro associazione\u00a0Citt\u00e0 di Isaura.\u00a0Luned\u00ec 4 [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-01T08:41:19+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/formello\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/cultura.png","height":600,"width":1200,"type":""}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"ALLE RUGHE &#8220;LE ARTI DEL LUNEDI'&#8221; CON TEMA L&#8217;AMORE","datePublished":"2019-02-01T08:41:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/"},"wordCount":112,"articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/","url":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/","name":"ALLE RUGHE \"LE ARTI DEL LUNEDI'\" CON TEMA L'AMORE - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"datePublished":"2019-02-01T08:41:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/01\/alle-rughe-le-arti-del-lunedi-con-tema-lamore-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"ALLE RUGHE &#8220;LE ARTI DEL LUNEDI'&#8221; CON TEMA L&#8217;AMORE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/495\/revisions"}],"predecessor-version":[{"id":496,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/495\/revisions\/496"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}