{"id":539,"date":"2019-02-11T11:44:19","date_gmt":"2019-02-11T10:44:19","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=539"},"modified":"2019-02-11T11:44:19","modified_gmt":"2019-02-11T10:44:19","slug":"incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/","title":{"rendered":"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA"},"content":{"rendered":"<p><strong>&#8220;La famiglia che sostiene&#8221;<\/strong> \u00e8 il tema di due\u00a0incontri di formazione e scambio fra genitori ospitati dall&#8217;accademia Pasquini presso il Centro civico delle Rughe in viale America, col patrocinio dell&#8217;assessorato alla Cultura e alle Tradizioni. Il primo incontro, dal tema &#8220;Genitori oggi, che fatica! Quali sono le sfide di un genitore oggi? Come possiamo sostenerci tra genitori?&#8221;, \u00e8 previsto <strong>sabato 16 febbraio<\/strong> dalle 15,30 alle 17,30; il secondo, dal tema &#8220;Alla ricerca delle regole: quali, quante, perch\u00e9! Le regole sono necessarie, ma quali e quante? E come stabilirle a seconda dell&#8217;et\u00e0 dei figli?&#8221;, \u00e8\u00a0<strong>sabato 16 marzo<\/strong> dalle 15,30 alle 17,30. Agli incontri, gratuiti, interviene<strong> Carolina Pierfelice<\/strong>, psicologa, psicoterapeuta e maestra. Informazioni all&#8217;email lafamigliachesostiene@gmail.com.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-540\" src=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/LA-FAMIGLIA-SOSTIENE-724x1024.jpg\" alt=\"\" width=\"680\" height=\"962\" srcset=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/LA-FAMIGLIA-SOSTIENE-724x1024.jpg 724w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/LA-FAMIGLIA-SOSTIENE-212x300.jpg 212w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/LA-FAMIGLIA-SOSTIENE-768x1086.jpg 768w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/LA-FAMIGLIA-SOSTIENE-680x962.jpg 680w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/LA-FAMIGLIA-SOSTIENE.jpg 1131w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La famiglia che sostiene&#8221; \u00e8 il tema di due\u00a0incontri di formazione e scambio fra genitori ospitati dall&#8217;accademia Pasquini presso il Centro civico delle Rughe in viale America, col patrocinio dell&#8217;assessorato [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA - Formello\" \/>\n<meta property=\"og:description\" content=\"&#8220;La famiglia che sostiene&#8221; \u00e8 il tema di due\u00a0incontri di formazione e scambio fra genitori ospitati dall&#8217;accademia Pasquini presso il Centro civico delle Rughe in viale America, col patrocinio dell&#8217;assessorato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-11T10:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/Famiglia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA\",\"datePublished\":\"2019-02-11T10:44:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/\"},\"wordCount\":119,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/02\\\/Famiglia.png\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/\",\"name\":\"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/02\\\/Famiglia.png\",\"datePublished\":\"2019-02-11T10:44:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/02\\\/Famiglia.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/02\\\/Famiglia.png\",\"width\":1125,\"height\":749},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/02\\\/11\\\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/","og_locale":"it_IT","og_type":"article","og_title":"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA - Formello","og_description":"&#8220;La famiglia che sostiene&#8221; \u00e8 il tema di due\u00a0incontri di formazione e scambio fra genitori ospitati dall&#8217;accademia Pasquini presso il Centro civico delle Rughe in viale America, col patrocinio dell&#8217;assessorato [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-02-11T10:44:19+00:00","og_image":[{"width":1125,"height":749,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/Famiglia.png","type":"image\/png"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA","datePublished":"2019-02-11T10:44:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/"},"wordCount":119,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/Famiglia.png","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/","url":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/","name":"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/Famiglia.png","datePublished":"2019-02-11T10:44:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/Famiglia.png","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/02\/Famiglia.png","width":1125,"height":749},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/02\/11\/incontri-di-formazione-e-scambio-fra-genitori-sul-tema-della-famiglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"INCONTRI DI FORMAZIONE E SCAMBIO FRA GENITORI SUL TEMA DELLA FAMIGLIA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=539"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/539\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/539\/revisions\/542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/541"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}