{"id":577,"date":"2019-03-04T08:34:47","date_gmt":"2019-03-04T07:34:47","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=577"},"modified":"2019-03-04T08:34:47","modified_gmt":"2019-03-04T07:34:47","slug":"le-iniziative-per-la-giornata-della-donna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/","title":{"rendered":"LE INIZIATIVE PER LA GIORNATA DELLA DONNA"},"content":{"rendered":"<p><strong>&#8220;Lei&#8221;<\/strong> \u00e8 il tema della <strong>Giornata internazionale della Donna<\/strong> che il Comune di Formello celebra <strong>venerd\u00ec 8 marzo<\/strong> alle 17,30 nella Sala Grande di Palazzo Chigi in piazza San Lorenzo. Un pomeriggio per parlare di donne e futuro, con il coordinamento dell&#8217;assessore alle Pari opportunit\u00e0 <strong>Roberta Bellotti<\/strong>, che illustra i progetti di prevenzione al femminile. Il programma prevede anche la presentazione del libro &#8220;Lei. Storie di donne da tutti i mondi possibili&#8221; con l&#8217;autrice <strong>Monica Serra <\/strong>e l&#8217;introduzione di <strong>Loriana Lucciarini<\/strong>; l&#8217;incontro con <strong>Annamaria Mazzini<\/strong> su &#8220;L&#8217;attivit\u00e0 di pittura del corpo nel percorso di terapia e guarigione&#8221;; interventi musicali con l&#8217;accademia di musica &#8220;Pasquini&#8221;, la performance di danza col Centro Dimensione Danza e le letture di <strong>Anna Lucchiari.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-578\" src=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-Donna-2019-756x1024.jpg\" alt=\"\" width=\"680\" height=\"921\" srcset=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-Donna-2019.jpg 756w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-Donna-2019-221x300.jpg 221w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-Donna-2019-680x921.jpg 680w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-Donna-2019-600x813.jpg 600w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Lei&#8221; \u00e8 il tema della Giornata internazionale della Donna che il Comune di Formello celebra venerd\u00ec 8 marzo alle 17,30 nella Sala Grande di Palazzo Chigi in piazza San Lorenzo. [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LE INIZIATIVE PER LA GIORNATA DELLA DONNA - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LE INIZIATIVE PER LA GIORNATA DELLA DONNA - Formello\" \/>\n<meta property=\"og:description\" content=\"&#8220;Lei&#8221; \u00e8 il tema della Giornata internazionale della Donna che il Comune di Formello celebra venerd\u00ec 8 marzo alle 17,30 nella Sala Grande di Palazzo Chigi in piazza San Lorenzo. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-04T07:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"LE INIZIATIVE PER LA GIORNATA DELLA DONNA\",\"datePublished\":\"2019-03-04T07:34:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/\"},\"wordCount\":122,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/03\\\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/\",\"name\":\"LE INIZIATIVE PER LA GIORNATA DELLA DONNA - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/03\\\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg\",\"datePublished\":\"2019-03-04T07:34:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/03\\\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/03\\\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg\",\"width\":640,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/03\\\/04\\\/le-iniziative-per-la-giornata-della-donna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LE INIZIATIVE PER LA GIORNATA DELLA DONNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LE INIZIATIVE PER LA GIORNATA DELLA DONNA - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/","og_locale":"it_IT","og_type":"article","og_title":"LE INIZIATIVE PER LA GIORNATA DELLA DONNA - Formello","og_description":"&#8220;Lei&#8221; \u00e8 il tema della Giornata internazionale della Donna che il Comune di Formello celebra venerd\u00ec 8 marzo alle 17,30 nella Sala Grande di Palazzo Chigi in piazza San Lorenzo. [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-03-04T07:34:47+00:00","og_image":[{"width":640,"height":420,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"LE INIZIATIVE PER LA GIORNATA DELLA DONNA","datePublished":"2019-03-04T07:34:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/"},"wordCount":122,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/","url":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/","name":"LE INIZIATIVE PER LA GIORNATA DELLA DONNA - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg","datePublished":"2019-03-04T07:34:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/03\/Festa-della-donna-2019-auguri-e-immagini-le-migliori-cartoline.jpg","width":640,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/03\/04\/le-iniziative-per-la-giornata-della-donna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"LE INIZIATIVE PER LA GIORNATA DELLA DONNA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"predecessor-version":[{"id":580,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/577\/revisions\/580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/579"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}