{"id":715,"date":"2019-04-20T08:20:45","date_gmt":"2019-04-20T06:20:45","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?p=715"},"modified":"2019-04-20T08:20:45","modified_gmt":"2019-04-20T06:20:45","slug":"la-staffetta-per-la-speranza-martedi-23-a-formello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/","title":{"rendered":"LA STAFFETTA PER LA SPERANZA MARTEDI&#8217; 23 A FORMELLO"},"content":{"rendered":"<p>Militari dell\u2019Arma dei Carabinieri e dell\u2019Esercito nelle vesti di runners danno vita a un\u2019ultramaratona benefica partendo domenica 21 aprile dall\u2019Istituto di Ricerca Pediatrica di Padova per giungere, dopo 530 km, in Piazza San Pietro alla presenza di Papa Francesco la mattina di mercoled\u00ec 24 aprile: \u00e8 la <strong>Staffetta per la Speranza,<\/strong> organizzata dalla fondazione Citt\u00e0 della Speranza che da 25 anni si pone l\u2019obiettivo di migliorare le condizioni di cura e assistenza dei bambini nonch\u00e9 di sostenere la ricerca scientifica in \u00e0mbito oncologico e pediatrico. Significativa la penultima tappa che ha luogo a Formello con l\u2019arrivo dei partecipanti previsto<strong> alle ore 20 di marted\u00ec 23 aprile <\/strong>in piazza San Lorenzo, dopo aver tagliato il traguardo in piazza Donato Palmieri. Coinvolte tutte le associazioni di volontariato presenti e operanti nel territorio comunale di Formello. Dopo il discorso del sindaco <strong>Gian Filippo Santi<\/strong> e i saluti delle autorit\u00e0 civili e militari \u00e8 previsto un buffet. La cittadinanza \u00e8 invitata a partecipare e a conoscere presupposti e finalit\u00e0 del progetto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-716\" src=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Formello-InForma-staffetta-724x1024.png\" alt=\"\" width=\"680\" height=\"962\" srcset=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Formello-InForma-staffetta-724x1024.png 724w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Formello-InForma-staffetta-212x300.png 212w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Formello-InForma-staffetta-768x1086.png 768w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Formello-InForma-staffetta-680x961.png 680w, https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Formello-InForma-staffetta.png 1020w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Militari dell\u2019Arma dei Carabinieri e dell\u2019Esercito nelle vesti di runners danno vita a un\u2019ultramaratona benefica partendo domenica 21 aprile dall\u2019Istituto di Ricerca Pediatrica di Padova per giungere, dopo 530 km, [&hellip;]<\/p>\n","protected":false},"author":280,"featured_media":717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA STAFFETTA PER LA SPERANZA MARTEDI&#039; 23 A FORMELLO - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA STAFFETTA PER LA SPERANZA MARTEDI&#039; 23 A FORMELLO - Formello\" \/>\n<meta property=\"og:description\" content=\"Militari dell\u2019Arma dei Carabinieri e dell\u2019Esercito nelle vesti di runners danno vita a un\u2019ultramaratona benefica partendo domenica 21 aprile dall\u2019Istituto di Ricerca Pediatrica di Padova per giungere, dopo 530 km, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-20T06:20:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Staffetta-Speranza-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/\"},\"author\":{\"name\":\"sforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"headline\":\"LA STAFFETTA PER LA SPERANZA MARTEDI&#8217; 23 A FORMELLO\",\"datePublished\":\"2019-04-20T06:20:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/\"},\"wordCount\":172,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/04\\\/Staffetta-Speranza-1-2.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/\",\"name\":\"LA STAFFETTA PER LA SPERANZA MARTEDI' 23 A FORMELLO - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/04\\\/Staffetta-Speranza-1-2.jpg\",\"datePublished\":\"2019-04-20T06:20:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/04\\\/Staffetta-Speranza-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2019\\\/04\\\/Staffetta-Speranza-1-2.jpg\",\"width\":1000,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/2019\\\/04\\\/20\\\/la-staffetta-per-la-speranza-martedi-23-a-formello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA STAFFETTA PER LA SPERANZA MARTEDI&#8217; 23 A FORMELLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#\\\/schema\\\/person\\\/8120e57248a6d5f7abb9d45d960c70b0\",\"name\":\"sforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g\",\"caption\":\"sforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/author\\\/sforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA STAFFETTA PER LA SPERANZA MARTEDI' 23 A FORMELLO - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/","og_locale":"it_IT","og_type":"article","og_title":"LA STAFFETTA PER LA SPERANZA MARTEDI' 23 A FORMELLO - Formello","og_description":"Militari dell\u2019Arma dei Carabinieri e dell\u2019Esercito nelle vesti di runners danno vita a un\u2019ultramaratona benefica partendo domenica 21 aprile dall\u2019Istituto di Ricerca Pediatrica di Padova per giungere, dopo 530 km, [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-04-20T06:20:45+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Staffetta-Speranza-1-2.jpg","type":"image\/jpeg"}],"author":"sforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/"},"author":{"name":"sforte","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"headline":"LA STAFFETTA PER LA SPERANZA MARTEDI&#8217; 23 A FORMELLO","datePublished":"2019-04-20T06:20:45+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/"},"wordCount":172,"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Staffetta-Speranza-1-2.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/","url":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/","name":"LA STAFFETTA PER LA SPERANZA MARTEDI' 23 A FORMELLO - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Staffetta-Speranza-1-2.jpg","datePublished":"2019-04-20T06:20:45+00:00","author":{"@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Staffetta-Speranza-1-2.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2019\/04\/Staffetta-Speranza-1-2.jpg","width":1000,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/2019\/04\/20\/la-staffetta-per-la-speranza-martedi-23-a-formello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"LA STAFFETTA PER LA SPERANZA MARTEDI&#8217; 23 A FORMELLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formello\/#\/schema\/person\/8120e57248a6d5f7abb9d45d960c70b0","name":"sforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/319d26737c2363f0916dbd7fa399ee857832b903e2984394097016723da3854d?s=96&d=mm&r=g","caption":"sforte"},"url":"https:\/\/comunicacity.net\/formello\/author\/sforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/users\/280"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/comments?post=715"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/715\/revisions"}],"predecessor-version":[{"id":718,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/posts\/715\/revisions\/718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/717"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/categories?post=715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/tags?post=715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}