{"id":83,"date":"2018-10-29T10:34:46","date_gmt":"2018-10-29T09:34:46","guid":{"rendered":"https:\/\/comunicacity.net\/formello\/?post_type=turismo&#038;p=83"},"modified":"2018-11-02T01:20:27","modified_gmt":"2018-11-02T00:20:27","slug":"la-storia-di-formello","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/","title":{"rendered":"La Storia di Formello"},"content":{"rendered":"<p><strong>Superficie <\/strong>Ha 3115<br \/>\n<strong>Quota centro urbano <\/strong>225 s.l.m.<br \/>\n<strong>Popolazione<\/strong> 13.113 abitanti (aggiornato a 31 ottobre 2017)<br \/>\n<strong>A.S.L.<\/strong> RM F<br \/>\n<strong>Distretto scolastico<\/strong> 31<br \/>\n<strong>Piano Territoriale Paesistico<\/strong> n. 4 &#8220;Valle del Tevere<\/p>\n<p>Il territorio di Formello rientra interamente nell&#8217;Agro Veientano, l&#8217;area politicamente controllata da Veio, la citt\u00e0 etrusca pi\u00f9 vicina a Roma.<br \/>\nSono testimonianza di questo periodo numerosi siti funerari e la fitta rete di cunicoli sotterranei scavati nel tufo per il drenaggio delle acque fluviali. Dalla parola latina &#8220;forma&#8221;, che significa appunto &#8220;condotto&#8221; &#8211; &#8220;canale&#8221;, sembra che tragga origine il nome di Formello.<br \/>\nUno dei monumenti pi\u00f9 significativi del periodo etrusco \u00e8 il Tumulo di Monte Aguzzo, una tomba principesca che ha restituito un ricco corredo di vasi tra cui la famosa Olpe Chigi ed un vaso di bucchero con alfabeto detto appunto &#8220;di Formello&#8221;.<\/p>\n<p>Con la conquista romana nel 396 a.C. Veio perde progressivamente la sua importanza; il territorio agricolo al contrario viene occupato da numerose ville e fattorie fino a tutto il II e parte del III secolo d. C.<br \/>\nCon la crisi dell&#8217;Impero Romano si assiste ad un forte calo demografico, all&#8217;abbandono della campagna, alla concentrazione della propriet\u00e0 terriere in grandi tenute.<br \/>\nQuesto periodo di decadenza dura fino all&#8217;VIII secolo d. C. quando, sotto l&#8217;impulso della Chiesa, si assiste ad un ripopolamento contadino.<br \/>\nNel territorio di Formello, ad opera del Papa Adriano I, nasce una delle nuove &#8220;domuscultae&#8221; o colonie agricole formate nell&#8217;agro romano, la cosiddetta &#8220;Domusculta Capracorum&#8221; (via di Santa Cornelia). Si tratta, secondo le pi\u00f9 recenti ipotesi, di un centro amministrativo con annessa chiesa, che mira ad un controllo pi\u00f9 diretto dei fondi che la Chiesa possedeva in quest&#8217;area per contrastare le ambizioni di una potente aristocrazia locale.<\/p>\n<p>Dopo le scorribande saracene del IX secolo, assistiamo ad un fenomeno di vastissime proporzioni che vede la popolazione rurale, che ancora viveva sparsa, trasferirsi su alture all&#8217;interno di villaggi fortificati. E&#8217; in questo periodo che sorgono i centri di Formello, Sacrofano, Campagnano e Isola Farnese.<br \/>\nDal 1081 fino al XIII secolo Formello risulta possesso del Monastero di San Paolo fuori le mura quindi, per concessione di Papa Niccolo III, passa alla famiglia Orsini. Nel 1661 il feudo di Formello viene venduto alla famiglia Chigi. Dopo l&#8217;invasione francese il potere dei Chigi va progressivamente scomparendo sostituito da una pi\u00f9 forte presenza del governo papale.<\/p>\n<p><em>&#8220;Formello di origine etrusca fu colonia romana\/ regnante Gregorio VII\/ col titolo di castrum pass\u00f2 ai monaci di S. Paolo\/ da questi agli Orsini poi ai Chigi\/ Ebbe uno Statuto da Paolo Giordano Orsini nel 1544\/ ed un consiglio generale retto da Massari fino al 1591\/ Dette i natali a Donato Palmieri\/pittore celebratissimo del XVI secolo&#8221; &#8211; iscrizione murale primi del &#8216;900&#8243;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Superficie Ha 3115 Quota centro urbano 225 s.l.m. Popolazione 13.113 abitanti (aggiornato a 31 ottobre 2017) A.S.L. RM F Distretto scolastico 31 Piano Territoriale Paesistico n. 4 &#8220;Valle del Tevere [&hellip;]<\/p>\n","protected":false},"featured_media":84,"parent":0,"menu_order":0,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-83","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Storia di Formello - Formello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Storia di Formello - Formello\" \/>\n<meta property=\"og:description\" content=\"Superficie Ha 3115 Quota centro urbano 225 s.l.m. Popolazione 13.113 abitanti (aggiornato a 31 ottobre 2017) A.S.L. RM F Distretto scolastico 31 Piano Territoriale Paesistico n. 4 &#8220;Valle del Tevere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/\" \/>\n<meta property=\"og:site_name\" content=\"Formello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-02T00:20:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/Storia-Formello.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"244\" \/>\n\t<meta property=\"og:image:height\" content=\"167\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/\",\"name\":\"La Storia di Formello - Formello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/Storia-Formello.jpg\",\"datePublished\":\"2018-10-29T09:34:46+00:00\",\"dateModified\":\"2018-11-02T00:20:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/Storia-Formello.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/wp-content\\\/uploads\\\/sites\\\/159\\\/2018\\\/10\\\/Storia-Formello.jpg\",\"width\":244,\"height\":167},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/turismo\\\/la-storia-di-formello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Storia di Formello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/\",\"name\":\"Formello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Storia di Formello - Formello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/","og_locale":"it_IT","og_type":"article","og_title":"La Storia di Formello - Formello","og_description":"Superficie Ha 3115 Quota centro urbano 225 s.l.m. Popolazione 13.113 abitanti (aggiornato a 31 ottobre 2017) A.S.L. RM F Distretto scolastico 31 Piano Territoriale Paesistico n. 4 &#8220;Valle del Tevere [&hellip;]","og_url":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/","og_site_name":"Formello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2018-11-02T00:20:27+00:00","og_image":[{"width":244,"height":167,"url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/Storia-Formello.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/","url":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/","name":"La Storia di Formello - Formello","isPartOf":{"@id":"https:\/\/comunicacity.net\/formello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/Storia-Formello.jpg","datePublished":"2018-10-29T09:34:46+00:00","dateModified":"2018-11-02T00:20:27+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/#primaryimage","url":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/Storia-Formello.jpg","contentUrl":"https:\/\/comunicacity.net\/formello\/wp-content\/uploads\/sites\/159\/2018\/10\/Storia-Formello.jpg","width":244,"height":167},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formello\/turismo\/la-storia-di-formello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formello\/"},{"@type":"ListItem","position":2,"name":"La Storia di Formello"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formello\/#website","url":"https:\/\/comunicacity.net\/formello\/","name":"Formello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/turismo\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/types\/turismo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media\/84"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/formello\/wp-json\/wp\/v2\/plugin_turismo?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}