{"id":557,"date":"2025-11-20T14:08:57","date_gmt":"2025-11-20T13:08:57","guid":{"rendered":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/"},"modified":"2025-11-20T14:09:16","modified_gmt":"2025-11-20T13:09:16","slug":"avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/","title":{"rendered":"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l."},"content":{"rendered":"<p><em>Avviso alle utenze.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In allegato documento con gli orari di apertura al pubblico degli uffici I.T.L. Spa e degli sportelli Publiservizi Srl.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_562\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/Copia_DocPrincipale-1-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/Copia_DocPrincipale-1-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Copia_DocPrincipale (1)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso alle utenze.&nbsp; Descrizione&nbsp; In allegato documento con gli orari di apertura al pubblico degli uffici I.T.L. Spa e degli sportelli Publiservizi Srl. \ud83d\udcce AllegatiCopia_DocPrincipale (1)<\/p>\n","protected":false},"author":63,"featured_media":561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l. - Formicola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l. - Formicola\" \/>\n<meta property=\"og:description\" content=\"Avviso alle utenze.&nbsp; Descrizione&nbsp; In allegato documento con gli orari di apertura al pubblico degli uffici I.T.L. Spa e degli sportelli Publiservizi Srl. \ud83d\udcce AllegatiCopia_DocPrincipale (1)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Formicola\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T13:08:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T13:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/stemma-formicola-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1451\" \/>\n\t<meta property=\"og:image:height\" content=\"1451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l.\",\"datePublished\":\"2025-11-20T13:08:57+00:00\",\"dateModified\":\"2025-11-20T13:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/\"},\"wordCount\":45,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/wp-content\\\/uploads\\\/sites\\\/229\\\/2025\\\/11\\\/stemma-formicola-2.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/\",\"name\":\"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l. - Formicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/wp-content\\\/uploads\\\/sites\\\/229\\\/2025\\\/11\\\/stemma-formicola-2.png\",\"datePublished\":\"2025-11-20T13:08:57+00:00\",\"dateModified\":\"2025-11-20T13:09:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/wp-content\\\/uploads\\\/sites\\\/229\\\/2025\\\/11\\\/stemma-formicola-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/wp-content\\\/uploads\\\/sites\\\/229\\\/2025\\\/11\\\/stemma-formicola-2.png\",\"width\":1451,\"height\":1451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/2025\\\/11\\\/20\\\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/formicola\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l. - Formicola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l. - Formicola","og_description":"Avviso alle utenze.&nbsp; Descrizione&nbsp; In allegato documento con gli orari di apertura al pubblico degli uffici I.T.L. Spa e degli sportelli Publiservizi Srl. \ud83d\udcce AllegatiCopia_DocPrincipale (1)","og_url":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/","og_site_name":"Formicola","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-11-20T13:08:57+00:00","article_modified_time":"2025-11-20T13:09:16+00:00","og_image":[{"width":1451,"height":1451,"url":"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/stemma-formicola-2.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/formicola\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l.","datePublished":"2025-11-20T13:08:57+00:00","dateModified":"2025-11-20T13:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/"},"wordCount":45,"publisher":{"@id":"https:\/\/comunicacity.net\/formicola\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/stemma-formicola-2.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/","url":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/","name":"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l. - Formicola","isPartOf":{"@id":"https:\/\/comunicacity.net\/formicola\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/stemma-formicola-2.png","datePublished":"2025-11-20T13:08:57+00:00","dateModified":"2025-11-20T13:09:16+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#primaryimage","url":"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/stemma-formicola-2.png","contentUrl":"https:\/\/comunicacity.net\/formicola\/wp-content\/uploads\/sites\/229\/2025\/11\/stemma-formicola-2.png","width":1451,"height":1451},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/formicola\/2025\/11\/20\/avviso-uffici-i-t-l-spa-e-orari-di-apertura-al-pubblico-degli-sportelli-publiservizi-s-r-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/formicola\/"},{"@type":"ListItem","position":2,"name":"Avviso uffici I.T.L. Spa e orari di apertura al pubblico degli sportelli Publiservizi S.r.l."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/formicola\/#website","url":"https:\/\/comunicacity.net\/formicola\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/formicola\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/formicola\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/formicola\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/formicola\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/formicola\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/formicola\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/formicola\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001946"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/posts\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"predecessor-version":[{"id":560,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/posts\/557\/revisions\/560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/media\/561"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/formicola\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}