{"id":656,"date":"2016-06-23T17:09:22","date_gmt":"2016-06-23T15:09:22","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?post_type=info&#038;p=656"},"modified":"2016-06-23T17:09:22","modified_gmt":"2016-06-23T15:09:22","slug":"info-generali","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/","title":{"rendered":"Info generali"},"content":{"rendered":"<div class=\"list\">\n<div class=\"item\">\n<p>Provincia<\/p>\n<h2 class=\"ccBold\">Latina<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Regione<\/p>\n<h2 class=\"ccBold\">Lazio<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Popolazione Residente<\/p>\n<h2 class=\"ccBold\">20.761<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>CAP<\/p>\n<h2 class=\"ccBold\">04024<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Prefisso Telefonico<\/p>\n<h2 class=\"ccBold\">0771<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Denominazione Abitanti<\/p>\n<h2 class=\"ccBold\">Gaetani<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Santo Patrono<\/p>\n<h2 class=\"ccBold\">SS. Erasmo e Marciano<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Festa Patronale<\/p>\n<h2 class=\"ccBold\">2 giugno<\/h2>\n<\/p><\/div>\n<div class=\"item\">\n<p>Giorno di Mercato Settimanale<\/p>\n<h2 class=\"ccBold\">Mercoled\u00ec<\/h2>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Provincia Latina Regione Lazio Popolazione Residente 20.761 CAP 04024 Prefisso Telefonico 0771 Denominazione Abitanti Gaetani Santo Patrono SS. Erasmo e Marciano Festa Patronale 2 giugno Giorno di Mercato Settimanale Mercoled\u00ec<\/p>\n","protected":false},"featured_media":252,"parent":0,"menu_order":1,"template":"","meta":[],"class_list":["post-656","info","type-info","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Info generali - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Info generali - Gaeta\" \/>\n<meta property=\"og:description\" content=\"Provincia Latina Regione Lazio Popolazione Residente 20.761 CAP 04024 Prefisso Telefonico 0771 Denominazione Abitanti Gaetani Santo Patrono SS. Erasmo e Marciano Festa Patronale 2 giugno Giorno di Mercato Settimanale Mercoled\u00ec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/\",\"name\":\"Info generali - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/11\\\/gaeta.png\",\"datePublished\":\"2016-06-23T15:09:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/11\\\/gaeta.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2014\\\/11\\\/gaeta.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/info\\\/info-generali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Info generali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Info generali - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/","og_locale":"it_IT","og_type":"article","og_title":"Info generali - Gaeta","og_description":"Provincia Latina Regione Lazio Popolazione Residente 20.761 CAP 04024 Prefisso Telefonico 0771 Denominazione Abitanti Gaetani Santo Patrono SS. Erasmo e Marciano Festa Patronale 2 giugno Giorno di Mercato Settimanale Mercoled\u00ec","og_url":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/","og_site_name":"Gaeta","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/","url":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/","name":"Info generali - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.png","datePublished":"2016-06-23T15:09:22+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.png","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/info\/info-generali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Info generali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/info\/656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/info"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/252"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}