{"id":416,"date":"2015-01-13T14:56:51","date_gmt":"2015-01-13T13:56:51","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?p=416"},"modified":"2015-01-13T16:06:08","modified_gmt":"2015-01-13T15:06:08","slug":"chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/","title":{"rendered":"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria"},"content":{"rendered":"<p style=\"text-align: justify;\">La chiesa di San Giovanni a Mare ritorner\u00e0 a splendere per essere presto riaperta al culto. La Giunta Comunale, con apposito atto deliberativo, ha dato il via libera ai lavori di manutenzione straordinaria della chiesa pi\u00f9 antica di Gaeta.<\/p>\n<p style=\"text-align: justify;\">L&#8217;autorizzazione all&#8217;intervento \u00e9 stata richiesta dall&#8217;Arcidiocesi gaetana che, da tempo immemore, detiene l&#8217;uso dell&#8217;immobile, e che provveder\u00e0 a proprie spese ai lavori straordinari. La delibera di Giunta specifica anche che &#8220;rimangono in capo all&#8217;Arcidiocesi l&#8217;esclusiva responsabilit\u00e0 ed il costo della manutenzione ordinaria, nonch\u00e9 ogni tipo di intervento dovuto per la messa a norma dello stabile, soprattutto connesso con la sicurezza degli utenti ed in generale per la pubblica incolumit\u00e0&#8221;.<\/p>\n<p style=\"text-align: justify;\">La chiesa di San Giovanni a Mare, conosciuta anche con il nome di S. Giuseppe perch\u00e9 vi si riuniva la Confraternita dei falegnami, \u00e8 uno dei preziosi gioielli storico &#8211; architettonici del patrimonio comunale. Sicuramente \u00e8 tra le chiese pi\u00f9 caratteristiche del Centro Storico S. Erasmo per le diverse influenze architettoniche che vi si fondono. Edificata nel X secolo dal duca di Gaeta Giovanni IV, presenta una cupola di arte bizantina ed il pavimento leggermente inclinato per permettere il defluire delle acque del mare nei periodi di alta marea, essendo stata eretta nelle vicinanze del mare, all&#8217;esterno della cinta muraria, parzialmente demolita agli inizi degli anni Sessanta. Custodisce al suo interno un altare ricavato da un sarcofago, mentre le otto colonne che dividono la navata hanno capitelli di vario stile.<br \/>\nDa molti anni non vi si celebrano pi\u00f9 cerimonie religiose, poich\u00e9 necessita di importanti interventi di manutenzione straordinaria.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Arcidiocesi di Gaeta, intenzionata a riaprire al culto la chiesa, ha richiesto, dunque, al Comune l&#8217;autorizzazione ad eseguire tali lavori a propria cura e spese, senza alcun gravame per l&#8217;Amministrazione Comunale.<\/p>\n<p style=\"text-align: justify;\">Autorizzazione subito concessa &#8220;per restituire ai fedeli e all&#8217;intera cittadinanza -afferma il Sindaco Cosmo Mitrano &#8211; uno dei luoghi pi\u00f9 suggestivi di Gaeta, che racchiude in s\u00e9 importanti momenti della sua storia, e mostra ancora intatti percorsi di vita del suo popolo, nello scorrere dei secoli. Aver cura delle testimonianze del nostro passato, preservare e custodire i gioielli artistici e architettonici del patrimonio comunale sono obbiettivi prioritari per la nostra Amministrazione. Abbiamo, quindi, prontamente accolto la richiesta dell&#8217;Arcidiocesi poich\u00e9 ci viene incontro, garantendo il ritorno della piccola chiesa alla sua antica bellezza, sollevando il Comune da ogni impegno di spesa. Un aiuto importante nell&#8217;attuale periodo di scarse risorse pubbliche&#8221; .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chiesa di San Giovanni a Mare ritorner\u00e0 a splendere per essere presto riaperta al culto. La Giunta Comunale, con apposito atto deliberativo, ha dato il via libera ai lavori [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria - Gaeta\" \/>\n<meta property=\"og:description\" content=\"La chiesa di San Giovanni a Mare ritorner\u00e0 a splendere per essere presto riaperta al culto. La Giunta Comunale, con apposito atto deliberativo, ha dato il via libera ai lavori [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-13T13:56:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-13T15:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/01\/san-giovanni-a-mare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria\",\"datePublished\":\"2015-01-13T13:56:51+00:00\",\"dateModified\":\"2015-01-13T15:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/\"},\"wordCount\":406,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/01\\\/san-giovanni-a-mare.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/\",\"name\":\"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/01\\\/san-giovanni-a-mare.jpg\",\"datePublished\":\"2015-01-13T13:56:51+00:00\",\"dateModified\":\"2015-01-13T15:06:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/01\\\/san-giovanni-a-mare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/01\\\/san-giovanni-a-mare.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/01\\\/13\\\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria - Gaeta","og_description":"La chiesa di San Giovanni a Mare ritorner\u00e0 a splendere per essere presto riaperta al culto. La Giunta Comunale, con apposito atto deliberativo, ha dato il via libera ai lavori [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/","og_site_name":"Gaeta","article_published_time":"2015-01-13T13:56:51+00:00","article_modified_time":"2015-01-13T15:06:08+00:00","og_image":[{"width":533,"height":400,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/01\/san-giovanni-a-mare.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria","datePublished":"2015-01-13T13:56:51+00:00","dateModified":"2015-01-13T15:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/"},"wordCount":406,"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/01\/san-giovanni-a-mare.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/","url":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/","name":"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/01\/san-giovanni-a-mare.jpg","datePublished":"2015-01-13T13:56:51+00:00","dateModified":"2015-01-13T15:06:08+00:00","author":{"@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/01\/san-giovanni-a-mare.jpg","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/01\/san-giovanni-a-mare.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/01\/13\/chiesa-di-san-giovanni-a-mare-via-libera-della-giunta-comunale-ai-lavori-di-manutenzione-straordinaria-a-cura-e-spese-dellarcidiocesi-di-gaeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Chiesa di San Giovanni a Mare: Via libera ai lavori di manutenzione straordinaria"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/gaeta\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"predecessor-version":[{"id":428,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/416\/revisions\/428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/417"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/categories?post=416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/tags?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}