{"id":517,"date":"2015-03-02T13:21:10","date_gmt":"2015-03-02T12:21:10","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?p=517"},"modified":"2015-03-02T13:21:10","modified_gmt":"2015-03-02T12:21:10","slug":"stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/","title":{"rendered":"Stadio Riciniello: aggiudicata la gara per l&#8217;affidamento dei lavori"},"content":{"rendered":"<p style=\"text-align: justify;\">Aggiudicati i lavori di adeguamento e riqualificazione del Campo Riciniello alla ditta Limonta Sport S.p.A<strong>,<\/strong> leader nella produzione e distribuzione di erba sintetica per lo sport.<\/p>\n<p style=\"text-align: justify;\">La notizia \u00e8 stata data dal Sindaco Cosmo Mitrano e dall&#8217;Assessore allo Sport Gigi Ridolfi, nel corso di un&#8217;affollata conferenza stampa, svoltasi il 27 febbraio u.s, nell&#8217;Aula Consiliare del Palazzo Comunale, cui hanno partecipato anche i rappresentanti delle societ\u00e0 sportive locali. Un incontro che ha visto il contributo del Consigliere Comunale Maurizio Caso, Presidente della Commissione Sport, e del Dirigente del Dipartimento Cura, Tutela del Territorio e Sostenibilit\u00e0 Ambientale dr. Pasquale Fusco.<br \/>\nUna gran bella notizia per l&#8217;universo sportivo gaetano, che ripaga dei sacrifici sopportati in tanti anni di lunga attesa. Perch\u00e9, in realt\u00e0, prima dell&#8217;insediamento dell&#8217;Amministrazione Mitrano nulla era stato fatto per affrontare in modo efficace le problematiche del principale campo sportivo cittadino, lasciato a languire in un triste destino di abbandono. E&#8217; stato detto a chiare lettere dagli amministratori comunali che hanno sottolineato anche &#8220;l&#8217;intenso lavoro svolto con tenacia da tutto il team tecnico &#8211; amministrativo comunale, superando l&#8217;iniziale atteggiamento \u00a0ostico della Federazione Italiana Gioco Calcio. Un atteggiamento purtroppo causato dall&#8217;inerzia delle precedenti Amministrazioni Comunali dalle quali la Federazione si sentiva presa in giro, come pi\u00f9 volte ha affermato&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;Un grande risultato quello che oggi stiamo comunicando &#8211; <strong>ha detto il Primo Cittadino<\/strong> &#8211; abbiamo espletato la gara pubblica per l&#8217;affidamento\u00a0 dei lavori allo Stadio Riciniello, ottenuto la devoluzione di un vecchio mutuo,\u00a0 acceso nel 2002, ma lasciato in stand by.\u00a0 Proprio in questi giorni l&#8217;Istituto per il Credito Sportivo ha dato il definitivo via libera al diverso utilizzo della parte di mutuo residuo. Il tutto nell&#8217;arco di due anni e mezzo!&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il mutuo in questione era stato inizialmente finalizzato alla costruzione di un bocciodromo. Con la devoluzione proposta e approvata, il mutuo residuo\u00a0 viene destinato in parte ai lavori nel campo Riciniello, e parte al primo stralcio dei lavori per la realizzazione di un complesso sportivo per il gioco del tennis, la Cittadella del Tennis. In sintesi il diverso utilizzo del mutuo contratto con il Credito Sportivo pari ad \u20ac. 1.116.808,27 \u00e8 cos\u00ec ripartito: \u20ac. 630.000,00 per la realizzazione completa del nuovo manto in erba sintetica e la manutenzione straordinaria della pista di atletica leggera del Campo Sportivo \u201cA. Riciniello\u201d; \u20ac. 486.808,27 per la realizzazione del 1\u00b0 stralcio dei lavori per la realizzazione di in complesso sportivo per il gioco del tennis.<\/p>\n<p style=\"text-align: justify;\">Il mutuo in questione era stato inizialmente finalizzato alla costruzione di un bocciodromo. Con la devoluzione proposta e approvata, il mutuo residuo\u00a0 viene destinato in parte ai lavori nel campo Riciniello, e parte al primo stralcio dei lavori per la realizzazione di un complesso sportivo per il gioco del tennis, la Cittadella del Tennis. In sintesi il diverso utilizzo del mutuo contratto con il Credito Sportivo pari ad \u20ac. 1.116.808,27 \u00e8 cos\u00ec ripartito: \u20ac. 630.000,00 per la realizzazione completa del nuovo manto in erba sintetica e la manutenzione straordinaria della pista di atletica leggera del Campo Sportivo \u201cA. Riciniello\u201d; \u20ac. 486.808,27 per la realizzazione del 1\u00b0 stralcio dei lavori per la realizzazione di in complesso sportivo per il gioco del tennis.<\/p>\n<p style=\"text-align: justify;\">&#8220;A dispetto dei nostri detrattori, delle tante falsit\u00e0 \u00a0che hanno diffuso a mezzo stampa &#8211; <strong>ha aggiunto il Sindaco Mitrano<\/strong>&#8211;\u00a0 inizieremo i lavori di riqualificazione complessiva dello Stadio Riciniello. Sono particolarmente felice per i nostri giovani atleti, per le societ\u00e0 sportive, per i tifosi, per tutto il mondo sportivo di Gaeta. Quello che restituiremo alla citt\u00e0 nel mese di settembre, questo \u00e8 il nostro auspicio, sar\u00e0 uno Stadio omologato, in regola con tutte le certificazioni, pienamente agibile e rinnovato. Ringrazio le Societ\u00e0 sportive che hanno creduto nella ferma volont\u00e0 della nostra Amministrazione di risolvere l&#8217;annosa problematica. E con spirito collaborativo, con \u00a0grande senso civico hanno saputo aspettare questo giorno, organizzandosi tra mille difficolt\u00e0, portando avanti gli allenamenti e i campionati. Tanti i sacrifici affrontati che oggi vengono ricompensati \u00a0dalla certezza che l&#8217;intervento al Riciniello si far\u00e0, perch\u00e9 la nostra Amministrazione ha mantenuto la parola&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>All&#8217;Assessore allo Sport Gigi\u00a0 Ridolfi il compito di delineare il percorso\u00a0 che ha portato\u00a0 al conseguimento dell&#8217;importante risultato<\/strong>: &#8220;Nel 2012, anno dell&#8217;insediamento della Giunta Mitrano, scadeva l&#8217;ennesima proroga della FIGC concessa allo Stadio Riciniello. Il primo contatto con la Federazione \u00e8 stato molto negativo: si rifiutava di parlare con il Comune di Gaeta perch\u00e9 si sentiva presa in giro. Rasserenati i rapporti con la FIGC, abbiamo vissuto l&#8217;infelice esperienza dell&#8217;affidamento della gestione del campo a privati. Nel novembre 2013, il Sindaco, con apposito atto, ha annullato tutte le concessioni dei campi sportivi comunali a privati, avocando a s\u00e9\u00a0 la gestione degli impianti. Ci mettemmo subito al lavoro per individuare una soluzione alternativa: nel 2002 era stato acceso un mutuo presso l&#8217;Istituto per il Credito Sportivo, in parte inutilizzato, e di cui si continuavano a pagare gli interessi. La nostra idea, andata poi a buon fine, era la devoluzione del mutuo residuo per due importanti finalit\u00e0: il Campo Riciniello e la Cittadella del Tennis. L&#8217;iter \u00e8 stato lungo e complesso, ma \u00e8 giunto felicemente a conclusione. Ci aspettavamo supporto, collaborazione e solidariet\u00e0 da parte di chi rappresenta la citt\u00e0, anche se in minoranza, e ha cuore i suoi abitanti. Invece abbiamo ricevuto solo un becero ostruzionismo che non fa onore a Gaeta. Ma noi andiamo avanti, inizieremo i lavori compatibilmente con le esigenze delle societ\u00e0 sportive che devono concludere i campionati, e a Settembre inaugureremo il nuovo Riciniello con una grande festa dove protagonisti saranno proprio i giovani atleti e le societ\u00e0 sportive!&#8221;.<\/p>\n<p style=\"text-align: justify;\">\u00a0&#8220;Questo intervento\u00a0 &#8211; <strong>conclude Ridolfi<\/strong> &#8211; che si realizza dopo venti anni di totale disinteresse ed inazione, \u00e8 un altro tassello, nel quadro dell&#8217;impiantistica sportiva, che si aggiunge all&#8217;espletamento dell&#8217;iter burocratico, relativo alla variante al Piano regolatore, per la realizzazione del nuovo Palazzetto dello Sport in Via Venezia, e la riqualificazione del Campo S. Carlo. In proposito tengo a precisare che sicuramente a fronte delle tante criticit\u00e0 che il San Carlo presenta, a partire dalla conformazione del terreno, dall&#8217;assenza di reti di protezione, siamo intenzionati a realizzare piccoli interventi\u00a0 in questo campo, che consentano di svolgere, in modo sereno, \u00a0le partite e gli allenamenti. Ma non potremo fare grandi investimenti anche perch\u00e9 il campo appartiene all&#8217;Autorit\u00e0 Portuale, la nostra Amministrazione l&#8217;ha ottenuto in concessione fino al 2016. Il futuro \u00e8 incerto. Per tale ragione non possiamo prevedere al Campo San Carlo i grandi lavori di cui avrebbe bisogno per un&#8217;ottimale fruizione&#8221;.<br \/>\nI lavori al Riciniello, illustrati dal Dirigente Fusco, consisteranno nello smaltimento dell&#8217;attuale manto erboso e nella sua sostituzione con il nuovo manto omologato per le massime categorie di campionato. Inoltre si proceder\u00e0 a riqualificare l&#8217;anello di atletica e a realizzare un&#8217;area per gli allenamenti, localizzata nella zona retrostante le porte del campo di calcio. L&#8217;intervento interesser\u00e0 anche gli impianti elettrici, termici ed antincendio, richiesti per l\u2019ottenimento della certificazione di agibilit\u00e0 dell\u2019intero complesso sportivo. &#8220;Finiti i lavori &#8211; <strong>ha affermato Fusco<\/strong> &#8211; il Riciniello sar\u00e0 il fiore all&#8217;occhiello degli impianti sportivi della provincia di Latina&#8221;.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Grande la soddisfazione del<\/strong> <strong>Consigliere Caso<\/strong> che si \u00e8 detto felicissimo per la conclusione di un iter burocratico pieno di ostacoli e barriere: &#8220;Adesso basta con le strumentalizzazioni che ci hanno fatto davvero male! Con i fatti stiamo smontando ogni falsit\u00e0 ed ostruzionismo di chi non lavora per il bene di Gaeta. Noi continueremo ad impegnarci alacremente per il raggiungimento di altri importanti traguardi che definiranno una citt\u00e0 completamente rinnovata!&#8221;.<\/p>\n<p style=\"text-align: justify;\">Parole di vivo ringraziamento al Sindaco e alla sua squadra per il risultato raggiunto sono state espresse dai delegati delle societ\u00e0 sportive di Gaeta, presenti all&#8217;incontro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aggiudicati i lavori di adeguamento e riqualificazione del Campo Riciniello alla ditta Limonta Sport S.p.A, leader nella produzione e distribuzione di erba sintetica per lo sport. La notizia \u00e8 stata [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stadio Riciniello: aggiudicata la gara per l&#039;affidamento dei lavori - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stadio Riciniello: aggiudicata la gara per l&#039;affidamento dei lavori - Gaeta\" \/>\n<meta property=\"og:description\" content=\"Aggiudicati i lavori di adeguamento e riqualificazione del Campo Riciniello alla ditta Limonta Sport S.p.A, leader nella produzione e distribuzione di erba sintetica per lo sport. La notizia \u00e8 stata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-02T12:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/stadio-riciniello.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Stadio Riciniello: aggiudicata la gara per l&#8217;affidamento dei lavori\",\"datePublished\":\"2015-03-02T12:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/\"},\"wordCount\":1243,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/stadio-riciniello.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/\",\"name\":\"Stadio Riciniello: aggiudicata la gara per l'affidamento dei lavori - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/stadio-riciniello.jpg\",\"datePublished\":\"2015-03-02T12:21:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/stadio-riciniello.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/stadio-riciniello.jpg\",\"width\":600,\"height\":304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/02\\\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stadio Riciniello: aggiudicata la gara per l&#8217;affidamento dei lavori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stadio Riciniello: aggiudicata la gara per l'affidamento dei lavori - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/","og_locale":"it_IT","og_type":"article","og_title":"Stadio Riciniello: aggiudicata la gara per l'affidamento dei lavori - Gaeta","og_description":"Aggiudicati i lavori di adeguamento e riqualificazione del Campo Riciniello alla ditta Limonta Sport S.p.A, leader nella produzione e distribuzione di erba sintetica per lo sport. La notizia \u00e8 stata [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/","og_site_name":"Gaeta","article_published_time":"2015-03-02T12:21:10+00:00","og_image":[{"width":600,"height":304,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/stadio-riciniello.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Stadio Riciniello: aggiudicata la gara per l&#8217;affidamento dei lavori","datePublished":"2015-03-02T12:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/"},"wordCount":1243,"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/stadio-riciniello.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/","url":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/","name":"Stadio Riciniello: aggiudicata la gara per l'affidamento dei lavori - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/stadio-riciniello.jpg","datePublished":"2015-03-02T12:21:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/stadio-riciniello.jpg","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/stadio-riciniello.jpg","width":600,"height":304},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/02\/stadio-riciniello-aggiudicata-la-gara-per-laffidamento-dei-lavori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Stadio Riciniello: aggiudicata la gara per l&#8217;affidamento dei lavori"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/gaeta\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/517\/revisions"}],"predecessor-version":[{"id":519,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/517\/revisions\/519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/518"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/categories?post=517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/tags?post=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}