{"id":549,"date":"2015-03-18T15:39:06","date_gmt":"2015-03-18T14:39:06","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?p=549"},"modified":"2015-03-18T15:39:06","modified_gmt":"2015-03-18T14:39:06","slug":"problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/","title":{"rendered":"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#8217;intervento del Ministero dello Sviluppo Economico e di RAIWAY"},"content":{"rendered":"<p style=\"text-align: justify;\">Rappresentanti del Ministero dello Sviluppo Economico e Tecnici RaiWay questa mattina hanno effettuato un sopralluogo in diversi punti della citt\u00e0 di Gaeta, per verificare, e valutare, le soluzioni pi\u00f9 idonee\u00a0 al superamento dei problemi esistenti nella ricezione di canali televisivi con il sistema del digitale terrestre.<\/p>\n<p style=\"text-align: justify;\">Immediata, quindi, \u00e8 stata la risposta degli Enti coinvolti alle segnalazioni del Sindaco Cosmo Mitrano, che si \u00e8 reso portavoce dei perduranti e gravi disagi cui sono sottoposti molti gaetani, a causa\u00a0 dalla mancata ricezione del segnale televisivo, sin dall&#8217;avvio della tecnologia del digitale terrestre (2012).<\/p>\n<p style=\"text-align: justify;\">&#8220;Davvero encomiabile la tempestiva risposta del Ministero dello Sviluppo Economico e di RAIWAY cui abbiamo rivolto il nostro appello. Ad essi va il nostro pi\u00f9 vivo ringraziamento per l&#8217;attenzione data ad una problematica particolarmente sentita nella nostra citt\u00e0. Ci\u00f2 fa ben sperare per una soluzione\u00a0 altrettanto veloce degli attuali disagi&#8221; \u00e8 il commento del Primo Cittadino.<\/p>\n<p style=\"text-align: justify;\">Due mesi fa (il 9 gennaio scorso) il Sindaco Mitrano scriveva al Ministro dello Sviluppo Economico Federica Guidi e al Presidente dell&#8217;Autorit\u00e0 per le Garanzie nelle Comunicazioni (AGCOM) Angelo Marcello Cardani, comunicando le proteste ricevute da molti cittadini che riscontrano le succitate difficolt\u00e0, pur avendo adeguato i propri impianti di ricezione e pur essendosi muniti di appositi decoder o apparecchi tv con decoder integrato, oltre che delle apposite antenne di ricezione&#8221;. E rimarcando come &#8220;la corretta fruizione o meno del segnale del digitale terrestre e, quindi, la normale visione o meno dei canali della televisione pubblica &#8211; per la quale i contribuenti pagano un canone &#8211; faccia parte del diritto di cittadinanza in un territorio e possa condizionarne negativamente il suo pieno godimento&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;E davvero ingiusto &#8211; proseguiva il Sindaco nella sua lettera &#8211; il fatto che numerose famiglie , che regolarmente pagano il canone RAI, non possano usufruire nemmeno dei canali privati, pur essendosi sobbarcate le spese per l&#8217;adeguamento degli impianti di ricezione Pertanto, facendomi interprete delle lamentele dei miei concittadini, chiedo che al pi\u00f9 presto vengano disposti i dovuti interventi tecnici affinch\u00e9 tutti gli abitanti del territorio possano regolarmente usufruire della corretta ricezione dei canali TV, attraverso il digitale terrestre, e che non vengano quindi penalizzati nel loro diritto ad usufruire di uno dei pi\u00f9 importanti mezzi di comunicazione. \u00c8 doveroso, in particolare, che la Rai e quanti di competenza provvedano con urgenza a sanare questo odioso gap di unit\u00e0 nazionale, che penalizza molti cittadini e, perdurando il quale, sicuramente contribuir\u00e0 ad aumentare le proteste dei cittadini contribuenti rispetto al pagamento del canone&#8221;.<\/p>\n<p style=\"text-align: justify;\">L&#8217;intervento richiesto dal Sindaco Mitrano non si \u00e8 fatto attendere: questa mattina rappresentanti del Ministero dello Sviluppo Economico\u00a0 &#8211; Centro Controllo Radio di Latina, e\u00a0 un\u00a0 tecnico RAIWAY del reparto controllo qualit\u00e0, zona territoriale Lazio,\u00a0 accompagnati da tecnici comunali, hanno svolto un sopralluogo nelle zone di Gaeta in cui persiste il problema denunciato dai cittadini.<\/p>\n<p style=\"text-align: justify;\">A conclusione della verifica, i tecnici hanno riferito al Sindaco Mitrano l&#8217;esito delle valutazioni. Nelle aree cittadine segnalate \u00e8 stato riscontrata un&#8217;ottima qualit\u00e0 del segnale sulle reti RAI 1, 2, 3 e RAINews, e una buona qualit\u00e0 sui canali tematici.\u00a0 In particolare laddove la conformazione del territorio presenta avvallamenti, come a Calegna, pu\u00f2 verificarsi una riduzione del segnale.\u00a0 Le difficolt\u00e0, quindi, sono con grande probabilit\u00e0 dovute ad un erroneo orientamento delle antenne, riscontrato dai tecnici durante il sopralluogo, che causa una cattiva ricezione del segnale. Il tecnico RAIWAY ha ben ben spiegato che gli orientamenti corretti delle antenne sono due: o verso le parabole di Castellonorato di Formia o verso quelle posizionate a Monte Orlando. Le antenne devono, quindi,\u00a0 essere orientate verso uno di questi due siti, a seconda della zona in cui insiste l&#8217;abitazione. Solo in un secondo momento se, pur modificando l&#8217;orientamento delle proprie antenne, la ricezione continua ad essere cattiva, allora si dovr\u00e0 procedere alla sostituzione dell&#8217;impianto antennistico, che potrebbe essere non adeguato in quanto datato. Il tecnico ha anche sottolineato che non esiste un impianto specifico per la ricezione del digitale terrestre, mettendo in guardia da eventuali diverse informazioni.<\/p>\n<p style=\"text-align: justify;\">Massima la disponibilit\u00e0 del Ministero e di RAIWAY ad intervenire per qualsiasi altra problematica dovesse sorgere sul territorio, cos\u00ec come a collaborare, tramite il Comune,\u00a0 con le associazioni di categoria locali per realizzare progetti di formazione ed informazione relativi al sistema del digitale terrestre e alla sua corretta ricezione. E&#8217; stato anche indicato il NUMERO VERDE\u00a0 800 111 555, cui \u00e8 possibile rivolgersi per segnalare eventuali problemi di ricezione e di cattiva qualit\u00e0 del segnale.<\/p>\n<p style=\"text-align: justify;\">Piena soddisfazione \u00e8 stata espressa dal Primo Cittadino per la verifica effettuata e le spiegazioni, chiare ed esaustive, fornite dai tecnici in merito alla situazione denunciata da diversi cittadini di Gaeta. Accolta positivamente anche la proposta avanzata di collaborazione per creare sul territorio momenti formativi e di informazione, rivolti in particolare alle categorie del settore.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rappresentanti del Ministero dello Sviluppo Economico e Tecnici RaiWay questa mattina hanno effettuato un sopralluogo in diversi punti della citt\u00e0 di Gaeta, per verificare, e valutare, le soluzioni pi\u00f9 idonee\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":550,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#039;intervento del Ministero dello Sviluppo Economico e di RAIWAY - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#039;intervento del Ministero dello Sviluppo Economico e di RAIWAY - Gaeta\" \/>\n<meta property=\"og:description\" content=\"Rappresentanti del Ministero dello Sviluppo Economico e Tecnici RaiWay questa mattina hanno effettuato un sopralluogo in diversi punti della citt\u00e0 di Gaeta, per verificare, e valutare, le soluzioni pi\u00f9 idonee\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-18T14:39:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/switch-off.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#8217;intervento del Ministero dello Sviluppo Economico e di RAIWAY\",\"datePublished\":\"2015-03-18T14:39:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/\"},\"wordCount\":794,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/switch-off.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/\",\"name\":\"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l'intervento del Ministero dello Sviluppo Economico e di RAIWAY - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/switch-off.jpg\",\"datePublished\":\"2015-03-18T14:39:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/switch-off.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/switch-off.jpg\",\"width\":280,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/18\\\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#8217;intervento del Ministero dello Sviluppo Economico e di RAIWAY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l'intervento del Ministero dello Sviluppo Economico e di RAIWAY - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/","og_locale":"it_IT","og_type":"article","og_title":"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l'intervento del Ministero dello Sviluppo Economico e di RAIWAY - Gaeta","og_description":"Rappresentanti del Ministero dello Sviluppo Economico e Tecnici RaiWay questa mattina hanno effettuato un sopralluogo in diversi punti della citt\u00e0 di Gaeta, per verificare, e valutare, le soluzioni pi\u00f9 idonee\u00a0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/","og_site_name":"Gaeta","article_published_time":"2015-03-18T14:39:06+00:00","og_image":[{"width":280,"height":300,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/switch-off.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#8217;intervento del Ministero dello Sviluppo Economico e di RAIWAY","datePublished":"2015-03-18T14:39:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/"},"wordCount":794,"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/switch-off.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/","url":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/","name":"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l'intervento del Ministero dello Sviluppo Economico e di RAIWAY - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/switch-off.jpg","datePublished":"2015-03-18T14:39:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/switch-off.jpg","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/switch-off.jpg","width":280,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/18\/problemi-nel-digitale-terrestre-sindaco-portavoce-delle-proteste-dei-cittadini-immediato-lintervento-del-ministero-dello-sviluppo-economico-e-di-raiway\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Problemi nel digitale terrestre: Sindaco portavoce delle proteste dei cittadini, immediato l&#8217;intervento del Ministero dello Sviluppo Economico e di RAIWAY"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/gaeta\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/comments?post=549"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/549\/revisions"}],"predecessor-version":[{"id":551,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/549\/revisions\/551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/550"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/categories?post=549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/tags?post=549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}