{"id":562,"date":"2015-03-31T17:10:05","date_gmt":"2015-03-31T15:10:05","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?p=562"},"modified":"2015-03-31T17:10:05","modified_gmt":"2015-03-31T15:10:05","slug":"turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/","title":{"rendered":"Turismo: le strategie di sviluppo nell&#8217;incontro comprensoriale con il Direttore Generale dell&#8217;Agenzia del Turismo della Regione Lazio"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>&#8220;<\/strong>Non \u00e8 facile pianificare strategie di sviluppo turistico in un grave momento di rigida contrazione della stagione turistica e delle spese da parte del turista, a causa della prolungata congiuntura economica negativa, nazionale ed internazionale. Ma unendo le forze ce la possiamo fare&#8221;! <strong>Cos\u00ec il Sindaco Cosmo Mitrano <\/strong>al termine dell&#8217;incontro promosso con il Direttore Generale dell&#8217;Agenzia del Turismo della Regione Lazio Giovanni Bastianelli, cui hanno partecipato i rappresentanti di diversi Comuni del comprensorio.<br \/>\nSul tavolo la scottante problematica del rilancio turistico del Golfo. Nell&#8217;Aula Consiliare del Palazzo Comunale, luned\u00ec 30 marzo 2015, \u00a0il Direttore Bastianelli ha esposto un&#8217;attenta disamina dell&#8217;attuale situazione che necessita di una svolta radicale nelle politiche di marketing territoriale, non solo nel Golfo, ma in tutto il Lazio.<\/p>\n<p style=\"text-align: justify;\">&#8220;Si \u00e8 fatto molto poco nel passato per la promozione del territorio regionale e delle sue specificit\u00e0 &#8211; <strong>ha affermato il Direttore Generale<\/strong> &#8211; Molto carente anche l&#8217;informazione sia delle sue peculiarit\u00e0 enogastronomiche che delle sue bellezze e potenzialit\u00e0 paesaggistiche e ambientali. Sono poco conosciuti ad esempio i Parchi della nostra Regione, ed ancora scarsi i collegamenti tra e con le isole ponziane. Altra nota dolente la ricettivit\u00e0 che risulta essere inadeguata e non al passo con i tempi, nel Golfo e in tutto il Lazio.<\/p>\n<p style=\"text-align: justify;\">\u00a0Recuperare il tempo perduto si pu\u00f2. Tre le linee direttrici da seguire per colmare il gap: turismo, cultura, e produzioni agricole o del mare. La vicinanza di grandi poli di attrazione culturale e religiosa come Roma e Napoli devono spingere ad unire eventi culturali con manifestazioni enogastronomiche che facciano conoscere meglio i prodotti tipici del posto. E&#8217; questa la strategia da delineare che sar\u00e0 premiante se si svilupper\u00e0 in \u00a0ambito comprensoriale, attraverso le unioni tra i Comuni. Unioni non formali, ma di fatto. Superando ogni barriera politica ed ideologica, perch\u00e9 la crescita turistica \u00e8 e deve essere bipartisan. \u00a0Fare rete \u00e8 la mossa vincente: i Comuni del Golfo dovranno quindi coordinarsi per promuovere in sintonia, e non in antagonismo, le varie peculiarit\u00e0 di ciascun territorio, favorire l&#8217;interscambio dei flussi turistici, evitando la sovrapposizione di iniziative ed eventi. Fondamentale anche la stretta collaborazione per la promozione turistica del Golfo via internet, sopratutto attraverso i social network.<\/p>\n<p style=\"text-align: justify;\">Creare un gruppo di lavoro \u00a0comprensoriale \u00e8 quindi prioritario. Primo obiettivo: la realizzazione di un calendario unico di eventi e manifestazioni, in cui siano inserite le iniziative di tutti i Comuni, in modo non conflittuale, ma fluido. Insomma un&#8217;unica grande programmazione che mira alla valorizzazione dei punti di forza (storici, culturali, enogastronomici, paesaggistici, artistici) di ciascun territorio&#8221;.<\/p>\n<p style=\"text-align: justify;\">La proposta \u00e8 stata subito avallata dal Sindaco Mitrano e accolta positivamente da tutti i presenti che si sono resi disponibili a lavorare da subito per questo progetto sinergico, avvalendosi degli uffici turistici distaccati della Regione e presenti nel Golfo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Non \u00e8 facile pianificare strategie di sviluppo turistico in un grave momento di rigida contrazione della stagione turistica e delle spese da parte del turista, a causa della prolungata congiuntura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Turismo: le strategie di sviluppo nell&#039;incontro comprensoriale con il Direttore Generale dell&#039;Agenzia del Turismo della Regione Lazio - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turismo: le strategie di sviluppo nell&#039;incontro comprensoriale con il Direttore Generale dell&#039;Agenzia del Turismo della Regione Lazio - Gaeta\" \/>\n<meta property=\"og:description\" content=\"&#8220;Non \u00e8 facile pianificare strategie di sviluppo turistico in un grave momento di rigida contrazione della stagione turistica e delle spese da parte del turista, a causa della prolungata congiuntura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-31T15:10:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Turismo: le strategie di sviluppo nell&#8217;incontro comprensoriale con il Direttore Generale dell&#8217;Agenzia del Turismo della Regione Lazio\",\"datePublished\":\"2015-03-31T15:10:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/\"},\"wordCount\":469,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/\",\"name\":\"Turismo: le strategie di sviluppo nell'incontro comprensoriale con il Direttore Generale dell'Agenzia del Turismo della Regione Lazio - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"datePublished\":\"2015-03-31T15:10:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"width\":600,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/03\\\/31\\\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turismo: le strategie di sviluppo nell&#8217;incontro comprensoriale con il Direttore Generale dell&#8217;Agenzia del Turismo della Regione Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turismo: le strategie di sviluppo nell'incontro comprensoriale con il Direttore Generale dell'Agenzia del Turismo della Regione Lazio - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Turismo: le strategie di sviluppo nell'incontro comprensoriale con il Direttore Generale dell'Agenzia del Turismo della Regione Lazio - Gaeta","og_description":"&#8220;Non \u00e8 facile pianificare strategie di sviluppo turistico in un grave momento di rigida contrazione della stagione turistica e delle spese da parte del turista, a causa della prolungata congiuntura [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/","og_site_name":"Gaeta","article_published_time":"2015-03-31T15:10:05+00:00","og_image":[{"width":600,"height":354,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Turismo: le strategie di sviluppo nell&#8217;incontro comprensoriale con il Direttore Generale dell&#8217;Agenzia del Turismo della Regione Lazio","datePublished":"2015-03-31T15:10:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/"},"wordCount":469,"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/","url":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/","name":"Turismo: le strategie di sviluppo nell'incontro comprensoriale con il Direttore Generale dell'Agenzia del Turismo della Regione Lazio - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","datePublished":"2015-03-31T15:10:05+00:00","author":{"@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","width":600,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/03\/31\/turismo-le-strategie-di-sviluppo-nellincontro-comprensoriale-con-il-direttore-generale-dellagenzia-del-turismo-della-regione-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Turismo: le strategie di sviluppo nell&#8217;incontro comprensoriale con il Direttore Generale dell&#8217;Agenzia del Turismo della Regione Lazio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/gaeta\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/comments?post=562"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/562\/revisions"}],"predecessor-version":[{"id":564,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/562\/revisions\/564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/563"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/categories?post=562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/tags?post=562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}