{"id":618,"date":"2015-05-25T13:21:34","date_gmt":"2015-05-25T11:21:34","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?p=618"},"modified":"2015-05-25T13:21:34","modified_gmt":"2015-05-25T11:21:34","slug":"torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/","title":{"rendered":"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi"},"content":{"rendered":"<p style=\"text-align: justify;\">Ancora un accorato appello del Sindaco di Gaeta Cosmo Mitrano alla Regione Lazio affinch\u00e9 si proceda alla riqualificazione del Torrente Pontone, adottando tutti gli interventi necessari ad evitare future possibili perdite di ulteriori vite umane e lesioni gravi alle persone, danni agli edifici, alle infrastrutture e al patrimonio ambientale, nonch\u00e9 alle attivit\u00e0 socio-economiche.<\/p>\n<p style=\"text-align: justify;\">E&#8217; questo il contenuto della missiva inviata oggi dal Primo Cittadino di Gaeta a tutti gli Enti e organi coinvolti: Presidente della Regione Lazio On. Nicola Zingaretti, Assessore Infrastrutture, Politiche abitative, Ambiente On. Fabio Refrigeri, Ministro delle Infrastrutture e dei Trasporti On. Graziano Delrio, Area Genio Civile Lazio Sud, Sindaco di Formia Sandro Bartolomeo, Sindaco di Itri Giuseppe De Santis, Corpo Forestale dello Stato &#8211; Comando di Latina, Consorzio di Bonifica Sud Pontino, Prefettura di Latina, Direttore ARPA Lazio di Latina. Alla lettera il Sindaco Mitrano ha allegato l&#8217;interrogazione del 19\/05\/2015 sulla messa in sicurezza del Rio d&#8217;Itri\/Torrente Pontone, a firma del Comitato Pontone.<\/p>\n<p style=\"text-align: justify;\">Il Primo Cittadino rafforza il coro di proteste per il mancato avvio delle opere necessarie al ripristino della sicurezza degli argini del Torrente in questione, scrivendo &#8220;Nell&#8217;incontro tenutosi a Roma il 30 gennaio 2015 presso l&#8217;Assessorato Infrastrutture, Politiche abitative, Ambiente &#8211; presenti i Sindaci di Gaeta, Formia e Itri; i tecnici Fusco e Monacelli nonch\u00e9 due rappresentanti del Comitato Pontone &#8211; l&#8217;Assessore Fabio Refrigeri si era impegnato a reperire i fondi, anche alla luce dei trasferimenti statali previsti entro lo scorso mese di febbraio, assicurando che il progetto per la sistemazione del torrente Pontone, gi\u00e0 validato dai competenti uffici regionali, era stato gi\u00e0 inserito tra le priorit\u00e0 degli interventi sul dissesto idrogeologico.<br \/>\nNelle more, accogliendo la richiesta dei tre Sindaci, l&#8217;Assessore Refrigeri si era impegnato a garantire un primo intervento di 200.000 euro finalizzati a sagomare ed innalzare gli argini del torrente. Inoltre, per fare il punto della situazione, si era fatto carico di convocare un incontro con i tre Sindaci e i due rappresentanti del Comitato entro il mese di aprile.<\/p>\n<p style=\"text-align: justify;\">Gli interventi si rendono necessari ed improcrastinabili. Di questo sono consapevoli tutti gli enti dal momento che questa problematica \u00e8 diventata ormai di natura ordinaria e ricorrente. A noi preme che si intervenga per evitare di incorrere in un ulteriore rischio esondazione con l&#8217;approssimarsi della stagione autunnale, caratterizzata da copiose piogge&#8221;.<\/p>\n<p>Il Sindaco di Gaeta conclude il suo appello facendo notare che, essendo ormai giunti alla fine del mese di maggio, sarebbe cosa gradita &#8220;se l&#8217;Assessore Refrigeri fissasse la data dell&#8217;incontro a Roma al fine di acquisire elementi conoscitivi utili su modalit\u00e0 e tempistica degli interventi di riqualificazione da effettuare sul Torrente Pontone&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora un accorato appello del Sindaco di Gaeta Cosmo Mitrano alla Regione Lazio affinch\u00e9 si proceda alla riqualificazione del Torrente Pontone, adottando tutti gli interventi necessari ad evitare future possibili [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi - Gaeta\" \/>\n<meta property=\"og:description\" content=\"Ancora un accorato appello del Sindaco di Gaeta Cosmo Mitrano alla Regione Lazio affinch\u00e9 si proceda alla riqualificazione del Torrente Pontone, adottando tutti gli interventi necessari ad evitare future possibili [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-25T11:21:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi\",\"datePublished\":\"2015-05-25T11:21:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/\"},\"wordCount\":440,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/\",\"name\":\"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"datePublished\":\"2015-05-25T11:21:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/03\\\/logo-regione-lazio.jpg\",\"width\":600,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/05\\\/25\\\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/","og_locale":"it_IT","og_type":"article","og_title":"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi - Gaeta","og_description":"Ancora un accorato appello del Sindaco di Gaeta Cosmo Mitrano alla Regione Lazio affinch\u00e9 si proceda alla riqualificazione del Torrente Pontone, adottando tutti gli interventi necessari ad evitare future possibili [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/","og_site_name":"Gaeta","article_published_time":"2015-05-25T11:21:34+00:00","og_image":[{"width":600,"height":354,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi","datePublished":"2015-05-25T11:21:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/"},"wordCount":440,"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/","url":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/","name":"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","datePublished":"2015-05-25T11:21:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/03\/logo-regione-lazio.jpg","width":600,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/05\/25\/torrente-pontone-sindaco-mitrano-in-prima-linea-per-sollecitare-i-necessari-interventi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Torrente Pontone: Sindaco Mitrano in prima linea per sollecitare i necessari interventi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/gaeta\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/comments?post=618"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/618\/revisions"}],"predecessor-version":[{"id":619,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/618\/revisions\/619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/563"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/categories?post=618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/tags?post=618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}