{"id":625,"date":"2015-06-05T13:49:39","date_gmt":"2015-06-05T11:49:39","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?p=625"},"modified":"2015-06-05T13:49:39","modified_gmt":"2015-06-05T11:49:39","slug":"gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/","title":{"rendered":"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta"},"content":{"rendered":"<p style=\"text-align: justify;\">Sport, turismo, ambiente e spettacolo protagonisti assoluti a Gaeta nella prima edizione del Gaeta Sport eXperience Village. Dal 3 al 7 giugno 2015, in occasione del Campionato Europeo di Vela riservato alla classe Star, che si svolger\u00e0 nella cittadina del Golfo, il Comune, in collaborazione con lo Yacht Club Gaeta E.V.S ed il Club Nautico Gaeta e con il patrocinio di Regione Lazio, \u00a0Unindustria, FIV, CONI, e ISAF, organizza la prima esperienza di Villaggio dello Sport, interattivo e dinamico, in Piazza della Libert\u00e0.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">&#8220;Gaeta Sport eXperience Village &#8211; <strong>dichiara il Sindaco Cosmo Mitrano<\/strong> &#8211;\u00a0 sar\u00e0 una grande palestra, opportunamente attrezzata per conoscere e sperimentare tantissime discipline sportive, sopratutto quelle meno diffuse e quelle pi\u00f9 nuove. Una vera e propria vetrina dello Sport dove gli stand non saranno semplicemente espositivi, ma\u00a0 allestiti per la pratica sportiva. Inoltre l&#8217;evento sar\u00e0 anche \u00a0l&#8217;avvio, sul nostro territorio, di iniziative volte a sviluppare una forma di turismo, in Italia ancora &#8220;di nicchia&#8221;, ma che va diffondendosi rapidamente: quello sportivo. Gaeta e l&#8217;intero Golfo sono in realt\u00e0 una palestra straordinaria, dove mare e montagna si fondono, creando un ambiente unico nel quale \u00e8 possibile praticare infinite attivit\u00e0 sportive 365 giorni l&#8217;anno. Una grande opportunit\u00e0 per il nostro territorio, un input che dobbiamo assolutamente raccogliere per sfruttarne le potenzialit\u00e0 di sviluppo in termini economici e occupazionali&#8221;.<\/p>\n<p style=\"text-align: justify;\">Davvero notevoli le proposte di sport e movimento del Gaeta Sport eXperience Village in Piazza della Libert\u00e0 e nella darsena, come spiega <strong>l&#8217;Assessore allo Sport Gigi Ridolfi<\/strong> :&#8221;Il villaggio in Piazza\u00a0 della Libert\u00e0, ad ingresso libero, sar\u00e0 allestito con piscina, rampa per lo skate, mini campo polivalente, area maneggio, \u00a0per consentire a tutti i visitatori di cimentarsi\u00a0 in: idrobike, rugby,\u00a0 volley, calcio femminile, basket, Mountain Bike, arti marziali, equitazione, skateboard, minihalfpipe, breakdance, kickboxing, tennis da tavolo ed anche urban rebounding ovvero il fitness con il tappetino elastico. E non solo&#8230; con prenotazione obbligatoria si potr\u00e0\u00a0 sperimentare il Tree Climbing, fare un tour in bicicletta, \u00a0provare il brivido di un giro sulla Ferrari. Le Mitiche Rosse, infatti, vi aspettano al villaggio dove saranno in esposizione sabato 6 e domenica 7 giugno, tutto a cura del Club Ferrari. Tanto sport anche \u00a0in mare, nella darsena, dove si potr\u00e0 familiarizzare con il diving, conoscere il coastal rowing, sperimentare lo sci nautico, il Sup (<strong>stand up paddle<\/strong>, una variante del surf in cui si sta in piedi su una longboard e ci si sposta utilizzando una pagaia), \u00a0assistere a dimostrazioni di voga e polobeach, e per i pi\u00f9 piccoli divertimento garantito con il windsurf, la vela e le dimostrazioni di pesca! Numerose, quindi, le occasioni per fare attivit\u00e0 fisica e stare in compagnia. Non perdiamo questa bella opportunit\u00e0!&#8221;<\/p>\n<p style=\"text-align: justify;\">Davvero notevoli le proposte di sport e movimento del Gaeta Sport eXperience Village in Piazza della Libert\u00e0 e nella darsena, come spiega :&#8221;,<\/p>\n<p style=\"text-align: justify;\">Gaeta Sport eXperience Village \u00e8 anche Grandi Eventi, tra gli altri: <strong>gioved\u00ec 4 alle ore 20.45 l&#8217;incontro &#8220;In vetta al mondo<\/strong>&#8221; <strong>con l&#8217;alpinista Daniele Nardi,<\/strong> durante il quale sar\u00e0 proiettato un video commentato dal vivo dallo sportivo Le immagini \u00a0 raccontano la storia dell&#8217;alpinista di Sezze a partire\u00a0dalle prime scalate fatte sui monti Lepini fino alla grande sfida al Nanga Parbat in inverno. Un percorso di crescita\u00a0alpinistica ed umana, durante il quale Daniele Nardi impara a scalare le\u00a0montagne di 8000m e che lo porta a decidere di affrontare in Stile Alpino il\u00a0Nanga Parbat.\u00a0Idea folle e visionaria mai applicata in maniera integrale da nessuna spedizione nella\u00a0storia alpinistica. <strong>Venerd\u00ec 5 giugno, alle ore 17,\u00a0 la Darsena Yacht Club ospiter\u00e0 il Convegno sul tema &#8220;Turismo Sportivo: Opportunit\u00e0 di crescita per il territorio&#8221;,<\/strong> a cura di Unindustria, Yacht Club Gaeta e Club Nautico Gaeta. <strong>Mentre alle ore 21.30 al Villaggio I Cameristi Italiani dell&#8217;Ass. Europa Musica presentano &#8220;I Capolavori del Cinema Italiano&#8221;.<\/strong> <strong>Sabato 6 sar\u00e0 allestito il maxi schermo in occasione della finale di Champions League Juventus &#8211; Barcellona,<\/strong> con inizio alle ore 20.45. <strong>Sabato e Domenica a Gaeta Medievale e Serapo si svolger\u00e0 la Gaeta Sup Race, a cura di MCD Surf Club Gaeta.<\/strong> Infine saranno esposti i lavori del Progetto &#8220;Enea e la sua nave da Troia alla Foce del Tevere&#8221;, a cura dell&#8217;Istituto Comprensivo Principe Amedeo e l&#8217;Associazione Gaeta e il Mare.<\/p>\n<p style=\"text-align: justify;\">Gaeta Sport eXperience Village \u00e8 anche Grandi Eventi, tra gli altri: &#8221; durante il quale sar\u00e0 proiettato un video commentato dal vivo dallo sportivo Le immagini \u00a0 raccontano la storia dell&#8217;alpinista di Sezze a partire\u00a0dalle prime scalate fatte sui monti Lepini fino alla grande sfida al Nanga Parbat in inverno. Un percorso di crescita\u00a0alpinistica ed umana, durante il quale Daniele Nardi impara a scalare le\u00a0montagne di 8000m e che lo porta a decidere di affrontare in Stile Alpino il\u00a0Nanga Parbat.\u00a0Idea folle e visionaria mai applicata in maniera integrale da nessuna spedizione nella\u00a0storia alpinistica. a cura di Unindustria, Yacht Club Gaeta e Club Nautico Gaeta. con inizio alle ore 20.45. Infine saranno esposti i lavori del Progetto &#8220;Enea e la sua nave da Troia alla Foce del Tevere&#8221;, a cura dell&#8217;Istituto Comprensivo Principe Amedeo e l&#8217;Associazione Gaeta e il Mare.<\/p>\n<p style=\"text-align: justify;\">\nMa soprattutto\u00a0dal 3 al 7 giugno, Gaeta ed il suo incantevole Golfo faranno da scenario al Campionato Europeo di Vela Classe Star. La Star Sailor League, in considerazione dell&#8217;importanza delle regate di Gaeta, ha organizzato la possibilit\u00e0 di seguire virtualmente il Campionato attraverso il sito web <a href=\"http:\/\/www.starsailors.com\/\"><span style=\"color: #0000ff;\">www.starsailors.com<\/span><\/a>. Le nuove tecnologie in termini di connettivit\u00e0 web permettono di ricevere a terra il segnale di movimento di ogni singola imbarcazione. Un software, appositamente creato per la Classe Star, restituir\u00e0 sul web o sugli schermi installati nel Villaggio, tutte le posizioni\u00a0simulando gli effettivi movimenti delle star.<\/p>\n<p style=\"text-align: justify;\">\nIl Campionato Europeo di Vela Classe Star vedr\u00e0 la collaborazione dell&#8217;Istituto Nautico Caboto e del Liceo Scientifico Fermi.\u00a0 Grazie all&#8217;azienda agricola Cosmo Di Russo ciascun equipaggio potr\u00e0 gustare gli ottimi prodotti della terra gaetana, in primis le olive.<\/p>\n<p style=\"text-align: justify;\">\n&#8220;Ben 35 le associazioni del territorio coinvolte nell&#8217;organizzazione di Gaeta Sport eXperience \u00a0Village &#8211; <strong>ricorda il collaboratore del Sindaco ai Grandi Eventi Dino Pascali<\/strong>\u00a0 &#8211; una sinergia vincente per dare alla nostra citt\u00e0, all&#8217;intero Golfo e a tutti i visitatori la grande opportunit\u00e0 di vivere un evento di profilo internazionale qual \u00e8 Campionato Europeo di Vela\u00a0 in un contesto sportivo, culturale\u00a0 e ambientale del tutto nuovo e ricco di stimoli!&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sport, turismo, ambiente e spettacolo protagonisti assoluti a Gaeta nella prima edizione del Gaeta Sport eXperience Village. Dal 3 al 7 giugno 2015, in occasione del Campionato Europeo di Vela [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta - Gaeta\" \/>\n<meta property=\"og:description\" content=\"Sport, turismo, ambiente e spettacolo protagonisti assoluti a Gaeta nella prima edizione del Gaeta Sport eXperience Village. Dal 3 al 7 giugno 2015, in occasione del Campionato Europeo di Vela [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-05T11:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/06\/gaeta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"308\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta\",\"datePublished\":\"2015-06-05T11:49:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/\"},\"wordCount\":1042,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/06\\\/gaeta.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/\",\"name\":\"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/06\\\/gaeta.jpg\",\"datePublished\":\"2015-06-05T11:49:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/06\\\/gaeta.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2015\\\/06\\\/gaeta.jpg\",\"width\":308,\"height\":164},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/2015\\\/06\\\/05\\\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/","og_locale":"it_IT","og_type":"article","og_title":"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta - Gaeta","og_description":"Sport, turismo, ambiente e spettacolo protagonisti assoluti a Gaeta nella prima edizione del Gaeta Sport eXperience Village. Dal 3 al 7 giugno 2015, in occasione del Campionato Europeo di Vela [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/","og_site_name":"Gaeta","article_published_time":"2015-06-05T11:49:39+00:00","og_image":[{"width":308,"height":164,"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/06\/gaeta.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta","datePublished":"2015-06-05T11:49:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/"},"wordCount":1042,"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/06\/gaeta.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/","url":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/","name":"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/06\/gaeta.jpg","datePublished":"2015-06-05T11:49:39+00:00","author":{"@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#primaryimage","url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/06\/gaeta.jpg","contentUrl":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2015\/06\/gaeta.jpg","width":308,"height":164},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/2015\/06\/05\/gaeta-sport-experience-village-sport-turismo-ambiente-e-spettacolo-protagonisti-a-gaeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Gaeta Sport eXperience Village: Sport, turismo, ambiente e spettacolo protagonisti a Gaeta"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/gaeta\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/gaeta\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"predecessor-version":[{"id":627,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/posts\/625\/revisions\/627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media\/626"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}