{"id":730,"date":"2016-07-22T14:28:30","date_gmt":"2016-07-22T12:28:30","guid":{"rendered":"https:\/\/comunicacity.net\/gaeta\/?post_type=rdif&#038;p=730"},"modified":"2016-08-02T16:34:47","modified_gmt":"2016-08-02T14:34:47","slug":"lunedi","status":"publish","type":"rdif","link":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/","title":{"rendered":"Luned\u00ec"},"content":{"rendered":"<h1 class=\"ccAzure ccCenter\">Carta e Cartone<\/h1>\n<div class=\"ccCenter\">\n   <span class=\"fa-stack fa-4x\"><i class=\"fa fa-circle fa-stack-2x ccAzure\"><\/i><i class=\"fa fa-trash fa-stack-1x fa-inverse\"><\/i><\/span>\n<\/div>\n<h3 class=\"ccAzure ccCenter\">Secchio o carrellato blu<\/h3>\n<p>\n    <i class=\"fa fa-clock-o\"><\/i> Raccolta effettuata tutto l&#8217;anno.\n<\/p>\n<hr>\n<h1 class=\"ccGrey ccCenter\">Indifferenziato<\/h1>\n<div class=\"ccCenter\">\n   <span class=\"fa-stack fa-4x\"><i class=\"fa fa-circle fa-stack-2x ccGrey\"><\/i><i class=\"fa fa-trash fa-stack-1x fa-inverse\"><\/i><\/span>\n<\/div>\n<h3 class=\"ccGrey ccCenter\">Secchio o carrellato grigio<\/h3>\n<p>\n    <i class=\"fa fa-clock-o\"><\/i> Raccolta effettuata da maggio a settembre.\n<\/p>\n<hr>\n<h1 class=\"ccBrown ccCenter\">Organico<\/h1>\n<div class=\"ccCenter\">\n   <span class=\"fa-stack fa-4x\"><i class=\"fa fa-circle fa-stack-2x ccBrown\"><\/i><i class=\"fa fa-trash fa-stack-1x fa-inverse\"><\/i><\/span>\n<\/div>\n<h3 class=\"ccBrown ccCenter\">Secchio o carrellato marrone<\/h3>\n<p>\n    <i class=\"fa fa-clock-o\"><\/i> Raccolta effettuata tutto l&#8217;anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carta e Cartone Secchio o carrellato blu Raccolta effettuata tutto l&#8217;anno. Indifferenziato Secchio o carrellato grigio Raccolta effettuata da maggio a settembre. Organico Secchio o carrellato marrone Raccolta effettuata tutto [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":729,"menu_order":1,"template":"","meta":[],"class_list":["post-730","rdif","type-rdif","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luned\u00ec - Gaeta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luned\u00ec - Gaeta\" \/>\n<meta property=\"og:description\" content=\"Carta e Cartone Secchio o carrellato blu Raccolta effettuata tutto l&#8217;anno. Indifferenziato Secchio o carrellato grigio Raccolta effettuata da maggio a settembre. Organico Secchio o carrellato marrone Raccolta effettuata tutto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/\" \/>\n<meta property=\"og:site_name\" content=\"Gaeta\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-02T14:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/rdif\\\/calendario-commerciale\\\/lunedi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/rdif\\\/calendario-commerciale\\\/lunedi\\\/\",\"name\":\"Luned\u00ec - Gaeta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\"},\"datePublished\":\"2016-07-22T12:28:30+00:00\",\"dateModified\":\"2016-08-02T14:34:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/rdif\\\/calendario-commerciale\\\/lunedi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/rdif\\\/calendario-commerciale\\\/lunedi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/rdif\\\/calendario-commerciale\\\/lunedi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendario commerciale\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/rdif\\\/calendario-commerciale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luned\u00ec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/\",\"name\":\"Gaeta\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/gaeta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luned\u00ec - Gaeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/","og_locale":"it_IT","og_type":"article","og_title":"Luned\u00ec - Gaeta","og_description":"Carta e Cartone Secchio o carrellato blu Raccolta effettuata tutto l&#8217;anno. Indifferenziato Secchio o carrellato grigio Raccolta effettuata da maggio a settembre. Organico Secchio o carrellato marrone Raccolta effettuata tutto [&hellip;]","og_url":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/","og_site_name":"Gaeta","article_modified_time":"2016-08-02T14:34:47+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/gaeta\/wp-content\/uploads\/sites\/6\/2014\/11\/gaeta.jpg","height":50,"width":50,"type":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/","url":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/","name":"Luned\u00ec - Gaeta","isPartOf":{"@id":"https:\/\/comunicacity.net\/gaeta\/#website"},"datePublished":"2016-07-22T12:28:30+00:00","dateModified":"2016-08-02T14:34:47+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/lunedi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/gaeta\/"},{"@type":"ListItem","position":2,"name":"Calendario commerciale","item":"https:\/\/comunicacity.net\/gaeta\/rdif\/calendario-commerciale\/"},{"@type":"ListItem","position":3,"name":"Luned\u00ec"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/gaeta\/#website","url":"https:\/\/comunicacity.net\/gaeta\/","name":"Gaeta","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/gaeta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/rdif\/730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/rdif"}],"about":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/types\/rdif"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/rdif\/729"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/gaeta\/wp-json\/wp\/v2\/media?parent=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}