{"id":182,"date":"2025-03-11T08:37:53","date_gmt":"2025-03-11T07:37:53","guid":{"rendered":"https:\/\/comunicacity.net\/galluccio\/?p=182"},"modified":"2025-03-11T08:37:57","modified_gmt":"2025-03-11T07:37:57","slug":"interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/","title":{"rendered":"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale"},"content":{"rendered":"<p><em>Ordinanza n. 15 &#8211; Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>DIPARTIMENTO AREA TERRITORIO E INNOVAZIONE<\/strong><br \/>\n<strong>SETTORE VIABILIT\u00c0 E TRASPORTI<\/strong><br \/>\n<strong>SERVIZIO DIREZIONE LAVORI MANUTENZIONE ORDINARIA E STRAORDINARIA<\/strong><\/p>\n<p><strong>Provincia di Caserta<\/strong><\/p>\n<p><strong>OGGETTO: Ordinanza n. 15 del 11\/02\/2025<\/strong><br \/>\nInterventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_196\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/prot_par-0008531-del-13-02-2025-allegato-atto-originale-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/prot_par-0008531-del-13-02-2025-allegato-atto-originale-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>prot_par 0008531 del 13-02-2025 &#8211; allegato atto originale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ordinanza n. 15 &#8211; Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale - Galluccio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale - Galluccio\" \/>\n<meta property=\"og:description\" content=\"Ordinanza n. 15 &#8211; Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/\" \/>\n<meta property=\"og:site_name\" content=\"Galluccio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T07:37:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T07:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/pcaserta-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"782\" \/>\n\t<meta property=\"og:image:height\" content=\"241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale\",\"datePublished\":\"2025-03-11T07:37:53+00:00\",\"dateModified\":\"2025-03-11T07:37:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/\"},\"wordCount\":116,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2025\\\/03\\\/pcaserta-1.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/\",\"name\":\"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale - Galluccio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2025\\\/03\\\/pcaserta-1.png\",\"datePublished\":\"2025-03-11T07:37:53+00:00\",\"dateModified\":\"2025-03-11T07:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2025\\\/03\\\/pcaserta-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2025\\\/03\\\/pcaserta-1.png\",\"width\":782,\"height\":241},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2025\\\/03\\\/11\\\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale - Galluccio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/","og_locale":"it_IT","og_type":"article","og_title":"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale - Galluccio","og_description":"Ordinanza n. 15 &#8211; Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con [&hellip;]","og_url":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/","og_site_name":"Galluccio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-11T07:37:53+00:00","article_modified_time":"2025-03-11T07:37:57+00:00","og_image":[{"width":782,"height":241,"url":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/pcaserta-1.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale","datePublished":"2025-03-11T07:37:53+00:00","dateModified":"2025-03-11T07:37:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/"},"wordCount":116,"publisher":{"@id":"https:\/\/comunicacity.net\/galluccio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/pcaserta-1.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/","url":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/","name":"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale - Galluccio","isPartOf":{"@id":"https:\/\/comunicacity.net\/galluccio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/pcaserta-1.png","datePublished":"2025-03-11T07:37:53+00:00","dateModified":"2025-03-11T07:37:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#primaryimage","url":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/pcaserta-1.png","contentUrl":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2025\/03\/pcaserta-1.png","width":782,"height":241},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galluccio\/2025\/03\/11\/interventi-a-tutela-della-sicurezza-nella-percorrenza-delle-strade-di-competenza-provinciale-e-prevenzione-degli-incendi-manutenzione-della-vegetazione-e-dei-muri-dei-fondi-confinanti-con-la-pertinen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galluccio\/"},{"@type":"ListItem","position":2,"name":"Interventi a tutela della sicurezza nella percorrenza delle strade di competenza provinciale e prevenzione degli incendi: Manutenzione della vegetazione e dei muri dei fondi confinanti con la pertinenza stradale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galluccio\/#website","url":"https:\/\/comunicacity.net\/galluccio\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/galluccio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galluccio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/galluccio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/galluccio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002635"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/comments?post=182"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts\/182\/revisions"}],"predecessor-version":[{"id":184,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts\/182\/revisions\/184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/media\/195"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/media?parent=182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/categories?post=182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/tags?post=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}