{"id":451,"date":"2026-01-13T13:44:27","date_gmt":"2026-01-13T12:44:27","guid":{"rendered":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/"},"modified":"2026-01-13T13:44:27","modified_gmt":"2026-01-13T12:44:27","slug":"avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/","title":{"rendered":"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d"},"content":{"rendered":"<p><em>IL SEGRETARIO COMUNALE\/RPCT RENDE NOTO CHE<br \/>\n\u00e8 avviata la procedura aperta di consultazione, esterna ed interna, ai fini della formulazione di proposte e suggerimenti per l\u2019adozione del nuovo PIAO  2026\/2028 del Comune di Galluccio.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Tutti gli interessati: cittadini, stakeholders e soggetti esterni, nonch\u00e9 i dipendenti e gli amministratori locali, i collaboratori, anche consulenti, e i titolari degli uffici di diretta collaborazione con gli organi dell\u2019ente a presentare contributi e\/o proposte ai fini dell\u2019aggiornamento del Piano Triennale di Prevenzione della Corruzione e della Trasparenza, sottosezione \u201cRischi corruttivi e trasparenza\u201d della sezione \u201cValore pubblico, performance e anticorruzione\u201d del PIAO del Comune di Galluccio per il triennio 2026-2028.<br \/>\nLe proposte potranno essere inviate a questo Ente entro e non oltre il termine perentorio del 23 gennaio 2026 utilizzando il modulo pubblicato in allegato al presente avviso, da trasmettere secondo le seguenti modalit\u00e0:<br \/>\n1. tramite posta elettronica certificata al seguente indirizzo:<br \/>\nsegretariocomunale@pec.comune.galluccio.ce.it<br \/>\n2. tramite posta elettronica ordinaria al seguente indirizzo:<br \/>\nsegretariocomunale@comune.galluccio.ce.it<br \/>\n3. tramite consegna a mano presso la Casa comunale.<br \/>\nIn sede di predisposizione dell\u2019aggiornamento, il Comune di Galluccio potr\u00e0 tener conto degli eventuali contributi pervenuti.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_453\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/avviso-consultazione-piao_signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/avviso-consultazione-piao_signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso consultazione piao_signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>IL SEGRETARIO COMUNALE\/RPCT RENDE NOTO CHE \u00e8 avviata la procedura aperta di consultazione, esterna ed interna, ai fini della formulazione di proposte e suggerimenti per l\u2019adozione del nuovo PIAO 2026\/2028 [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d - Galluccio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d - Galluccio\" \/>\n<meta property=\"og:description\" content=\"IL SEGRETARIO COMUNALE\/RPCT RENDE NOTO CHE \u00e8 avviata la procedura aperta di consultazione, esterna ed interna, ai fini della formulazione di proposte e suggerimenti per l\u2019adozione del nuovo PIAO 2026\/2028 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/\" \/>\n<meta property=\"og:site_name\" content=\"Galluccio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-13T12:44:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/stemma-galluccio.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d\",\"datePublished\":\"2026-01-13T12:44:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/\"},\"wordCount\":215,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2026\\\/01\\\/stemma-galluccio.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/\",\"name\":\"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d - Galluccio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2026\\\/01\\\/stemma-galluccio.png\",\"datePublished\":\"2026-01-13T12:44:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2026\\\/01\\\/stemma-galluccio.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/2026\\\/01\\\/stemma-galluccio.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/2026\\\/01\\\/13\\\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galluccio\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d - Galluccio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d - Galluccio","og_description":"IL SEGRETARIO COMUNALE\/RPCT RENDE NOTO CHE \u00e8 avviata la procedura aperta di consultazione, esterna ed interna, ai fini della formulazione di proposte e suggerimenti per l\u2019adozione del nuovo PIAO 2026\/2028 [&hellip;]","og_url":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/","og_site_name":"Galluccio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-13T12:44:27+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/stemma-galluccio.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d","datePublished":"2026-01-13T12:44:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/"},"wordCount":215,"publisher":{"@id":"https:\/\/comunicacity.net\/galluccio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/stemma-galluccio.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/","url":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/","name":"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d - Galluccio","isPartOf":{"@id":"https:\/\/comunicacity.net\/galluccio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/stemma-galluccio.png","datePublished":"2026-01-13T12:44:27+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#primaryimage","url":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/stemma-galluccio.png","contentUrl":"https:\/\/comunicacity.net\/galluccio\/wp-content\/uploads\/sites\/220\/2026\/01\/stemma-galluccio.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galluccio\/2026\/01\/13\/avviso-per-consultazione-pubblica-piano-integrato-di-attivita-e-organizzazione-2026-2028-sezione-valore-pubblico-performance-e-anticorruzione-sottosezione-rischi-corrutti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galluccio\/"},{"@type":"ListItem","position":2,"name":"AVVISO PER CONSULTAZIONE PUBBLICA PIANO INTEGRATO DI ATTIVIT\u00c0 E ORGANIZZAZIONE 2026-2028 SEZIONE: \u201cVALORE PUBBLICO, PERFORMANCE E ANTICORRUZIONE\u201d SOTTOSEZIONE: \u201cRISCHI CORRUTTIVI E TRASPARENZA\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galluccio\/#website","url":"https:\/\/comunicacity.net\/galluccio\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/galluccio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galluccio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/galluccio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/galluccio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galluccio\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002804"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts\/451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/comments?post=451"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/posts\/451\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/media\/452"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/media?parent=451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/categories?post=451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galluccio\/wp-json\/wp\/v2\/tags?post=451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}