{"id":205,"date":"2015-12-18T12:55:42","date_gmt":"2015-12-18T10:55:42","guid":{"rendered":"https:\/\/comunicacity.net\/galverla\/?p=205"},"modified":"2015-12-18T12:55:42","modified_gmt":"2015-12-18T10:55:42","slug":"storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/","title":{"rendered":"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato"},"content":{"rendered":"<p style=\"text-align: justify;\">Il Presidente del GAL Loreto Policella e tutto lo staff hanno il piacere di invitarvi alla presentazione del libro &#8220;Storie di ordinaria persecuzione&#8221; di Antonio Pellegrini, che si terr\u00e0 sabato 19 dicembre 2015, alle ore 16.30, presso la Sala Consiliare del Comune di San Donato Valcomino.<\/p>\n<p style=\"text-align: justify;\">Tema del volume e dell&#8217;incontro le vicende umane, la militanza politica e l&#8217;impegno civile in Val di Comino e Provincia di Frosinone dal 1894 al 1943. Interveranno il Sindaco del Comune di San Donato Enrico Pittiglio, il Presidente del Galverla Loreto Policella, lo storico e docente dell&#8217;Universit\u00e0 degli studi di Cassino Pasquale Beneduce e il prof. Guido Pescosolido dell&#8217;Universit\u00e0 La Sapienza di Roma. A presentare Tonino Bernardelli mentre il commento musicale sar\u00e0 curato da Giacomo Cellucci. Sar\u00e0 anche l&#8217;occasione per uno scambio di auguri in vista delle imminenti festivit\u00e0 natalizie.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente del GAL Loreto Policella e tutto lo staff hanno il piacere di invitarvi alla presentazione del libro &#8220;Storie di ordinaria persecuzione&#8221; di Antonio Pellegrini, che si terr\u00e0 sabato [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato - GALVERLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato - GALVERLA\" \/>\n<meta property=\"og:description\" content=\"Il Presidente del GAL Loreto Policella e tutto lo staff hanno il piacere di invitarvi alla presentazione del libro &#8220;Storie di ordinaria persecuzione&#8221; di Antonio Pellegrini, che si terr\u00e0 sabato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/\" \/>\n<meta property=\"og:site_name\" content=\"GALVERLA\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-18T10:55:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/12\/storie-ordinaria-persecuzione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato\",\"datePublished\":\"2015-12-18T10:55:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/\"},\"wordCount\":147,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/12\\\/storie-ordinaria-persecuzione.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/\",\"name\":\"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato - GALVERLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/12\\\/storie-ordinaria-persecuzione.jpg\",\"datePublished\":\"2015-12-18T10:55:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/12\\\/storie-ordinaria-persecuzione.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/12\\\/storie-ordinaria-persecuzione.jpg\",\"width\":300,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/12\\\/18\\\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\",\"name\":\"GALVERLA\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato - GALVERLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/","og_locale":"it_IT","og_type":"article","og_title":"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato - GALVERLA","og_description":"Il Presidente del GAL Loreto Policella e tutto lo staff hanno il piacere di invitarvi alla presentazione del libro &#8220;Storie di ordinaria persecuzione&#8221; di Antonio Pellegrini, che si terr\u00e0 sabato [&hellip;]","og_url":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/","og_site_name":"GALVERLA","article_published_time":"2015-12-18T10:55:42+00:00","og_image":[{"width":300,"height":400,"url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/12\/storie-ordinaria-persecuzione.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato","datePublished":"2015-12-18T10:55:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/"},"wordCount":147,"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/12\/storie-ordinaria-persecuzione.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/","url":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/","name":"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato - GALVERLA","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/12\/storie-ordinaria-persecuzione.jpg","datePublished":"2015-12-18T10:55:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#primaryimage","url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/12\/storie-ordinaria-persecuzione.jpg","contentUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/12\/storie-ordinaria-persecuzione.jpg","width":300,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galverla\/2015\/12\/18\/storie-di-ordinaria-persecuzione-il-19-dicembre-la-presentazione-del-libro-di-antonio-pellegrini-a-san-donato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galverla\/"},{"@type":"ListItem","position":2,"name":"Storie di ordinaria persecuzione: il 19 dicembre la presentazione del libro di Antonio Pellegrini a San Donato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galverla\/#website","url":"https:\/\/comunicacity.net\/galverla\/","name":"GALVERLA","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galverla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/galverla\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"predecessor-version":[{"id":207,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/205\/revisions\/207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media\/206"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}