{"id":238,"date":"2016-03-10T13:46:33","date_gmt":"2016-03-10T11:46:33","guid":{"rendered":"https:\/\/comunicacity.net\/galverla\/?p=238"},"modified":"2016-03-10T13:46:33","modified_gmt":"2016-03-10T11:46:33","slug":"parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/","title":{"rendered":"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO"},"content":{"rendered":"<p><strong>Il CDA del GAL Versante Laziale del PNA<\/strong>, <strong>con delibera n. 6 del 7.03.2016<\/strong> ha approvato gli esiti della Commissione di Valutazione del bando per l&#8217;affidamento del servizio di supporto alla <strong>redazione del<\/strong> <strong>Piano di Sviluppo Locale 2014-2020:\u00a0<\/strong><\/p>\n<p>1-\u00a0 Raggruppamento temporaneo di professionisti <strong>TERRE DI COMINO<\/strong>\u00a0 &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 punteggio \u00a0<strong>95,33\/100<\/strong><\/p>\n<p>2 &#8211; Raggruppamento temporaneo di imprese <strong>SL&amp;A- AGRIPLAN<\/strong>\u00a0 &#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 punteggio \u00a0<strong>79\/100<\/strong><\/p>\n<p>3 &#8211; Raggruppamento temporaneo di imprese <strong>GLOBAL &amp; LOCAL<\/strong> srl &#8211; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 punteggio \u00a0<strong>35,83\/100<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Entra nel vivo la fase di ascolto per la predisposizione del nuovo PSL del Gal Verla che vedr\u00e0 impegnati i tecnici incaricati, \u00a0le amministrazioni, le associazioni, le imprese e i cittadini.<\/p>\n<p><strong>Gli ambiti tematici<\/strong> che saranno affrontati sono quelli <strong>dell\u2019accordo di partenariato<\/strong> come di seguito elencati:\u00a0 sviluppo e innovazione delle filiere e dei sistemi produttivi locali (agro-alimentari, artigianali e manifatturieri, produzioni ittiche); sviluppo della filiera dell\u2019energia rinnovabile (produzione e risparmio energia); turismo sostenibile; cura e tutela del paesaggio, dell\u2019uso del suolo e della biodiversit\u00e0 (animale e vegetale);\u00a0 valorizzazione e gestione delle risorse ambientali e naturali; valorizzazione di beni culturali e patrimonio artistico legato al territorio; accesso ai servizi pubblici essenziali; inclusione sociale di specifici gruppi svantaggiati e\/o marginali ; riqualificazione urbana con la creazione di servizi e spazi inclusivi per la comunit\u00e0; reti e comunit\u00e0 intelligenti.<\/p>\n<p>Per impostare l\u2019iter partecipativo del PSL si proporranno\u00a0 in particolar modo dei <strong>Tavoli di Lavoro.<\/strong><\/p>\n<p>Si invitano tutti i soggetti attivi del territorio a prendere parte al dialogo paritario e costruttivo per individuare soluzioni a breve\/medio\/lungo termine.<\/p>\n<p>info www.galverla.eu<\/p>\n<p>tel. 0776 513015<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il CDA del GAL Versante Laziale del PNA, con delibera n. 6 del 7.03.2016 ha approvato gli esiti della Commissione di Valutazione del bando per l&#8217;affidamento del servizio di supporto [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO - GALVERLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO - GALVERLA\" \/>\n<meta property=\"og:description\" content=\"Il CDA del GAL Versante Laziale del PNA, con delibera n. 6 del 7.03.2016 ha approvato gli esiti della Commissione di Valutazione del bando per l&#8217;affidamento del servizio di supporto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/\" \/>\n<meta property=\"og:site_name\" content=\"GALVERLA\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-10T11:46:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/03\/DSC_4472-arancio-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"galverla\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"galverla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/\"},\"author\":{\"name\":\"galverla\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/7d4e62a7171593b2b1dc6378fe56d612\"},\"headline\":\"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO\",\"datePublished\":\"2016-03-10T11:46:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/\"},\"wordCount\":266,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/03\\\/DSC_4472-arancio-2-1.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/\",\"name\":\"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO - GALVERLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/03\\\/DSC_4472-arancio-2-1.jpg\",\"datePublished\":\"2016-03-10T11:46:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/7d4e62a7171593b2b1dc6378fe56d612\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/03\\\/DSC_4472-arancio-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/03\\\/DSC_4472-arancio-2-1.jpg\",\"width\":600,\"height\":379},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/03\\\/10\\\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\",\"name\":\"GALVERLA\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/7d4e62a7171593b2b1dc6378fe56d612\",\"name\":\"galverla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g\",\"caption\":\"galverla\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/author\\\/galverla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO - GALVERLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/","og_locale":"it_IT","og_type":"article","og_title":"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO - GALVERLA","og_description":"Il CDA del GAL Versante Laziale del PNA, con delibera n. 6 del 7.03.2016 ha approvato gli esiti della Commissione di Valutazione del bando per l&#8217;affidamento del servizio di supporto [&hellip;]","og_url":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/","og_site_name":"GALVERLA","article_published_time":"2016-03-10T11:46:33+00:00","og_image":[{"width":600,"height":379,"url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/03\/DSC_4472-arancio-2-1.jpg","type":"image\/jpeg"}],"author":"galverla","twitter_misc":{"Scritto da":"galverla","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/"},"author":{"name":"galverla","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/7d4e62a7171593b2b1dc6378fe56d612"},"headline":"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO","datePublished":"2016-03-10T11:46:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/"},"wordCount":266,"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/03\/DSC_4472-arancio-2-1.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/","url":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/","name":"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO - GALVERLA","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/03\/DSC_4472-arancio-2-1.jpg","datePublished":"2016-03-10T11:46:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/7d4e62a7171593b2b1dc6378fe56d612"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#primaryimage","url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/03\/DSC_4472-arancio-2-1.jpg","contentUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/03\/DSC_4472-arancio-2-1.jpg","width":600,"height":379},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galverla\/2016\/03\/10\/parte-la-redazione-del-psl-affidata-al-gruppo-di-lavoro-terre-di-comino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galverla\/"},{"@type":"ListItem","position":2,"name":"PARTE LA REDAZIONE DEL PSL, AFFIDATA AL GRUPPO DI LAVORO TERRE DI COMINO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galverla\/#website","url":"https:\/\/comunicacity.net\/galverla\/","name":"GALVERLA","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galverla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/7d4e62a7171593b2b1dc6378fe56d612","name":"galverla","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g","caption":"galverla"},"url":"https:\/\/comunicacity.net\/galverla\/author\/galverla\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/comments?post=238"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/238\/revisions"}],"predecessor-version":[{"id":240,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/238\/revisions\/240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media\/239"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media?parent=238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/categories?post=238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/tags?post=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}