{"id":279,"date":"2016-04-28T17:01:35","date_gmt":"2016-04-28T15:01:35","guid":{"rendered":"https:\/\/comunicacity.net\/galverla\/?p=279"},"modified":"2016-04-28T17:01:35","modified_gmt":"2016-04-28T15:01:35","slug":"tavolo-di-lavoro-la-valorizzazione-della-montagna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/","title":{"rendered":"TAVOLO DI LAVORO &#8220;LA VALORIZZAZIONE DELLA MONTAGNA&#8221;"},"content":{"rendered":"<p>Dopo l&#8217;incontro tenutosi ieri a Picinisco, continuano i tavoli di lavoro per la costruzione del Piano di Sviluppo Locale del Gal Versante Laziale del PNA relativi a:<\/p>\n<p>&#8220;<strong>VALORIZZAZIONE DELLA MONTAGNA:<\/strong><\/p>\n<p><strong>Cooperative di comunit\u00e0, attivit\u00e0 forestali e agricole, energie rinnovabili e inclusione sociale&#8221;.<\/strong><\/p>\n<p><strong>I prossimi incontri<\/strong><\/p>\n<p><strong>Vallerotonda, Sala Polivalente &#8211; 29 Aprile ore 18,00<\/strong><\/p>\n<p><strong>Acquafondata, Sala Consiliare &#8211; 30 Aprile ore 17,00<\/strong><\/p>\n<p><strong>Terelle, Sala Consiliare &#8211; \u00a02 Maggio ore 17,00<\/strong><\/p>\n<p><strong>Belmonte Castello, Sala Consiliare &#8211; 3 Maggio ore 18,00<\/strong><\/p>\n<p>Ricordando che si tratta di incontri per la costruzione di progetti integrati, invitiamo gli amministratori e gli\u00a0operatori economici e culturali del territorio a partecipare al fine di condividere idee e progetti, che potranno trovare attuazione negli anni di programmazione Leader 2014-2020.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-280\" src=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna-206x300.jpg\" alt=\"la valorizzazione della montagna\" width=\"206\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna-206x300.jpg 206w, https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg 274w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><br \/>\nContact:<br \/>\nTel.:0039.0776.513015<br \/>\nFax.:0039.0776 513135<br \/>\nWeb_Site: <a href=\"http:\/\/www.galverla.eu\/\">www.galverla.eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo l&#8217;incontro tenutosi ieri a Picinisco, continuano i tavoli di lavoro per la costruzione del Piano di Sviluppo Locale del Gal Versante Laziale del PNA relativi a: &#8220;VALORIZZAZIONE DELLA MONTAGNA: [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TAVOLO DI LAVORO &quot;LA VALORIZZAZIONE DELLA MONTAGNA&quot; - GALVERLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TAVOLO DI LAVORO &quot;LA VALORIZZAZIONE DELLA MONTAGNA&quot; - GALVERLA\" \/>\n<meta property=\"og:description\" content=\"Dopo l&#8217;incontro tenutosi ieri a Picinisco, continuano i tavoli di lavoro per la costruzione del Piano di Sviluppo Locale del Gal Versante Laziale del PNA relativi a: &#8220;VALORIZZAZIONE DELLA MONTAGNA: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/\" \/>\n<meta property=\"og:site_name\" content=\"GALVERLA\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-28T15:01:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"274\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"galverla\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"galverla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/\"},\"author\":{\"name\":\"galverla\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/7d4e62a7171593b2b1dc6378fe56d612\"},\"headline\":\"TAVOLO DI LAVORO &#8220;LA VALORIZZAZIONE DELLA MONTAGNA&#8221;\",\"datePublished\":\"2016-04-28T15:01:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/\"},\"wordCount\":127,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/04\\\/la-valorizzazione-della-montagna.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/\",\"name\":\"TAVOLO DI LAVORO \\\"LA VALORIZZAZIONE DELLA MONTAGNA\\\" - GALVERLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/04\\\/la-valorizzazione-della-montagna.jpg\",\"datePublished\":\"2016-04-28T15:01:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/7d4e62a7171593b2b1dc6378fe56d612\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/04\\\/la-valorizzazione-della-montagna.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2016\\\/04\\\/la-valorizzazione-della-montagna.jpg\",\"width\":274,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2016\\\/04\\\/28\\\/tavolo-di-lavoro-la-valorizzazione-della-montagna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TAVOLO DI LAVORO &#8220;LA VALORIZZAZIONE DELLA MONTAGNA&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\",\"name\":\"GALVERLA\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/7d4e62a7171593b2b1dc6378fe56d612\",\"name\":\"galverla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g\",\"caption\":\"galverla\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/author\\\/galverla\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TAVOLO DI LAVORO \"LA VALORIZZAZIONE DELLA MONTAGNA\" - GALVERLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/","og_locale":"it_IT","og_type":"article","og_title":"TAVOLO DI LAVORO \"LA VALORIZZAZIONE DELLA MONTAGNA\" - GALVERLA","og_description":"Dopo l&#8217;incontro tenutosi ieri a Picinisco, continuano i tavoli di lavoro per la costruzione del Piano di Sviluppo Locale del Gal Versante Laziale del PNA relativi a: &#8220;VALORIZZAZIONE DELLA MONTAGNA: [&hellip;]","og_url":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/","og_site_name":"GALVERLA","article_published_time":"2016-04-28T15:01:35+00:00","og_image":[{"width":274,"height":400,"url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg","type":"image\/jpeg"}],"author":"galverla","twitter_misc":{"Scritto da":"galverla","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/"},"author":{"name":"galverla","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/7d4e62a7171593b2b1dc6378fe56d612"},"headline":"TAVOLO DI LAVORO &#8220;LA VALORIZZAZIONE DELLA MONTAGNA&#8221;","datePublished":"2016-04-28T15:01:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/"},"wordCount":127,"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/","url":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/","name":"TAVOLO DI LAVORO \"LA VALORIZZAZIONE DELLA MONTAGNA\" - GALVERLA","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg","datePublished":"2016-04-28T15:01:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/7d4e62a7171593b2b1dc6378fe56d612"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#primaryimage","url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg","contentUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2016\/04\/la-valorizzazione-della-montagna.jpg","width":274,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galverla\/2016\/04\/28\/tavolo-di-lavoro-la-valorizzazione-della-montagna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galverla\/"},{"@type":"ListItem","position":2,"name":"TAVOLO DI LAVORO &#8220;LA VALORIZZAZIONE DELLA MONTAGNA&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galverla\/#website","url":"https:\/\/comunicacity.net\/galverla\/","name":"GALVERLA","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galverla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/7d4e62a7171593b2b1dc6378fe56d612","name":"galverla","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b213e5e681c619cd602576319fb65294f6afbf4a8a0b8db3fd128d922f66f00c?s=96&d=mm&r=g","caption":"galverla"},"url":"https:\/\/comunicacity.net\/galverla\/author\/galverla\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/comments?post=279"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/279\/revisions"}],"predecessor-version":[{"id":281,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/279\/revisions\/281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media\/280"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/categories?post=279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/tags?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}