{"id":58,"date":"2015-08-31T10:45:26","date_gmt":"2015-08-31T08:45:26","guid":{"rendered":"https:\/\/comunicacity.net\/galverla\/?p=58"},"modified":"2015-08-31T10:45:26","modified_gmt":"2015-08-31T08:45:26","slug":"tutti-inviati-alla-vi-edizione-del-festival-delle-storie","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/","title":{"rendered":"Tutti inviati alla VI Edizione del Festival delle Storie."},"content":{"rendered":"<p style=\"text-align: justify;\">Gal Versante Laziale del PNA \u00e8 lieto di invitarvi alla VI Edizione del Festival delle Storie.Un ricco calendario di eventi, incontri e laboratori che animeranno la Valle di Comino dal 22 al 29 Agosto 2015.<\/p>\n<p style=\"text-align: justify;\"><em>Valle di Comino, 10 agosto 2015<\/em>. <strong>Dal 22 al 29 agosto torna il Festival delle Storie <\/strong>per far vivere la magia dei racconti di attori, scrittori, cantautori, filosofi, musicisti, giornalisti, scienziati, imprenditori, registi, sceneggiatori, artisti, intellettuali, italiani e stranieri, nel palcoscenico naturale della Valle di Comino, immersa nel Parco Nazionale d\u2019Abruzzo, Lazio e Molise.<\/p>\n<p style=\"text-align: justify;\">E\u2019 un festival itinerante che racconta una storia fatta di storie. Otto giorni di viaggio attraverso piazze medievali, vicoli, castelli, conventi, ville ottocentesche e roccaforti. Ogni giorno un paese diverso, ogni giorno una carta diversa detta il canovaccio del festival.<\/p>\n<p style=\"text-align: justify;\">La novit\u00e0 di quest\u2019anno \u00e8 che il ritmo e i contenuti ruotano intorno ai frutti della valle e non pi\u00f9, come negli anni passati, attorno ai tarocchi. Immaginate allora la Valle di Comino come un\u2019antica citt\u00e0, circondata da nemici invisibili che vogliono spegnerla, lasciarla al buio. Questa citt\u00e0 ha otto porte, ogni porta ha il nome di un frutto e ogni frutto \u00e8 il simbolo di un valore, che pu\u00f2 avere il volto e la personalit\u00e0 di un eroe antico.<\/p>\n<p style=\"text-align: justify;\">Ogni porta rappresenta quindi l\u2019antidoto al buio. Ecco i paesi che saranno lo scenario del romanzo di quest\u2019anno e le porte per accedervi e per accendere le luci sull\u2019antica citt\u00e0, la Valle di Comino, che ancora una volta prende vita e si illumina delle sue storie.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La <strong>sesta edizione<\/strong> del <strong>Festival delle Storie <\/strong>apre il <strong>22 agosto<\/strong> a <strong>Sora<\/strong> con la carta del <strong><em>Fico Fallacciano<\/em><\/strong>: \u00e8 l\u2019immortalit\u00e0, il superamento della paura della morte, la comunicazione tra i mondi, la voce che arriva ovunque, la metamorfosi. Il giorno successivo, <strong>23 agosto<\/strong>, si prosegue a <strong>San Donato Val di Comino<\/strong> con <strong><em>l\u2019Uva Maturano<\/em><\/strong>, che rappresenta chi sfida gli dei e va oltre i limiti dell\u2019uomo. E\u2019 l\u2019impossibile. E\u2019 il talento e la hybris.<\/p>\n<p style=\"text-align: justify;\">E\u2019 il dono e il costo da pagare. Il <strong>24 agosto<\/strong> le torce si accendono su <strong>Villa Latina<\/strong> con la <strong><em>Mela selvatica<\/em><\/strong>: \u00e8 il divergente, chi si ribella al potere e alle leggi della citt\u00e0. E\u2019 Antigone. E\u2019 la legge degli uomini che resiste alle follie del legislatore. Sono i cattivi, ma che poi cos\u00ec cattivi non sono mai. La <strong>Susina <\/strong>\u00e8 la carta di <strong>Casalvieri<\/strong> il <strong>25 agosto<\/strong>: \u00e8 il doppio, il sosia, \u00e8 uno, nessuno e centomila. E\u2019 la ricerca dell\u2019altro, come amore, passione, identit\u00e0.<\/p>\n<p style=\"text-align: justify;\">E\u2019 che non tutte le cose hanno un solo nome. E\u2019 la susina e la prugna. Il cammino continua il <strong>26 agosto<\/strong> a <strong>Fontechiari <\/strong>con il <strong><em>Melograno<\/em><\/strong>: \u00e8 ricchezza e abbondanza. E\u2019 il deragliamento dionisiaco dei sensi e chi lavora ogni giorno per la ricchezza. E\u2019 il mercato e la ricerca della felicit\u00e0. E\u2019 il frutto rosso della crescita. Il <strong>27 agosto<\/strong> si accendono le luci di <strong>Alvito<\/strong> con un frutto raro e proprio per questo delizioso, la <strong><em>Visciola<\/em><\/strong>, che rappresenta il rispetto dei patti, la fiducia.<\/p>\n<p style=\"text-align: justify;\">E\u2019 il maestro. E\u2019 la storia. E\u2019 quello su cui si fonda la memoria condivisa di una citt\u00e0.\u00a0 Il nostro tempo e le sue contraddizioni. Il <strong><em>Gelso<\/em><\/strong> fa da protagonista il <strong>28 agosto<\/strong> nella giornata di <strong>Atina<\/strong>: \u00e8 la strada che non conosci. E\u2019 l\u2019altrove. E\u2019 andare lontano e superare i confini. E\u2019 navigare e salire. E\u2019 Ulisse e Marco Polo. E\u2019 una corda lanciata nella roccia. Chiude il festival il <strong>29 agosto<\/strong> a <strong>Picinisco <\/strong>la carta del<strong> <em>Sambuco nero<\/em><\/strong>: \u00e8 l\u2019indovino.<\/p>\n<p style=\"text-align: justify;\">E\u2019 Tiresia. E\u2019 la sfida dell\u2019uomo all\u2019architettura di Dio. E\u2019 riconoscere chi siamo, i nostri miti ed eroi, le nostre leggende. E\u2019 la scienza e la fantascienza.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Gli ospiti Festival delle Storie 2015 in ordine di apparizione:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>22 agosto, Sora, Carta del Fico Fallacciano:<\/strong><\/p>\n<p style=\"text-align: justify;\">Carla Rea, Giorgia Zirizotti, Francesco Polidori, Edoardo Inglese, Alessandra Pelagalli, Giacomo Sartori, Lorenzo Marone, Edoardo Boncinelli, Massimo Arcangeli, Chiara Colizzi, Ezio Luzzi, Enrico Menduni, Massimo Veronese, Davide Rondoni, Diego Bianchi, Maurizio Turriziani, Loreto Gismondi, Giacomo Cellucci.<\/p>\n<p style=\"text-align: justify;\"><strong>23 agosto, San Donato, Carta dell\u2019Uva Maturano:<\/strong><\/p>\n<p style=\"text-align: justify;\">Nora Moll, Davide Toffoli, Giuseppe Cossuto, Roberto Perrone, Marcello Paolillo, Ivan Paduano, Giorgio Nisini, Marco Cubeddu, Paolo Di Stefano, Giuseppe Peveri in arte Dente, Alexandro Ladaga, Silvia Manteiga, Team di Uland Communication, Vinicio Capossela, Alessandro &#8220;Asso&#8221; Stefana, Taketo Gohara, Alessandro Gnocchi, Antonio Costa, Giuseppe Marino, Antonio Catania.<\/p>\n<p style=\"text-align: justify;\"><strong>24 agosto, Villa Latina, Carta della Mela selvatica:<\/strong><\/p>\n<p style=\"text-align: justify;\">Ivan Nossa, Marco Orlandi, Andrea Meccia, Antonio Pellegrini, Tiziana Luciani, Sonya Orfalian, Francesco Magris, Sergio Claudio Perroni, Gian Luca Favetto, Loreto Gismondi, Maurizio Torchio, Vanni Santoni, Zvonimir Boban, Sanda Pandza, Mario Luzzatto Fegiz, Nicola Manuppelli.<\/p>\n<p style=\"text-align: justify;\"><strong>25 agosto, Casalvieri, Carta della Susina:<\/strong><\/p>\n<p style=\"text-align: justify;\">Gioachino Lanotte, Marino Magliani, Sandro Sangiorgi, Alessio Romano, Giulio Perrone, Silvia Truzzi, Giuseppe De Filippi, Massimo Roscia, Mogol, Angelo Carotenuto, Enrico Macioci, Edoardo Inglese, Amleto De Silva.<\/p>\n<p style=\"text-align: justify;\"><strong>26 agosto, Fontechiari, Carta del Melograno:<\/strong><\/p>\n<p style=\"text-align: justify;\">Sergio Andreatta, Gaetano Vincenzo Pelagalli, Cinzia Dal Brolo, Catia Pellegrino, Chiara Montanari, Mario Tozzi, Luca Bianchini, Romolo Bugaro, Marco Carta, Fabio Genovesi, Geppi Cucciari, Giorgio Lauro.<\/p>\n<p style=\"text-align: justify;\"><strong>27 agosto, Alvito, Carta della Visciola:<\/strong><\/p>\n<p style=\"text-align: justify;\">Carla Frank, Fulvia Ceccarelli, Dario Giuliano, Katherine Esposito, Aldo Mattia, Giampiero Aquila, Paolo Fiorelli, Alfonso Celotto, Giovanni Fasanella, Edoardo Camurri, Daniela Ranieri, Luciano De Crescenzo, Paolo Del Debbio, Francesco Bianconi, Ettore Bianconi, Sebastiano De Gennaro.<\/p>\n<p style=\"text-align: justify;\"><strong>28 agosto, Atina, Carta del Gelso:<\/strong><\/p>\n<p style=\"text-align: justify;\">Divier Nelli, Alessandro Robecchi, Gloria Sapio, Maurizio Repetto, Andrea Cauduro, Pietro Grossi,<\/p>\n<p style=\"text-align: justify;\">Elena Mearini, Massimo Onofri, Enrico Ianniello, Marco Olmo, Patrizio Oliva, Fabio Rocco Oliva, Marco Travaglio.<\/p>\n<p style=\"text-align: justify;\"><strong>29 agosto, Picinisco, Carta del Sambuco nero:<\/strong><\/p>\n<p style=\"text-align: justify;\">Armando Corridore, Andrea Mancia, Rodolfo Coccioni, Olivia Nesci, Rosetta Borchia, Stefano Amoroso, Andrea Iacomini, Simona Marchini, Marino Bartoletti, Franco Cardini, Emma Pomilio, Roberto Cingolani, Alessandro Cecchi Paone, Umberto Guidoni, Mario Lavezzi.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Il <strong>Festival delle Storie, <\/strong>nasce nel 2010 da un\u2019idea di Vittorio Macioce e Rachele Brancatisano. E\u2019 l\u2019idea di portare la cultura nelle piazze, nelle strade, in spazi storici da recuperare per offrire cultura a tutti.<\/p>\n<p style=\"text-align: justify;\">Il programma completo e tutte le attivit\u00e0 dell\u2019edizione 2015 del <strong>Festival delle Storie <\/strong>\u00e8 disponibile sul sito <a href=\"http:\/\/www.festivaldellestorie.org\/\"><strong>www.festivaldellestorie.org<\/strong><\/a>e sfogliabile a questo link <a href=\"http:\/\/www.sfogliami.it\/flip.asp?sc=lyluz2nrffly4u6y1mgifdqgiq1jeoly&amp;ID=121399\" target=\"_blank\">Programma Festival delle Storie 2015<\/a> .<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em>Si ringraziano i Sindaci di tutti i paesi della Valle di Comino, i\u00a0 partner tecnici e tutti gli sponsor (sul sito l\u2019elenco completo) che con il loro impegno rendono ogni anno possibile la realizzazione del Festival delle Storie.<\/em><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Gal Versante Laziale del PNA \u00e8 lieto di invitarvi alla VI Edizione del Festival delle Storie.Un ricco calendario di eventi, incontri e laboratori che animeranno la Valle di Comino dal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-58","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tutti inviati alla VI Edizione del Festival delle Storie. - GALVERLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tutti inviati alla VI Edizione del Festival delle Storie. - GALVERLA\" \/>\n<meta property=\"og:description\" content=\"Gal Versante Laziale del PNA \u00e8 lieto di invitarvi alla VI Edizione del Festival delle Storie.Un ricco calendario di eventi, incontri e laboratori che animeranno la Valle di Comino dal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/\" \/>\n<meta property=\"og:site_name\" content=\"GALVERLA\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-31T08:45:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/fds-2015-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"358\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Tutti inviati alla VI Edizione del Festival delle Storie.\",\"datePublished\":\"2015-08-31T08:45:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/\"},\"wordCount\":1034,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/fds-2015-web.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/\",\"name\":\"Tutti inviati alla VI Edizione del Festival delle Storie. - GALVERLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/fds-2015-web.jpg\",\"datePublished\":\"2015-08-31T08:45:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/fds-2015-web.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/fds-2015-web.jpg\",\"width\":358,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutti inviati alla VI Edizione del Festival delle Storie.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\",\"name\":\"GALVERLA\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tutti inviati alla VI Edizione del Festival delle Storie. - GALVERLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/","og_locale":"it_IT","og_type":"article","og_title":"Tutti inviati alla VI Edizione del Festival delle Storie. - GALVERLA","og_description":"Gal Versante Laziale del PNA \u00e8 lieto di invitarvi alla VI Edizione del Festival delle Storie.Un ricco calendario di eventi, incontri e laboratori che animeranno la Valle di Comino dal [&hellip;]","og_url":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/","og_site_name":"GALVERLA","article_published_time":"2015-08-31T08:45:26+00:00","og_image":[{"width":358,"height":400,"url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/fds-2015-web.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Tutti inviati alla VI Edizione del Festival delle Storie.","datePublished":"2015-08-31T08:45:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/"},"wordCount":1034,"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/fds-2015-web.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/","url":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/","name":"Tutti inviati alla VI Edizione del Festival delle Storie. - GALVERLA","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/fds-2015-web.jpg","datePublished":"2015-08-31T08:45:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#primaryimage","url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/fds-2015-web.jpg","contentUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/fds-2015-web.jpg","width":358,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/tutti-inviati-alla-vi-edizione-del-festival-delle-storie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galverla\/"},{"@type":"ListItem","position":2,"name":"Tutti inviati alla VI Edizione del Festival delle Storie."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galverla\/#website","url":"https:\/\/comunicacity.net\/galverla\/","name":"GALVERLA","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galverla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/galverla\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/58\/revisions"}],"predecessor-version":[{"id":60,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/58\/revisions\/60"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media\/59"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media?parent=58"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/categories?post=58"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/tags?post=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}