{"id":663,"date":"2022-10-07T13:16:26","date_gmt":"2022-10-07T11:16:26","guid":{"rendered":"https:\/\/comunicacity.net\/galverla\/?p=663"},"modified":"2022-10-07T13:16:26","modified_gmt":"2022-10-07T11:16:26","slug":"finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/","title":{"rendered":"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-364\" src=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg\" alt=\"\" width=\"742\" height=\"382\" srcset=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg 742w, https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio-300x154.jpg 300w, https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio-680x350.jpg 680w, https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio-600x309.jpg 600w\" sizes=\"auto, (max-width: 742px) 100vw, 742px\" \/><\/p>\n<p>Fondi del Piano Nazionale di Ripresa e Resilienza \u2013 NextGenerationEU al Patto dei Sindaci\u00a0\u201cTerre di Comino Smart Land\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d REDATTO DAL GAL VERLA PER UN IMPORTO TOTALE DI\u00a0 4,3 MILIONI DI EURO, UNO DEI 30 PROGETTI FINANZIATI IN ITALIA. SARA\u2019 UNA GRANDE OPPORTUNIT\u00c0 PER RIGENERARE IL TERRITORIO NON SOLO DA UN PUNTO DI VISTA AMBIENTALE MA ANCHE SOCIALE ED ECONOMICO, PER COSTRUIRE UN PERCORSO DI \u201cCOMUNITA\u2019 VIVE\u201d, DOVE SI CAMMINA INSIEME PER VINCERE LA SFIDA DEL FUTURO E DELLA TRANSIZIONE ECOLOGICA.<\/p>\n<p>&nbsp;<\/p>\n<p>Nei giorni della pi\u00f9 grave crisi energetica europea dal dopoguerra, la Presidenza Del Consiglio Dei Ministri ha finanziato il progetto Green Community presentato dal GAL Versante Laziale del PNA, per il Patto Dei Sindaci \u201cTerre di Comino Smart Land\u201d, nell\u2019ambito del Bando \u201cGreen Communities\u201d del PNRR.<\/p>\n<p>Il progetto interessa 11 comuni contigui dei 32 aderenti al Patto (Aquino, Castrocielo, Cervaro, Colle San Magno, Piedimonte San Germano, Pontecorvo, Roccasecca, San Vittore del Lazio, Sant\u2019Elia Fiumerapido, Terelle, Villa Santa Lucia).<\/p>\n<p><strong>Una sfida verso il futuro nell\u2019ecologia integrata.<\/strong><\/p>\n<p>In un momento cos\u00ec difficile della storia repubblicana, dopo 2 anni di grave crisi pandemica, nel pieno di una guerra mai cos\u00ec vicina, la green community non \u00e8 solo l\u2019opportunit\u00e0 di realizzare progetti di transizione ecologica ma un impegno degli Enti territoriali, non solo dei Comuni, di lavorare insieme superando l\u2019idea che ciascuno pu\u00f2 bastare a s\u00e9 stesso. Solo nella cooperazione, nel dialogo e nello scambio si pu\u00f2 lavorare insieme per una Strategia duratura. Unendo i tasselli dello sviluppo, di investimenti fatti e previsti, di operazioni di crescita inclusiva. Solo insieme si vince.<\/p>\n<p>Il Progetto Green Community Terre di Comino Smart Land tenta in piccolo di attivare concretamente ci\u00f2 che\u00a0 Papa Francesco ha descritto nell\u2019Enciclica Laudato Si\u2019: senza\u00a0 giustizia sociale non vi \u00e8 futuro, e\u00a0 la \u201ccura della Casa comune\u201d passa da un netto cambio di paradigma anche tra le sindache e i sindaci, tra amministrazioni e\u00a0 comunit\u00e0 locale.<\/p>\n<p>Il progetto, che deve essere concluso entro marzo 2026, prevede la certificazione del patrimonio agroforestale e di catena di custodia per le aziende, studi sulle risorse idriche e il loro uso sostenibile, installazione di case dell&#8217;acqua del Sindaco\/a per sensibilizzare i cittadini alla riduzione del consumo di acque minerali e della plastica, efficientamento energetico e miglioramento tecnologico di edifici\u00a0 pubblici per attivare\u00a0 i Poli della Green Community e impianti fotovoltaici per la produzione di energia rinnovabile.<\/p>\n<p>Per la mobilit\u00e0 dei cittadini, in collaborazione con il partner tecnico ON CHARGE, sar\u00e0 realizzata una &#8220;nuvola&#8221; di colonnine di ricarica elettriche (sia negli 11 comuni del progetto sia negli altri del Patto) unitamente alla realizzazione di 18 ciclostazioni e-bike (200 stalli) con una flotta di 100 mountain bike elettriche collegate ad un applicativo turistico e al sistema di monitoraggio ambientale; le ciclostazioni saranno alimentate da un pannello fotovoltaico, collegato ad una batteria di accumulo. \u00a0Il funzionamento del servizio avviene attraverso l\u2019utilizzo di un App custom dedicata (SMART LAND E-MOBILITY). Il progetto prevede anche l\u2019attivazione di una rete di monitoraggio ambientale con raccolta dati utili alle valutazioni ambientali e strategiche.\u00a0 Si lavorer\u00e0 inoltre alla diffusione del Marchio di Qualit\u00e0 delle 4E, marchio volontario ispirato ad Ecolabel (ecocompatibilit\u00e0, eticit\u00e0, efficacia ed efficienza) per creare reti i e migliorare la gestione delle strutture turistiche,\u00a0 tutto questo con il supporto dello Sportello della \u201cGreen Community Terre di Comino Smart Land\u201d che monitorer\u00e0 l\u2019avanzamento delle attivit\u00e0 e promuover\u00e0 azioni di sensibilizzazione per cittadini, imprese e amministratori sulla transizione ecologica, per \u201cseminare la partecipazione\u201d con attivit\u00e0 di sensibilizzazione all\u2019adozione di pratiche partecipative (forum di ascolto, focus group per l\u2019analisi delle soluzioni ai problemi e delle priorit\u00e0 da mettere in campo nell\u2019organizzazione degli strumenti formativi, degli spazi, dei tempi, delle politiche di genere, degli incentivi per i giovani ecc.).<\/p>\n<p>Il sindaco di Ripi Sementilli (Comune capofila del Patto) ha dichiarato: \u00e8 stata la coerenza del Piano di Azione per l\u2019Energia sostenibile e il Clima PAESC \u201cTerre di Comino Smart Land\u201d con il Piano Nazionale di Ripresa e Resilienza \u201cNext generation Italia\u201d che ha costituito il presupposto per l\u2019accesso privilegiato ai benefici offerti dal Bando Green Communities, coerenza sia nei metodi sia nei contenuti sia negli obbiettivi.<\/p>\n<p>Il Presidente del Gal l\u2019arch. Loreto Policella, struttura di supporto tecnico al PAESC, ha affermato: desidero portare all\u2019attenzione dei cittadini del nostro territorio l\u2019originale esperienza svolta nella Provincia di Frosinone dal Gal Verla nella costruzione del \u201cPatto dei Sindaci\u201d e nella redazione del PAESC (Piano di\u00a0 Azione Energia Sostenibile e Clima) nella convinzione che possa costituire un esempio\u00a0 concreto cui riferirsi, \u00a0in Italia e in particolare nelle aree interne, di programmazione economica dell\u2019economia circolare e di riduzione programmata delle emissioni di CO2. Come pi\u00f9 volte affermato la costituzione del \u201cPatto dei Sindaci\u201d, l\u2019elaborazione del PAESC e la sua approvazione da parte della UE \u00e8 risultato decisivo per l\u2019ottenimento dell\u2019ingente finanziamento del progetto Green Communities ottenuto con i fondi europei del PNRR\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Sindaco del Comune di Ripi<\/p>\n<p>Capofila del progetto e del Patto dei Sindaci \u00a0\u201cTerre di Comino Smart Land\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Il Presidente del Gal Versante Laziale del Parco Nazionale d\u2019Abruzzo<\/p>\n<p>Struttura di supporto tecnico al Patto dei Sindaci<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_664\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2022\/10\/LogoGal.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2022\/10\/LogoGal.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>LogoGal<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fondi del Piano Nazionale di Ripresa e Resilienza \u2013 NextGenerationEU al Patto dei Sindaci\u00a0\u201cTerre di Comino Smart Land\u201d &nbsp; FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":364,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d - GALVERLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d - GALVERLA\" \/>\n<meta property=\"og:description\" content=\"Fondi del Piano Nazionale di Ripresa e Resilienza \u2013 NextGenerationEU al Patto dei Sindaci\u00a0\u201cTerre di Comino Smart Land\u201d &nbsp; FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/\" \/>\n<meta property=\"og:site_name\" content=\"GALVERLA\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T11:16:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"742\" \/>\n\t<meta property=\"og:image:height\" content=\"382\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elide Di Duca\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elide Di Duca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/\"},\"author\":{\"name\":\"Elide Di Duca\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/0217c8c19958688fd1efc5871901ca08\"},\"headline\":\"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d\",\"datePublished\":\"2022-10-07T11:16:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/\"},\"wordCount\":879,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2017\\\/05\\\/invito-patto-dei-sindaci-ok-ritaglio.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/\",\"name\":\"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d - GALVERLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2017\\\/05\\\/invito-patto-dei-sindaci-ok-ritaglio.jpg\",\"datePublished\":\"2022-10-07T11:16:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/0217c8c19958688fd1efc5871901ca08\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2017\\\/05\\\/invito-patto-dei-sindaci-ok-ritaglio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2017\\\/05\\\/invito-patto-dei-sindaci-ok-ritaglio.jpg\",\"width\":742,\"height\":382},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2022\\\/10\\\/07\\\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\",\"name\":\"GALVERLA\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/0217c8c19958688fd1efc5871901ca08\",\"name\":\"Elide Di Duca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c21f79403c56db10f6b609c60f58b7e6aa161bef4a2077f8541f6f1072f76bf4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c21f79403c56db10f6b609c60f58b7e6aa161bef4a2077f8541f6f1072f76bf4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c21f79403c56db10f6b609c60f58b7e6aa161bef4a2077f8541f6f1072f76bf4?s=96&d=mm&r=g\",\"caption\":\"Elide Di Duca\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/author\\\/elidediduca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d - GALVERLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/","og_locale":"it_IT","og_type":"article","og_title":"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d - GALVERLA","og_description":"Fondi del Piano Nazionale di Ripresa e Resilienza \u2013 NextGenerationEU al Patto dei Sindaci\u00a0\u201cTerre di Comino Smart Land\u201d &nbsp; FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI [&hellip;]","og_url":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/","og_site_name":"GALVERLA","article_published_time":"2022-10-07T11:16:26+00:00","og_image":[{"width":742,"height":382,"url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg","type":"image\/jpeg"}],"author":"Elide Di Duca","twitter_misc":{"Scritto da":"Elide Di Duca","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/"},"author":{"name":"Elide Di Duca","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/0217c8c19958688fd1efc5871901ca08"},"headline":"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d","datePublished":"2022-10-07T11:16:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/"},"wordCount":879,"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/","url":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/","name":"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d - GALVERLA","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg","datePublished":"2022-10-07T11:16:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/0217c8c19958688fd1efc5871901ca08"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#primaryimage","url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg","contentUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2017\/05\/invito-patto-dei-sindaci-ok-ritaglio.jpg","width":742,"height":382},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galverla\/2022\/10\/07\/finanziato-il-progetto-green-community-del-patto-dei-sindaci-terre-di-comino-smart-land\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galverla\/"},{"@type":"ListItem","position":2,"name":"FINANZIATO IL PROGETTO GREEN COMMUNITY DEL \u201cPATTO DEI SINDACI TERRE DI COMINO SMART LAND\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galverla\/#website","url":"https:\/\/comunicacity.net\/galverla\/","name":"GALVERLA","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galverla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/0217c8c19958688fd1efc5871901ca08","name":"Elide Di Duca","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c21f79403c56db10f6b609c60f58b7e6aa161bef4a2077f8541f6f1072f76bf4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c21f79403c56db10f6b609c60f58b7e6aa161bef4a2077f8541f6f1072f76bf4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c21f79403c56db10f6b609c60f58b7e6aa161bef4a2077f8541f6f1072f76bf4?s=96&d=mm&r=g","caption":"Elide Di Duca"},"url":"https:\/\/comunicacity.net\/galverla\/author\/elidediduca\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/comments?post=663"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/663\/revisions"}],"predecessor-version":[{"id":665,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/663\/revisions\/665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media\/364"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media?parent=663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/categories?post=663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/tags?post=663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}