{"id":80,"date":"2015-08-31T15:09:29","date_gmt":"2015-08-31T13:09:29","guid":{"rendered":"https:\/\/comunicacity.net\/galverla\/?p=80"},"modified":"2015-08-31T15:09:29","modified_gmt":"2015-08-31T13:09:29","slug":"la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/","title":{"rendered":"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura"},"content":{"rendered":"<h4 style=\"text-align: justify;\">\u201cVivere nei cuori che lasciamo dietro di noi non \u00e8 morire\u201d T. Campbell.<\/h4>\n<p style=\"text-align: justify;\">Prendendo spun\u00adto dalla frase del noto poeta scoz\u00adzese Campbell, abbiamo voluto creare un\u2019associa\u00adzione culturale dedicata ad un nostro amico pre\u00admaturamente scomparso: amante della fotografia, dei libri, delle arti e della musica. Il modo miglio\u00adre per ricordare Danilo \u00e8 stato, per noi, promuove\u00adre la cultura e l\u2019associa\u00adzionismo nel nostro ter\u00adritorio.<\/p>\n<p style=\"text-align: justify;\">La nostra lettera di presentazione inizia\u00adva con: \u201cNon occorre es\u00adsere in tanti per realizza\u00adre un grande progetto, ma \u00e8 necessaria la con\u00addivisione di una volont\u00e0 e di un percorso comu\u00adne\u2026\u201d Ebbene, il risultato \u00e8 stato per noi sbalordi\u00adtivo: l\u2019associazione con\u00adta pi\u00f9 di duecento soci, pi\u00f9 una miriade di soste\u00adnitori e di idee da realiz\u00adzare.<\/p>\n<p style=\"text-align: justify;\">Le svariate attivit\u00e0 dell\u2019associazione si con\u00adcentrano principalmente sugli interessi e le passio\u00adni di Danilo, tra esse pri\u00adma fra tutte la fotografia. Poich\u00e9 uno dei suoi so\u00adgni era quello di allesti\u00adre una mostra fotografica, abbiamo voluto realizza\u00adre un\u2019esposizione di scatti dal titolo \u201cTracce\u201d, divisa in \u201cTracce di vita\u201d (raffi\u00adguranti momenti di vi\u00adta vissuta e di reportage), \u201cTracce di noi\u201d (dedicate ai ritratti) e infine \u201cTracce di me\u201d (interamente dedi\u00adcata a Danilo).<\/p>\n<p style=\"text-align: justify;\">Successi\u00advamente abbiamo deciso di istituire un importan\u00adte concorso nazionale di fotografia dal nome \u201cTro\u00adfeo Griecone\u201d.<\/p>\n<p style=\"text-align: justify;\">Uno dei progetti pi\u00f9 importanti realizzati dall\u2019ADF \u00e8 sta\u00adto inoltre l\u2019allestimento della Biblioteca comuna\u00adle di Posta Fibreno, at\u00adtraverso la donazione di pi\u00f9 di mille libri e di PC necessari per il collega\u00admento interbibliote cario. \u201cVicoli in Festa\u201d \u00e8 il no\u00adme dell\u2019altro importante evento creato dall\u2019Asso\u00adciazione Danilo Fiorini.<\/p>\n<p style=\"text-align: justify;\">La manifestazione, che si svolge durante il periodo natalizio per i vicoli del centro storico del nostro Comune, prevedendo l\u2019e\u00adsibizione di cori polifo\u00adnici, l\u2019apertura della Ca\u00adsa di Babbo Natale a tutti i bambini, serate culina\u00adrie dedicate alle tradizio\u00adni locali e, soprattutto, il concorso di Arte Prese\u00adpiale che spinge i nume\u00adrosi partecipanti ad al\u00adlestire bellissimi presepi artigianali nelle storiche abitazioni.<\/p>\n<p style=\"text-align: justify;\">Tutti insieme, unendo le nostre passioni ed il no\u00adstro impegno, faccia\u00admo in modo che il nome dell\u2019Associazione Danilo Fiorini sia il vero motore di tutto questo.<\/p>\n<p style=\"text-align: justify;\">[di Franco Angelo Lecce]<\/p>\n<hr \/>\n<h4 style=\"text-align: justify;\">La Storia<\/h4>\n<p style=\"text-align: justify;\">L\u2019Associazione Danilo Fiorini nasce cos\u00ec il 2 aprile 2007 a Posta Fibreno, un piccolo comune in provincia di Frosinone, conosciuto da tutti per la presenza di un meraviglioso lago, Riserva naturale regionale.<\/p>\n<p style=\"text-align: justify;\">Le sue attivit\u00e0 principali si svolgono all\u2019insegna della promozione artistica e della convivialit\u00e0, mettendo in campo le conoscenze degli associati per l\u2019organizzazione di corsi di fotografia e corsi di cucina di vario livello.<\/p>\n<p style=\"text-align: justify;\">Questo piccolo sogno pian piano sta diventando un modello di sviluppo culturale di riferimento per tutta la zona, con partecipazioni di pubblico numerose e con attestati di stima che fanno capire che la strada intrapresa dall\u2019associazione \u00e8 quella giusta.<\/p>\n<p style=\"text-align: justify;\">Info: C. da Tagliata 14, Posta Fibreno \u00b7 Frosinone \u00b7 03030 Italia<br \/>\n0776887451 \u00b7 3477573633 \u00b7 <a title=\"weblink\" href=\"http:\/\/www.associazionedanilofiorini.it\/\" target=\"_blank\">www.associazionedanilofiorini.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cVivere nei cuori che lasciamo dietro di noi non \u00e8 morire\u201d T. Campbell. Prendendo spun\u00adto dalla frase del noto poeta scoz\u00adzese Campbell, abbiamo voluto creare un\u2019associa\u00adzione culturale dedicata ad un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-80","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura - GALVERLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura - GALVERLA\" \/>\n<meta property=\"og:description\" content=\"\u201cVivere nei cuori che lasciamo dietro di noi non \u00e8 morire\u201d T. Campbell. Prendendo spun\u00adto dalla frase del noto poeta scoz\u00adzese Campbell, abbiamo voluto creare un\u2019associa\u00adzione culturale dedicata ad un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/\" \/>\n<meta property=\"og:site_name\" content=\"GALVERLA\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-31T13:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/26872_111437408886332_8077696_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"357\" \/>\n\t<meta property=\"og:image:height\" content=\"309\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura\",\"datePublished\":\"2015-08-31T13:09:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/\"},\"wordCount\":517,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/26872_111437408886332_8077696_n.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/\",\"name\":\"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura - GALVERLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/26872_111437408886332_8077696_n.jpg\",\"datePublished\":\"2015-08-31T13:09:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/26872_111437408886332_8077696_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2015\\\/08\\\/26872_111437408886332_8077696_n.jpg\",\"width\":357,\"height\":309},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/2015\\\/08\\\/31\\\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/\",\"name\":\"GALVERLA\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/galverla\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura - GALVERLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/","og_locale":"it_IT","og_type":"article","og_title":"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura - GALVERLA","og_description":"\u201cVivere nei cuori che lasciamo dietro di noi non \u00e8 morire\u201d T. Campbell. Prendendo spun\u00adto dalla frase del noto poeta scoz\u00adzese Campbell, abbiamo voluto creare un\u2019associa\u00adzione culturale dedicata ad un [&hellip;]","og_url":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/","og_site_name":"GALVERLA","article_published_time":"2015-08-31T13:09:29+00:00","og_image":[{"width":357,"height":309,"url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/26872_111437408886332_8077696_n.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura","datePublished":"2015-08-31T13:09:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/"},"wordCount":517,"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/26872_111437408886332_8077696_n.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/","url":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/","name":"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura - GALVERLA","isPartOf":{"@id":"https:\/\/comunicacity.net\/galverla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/26872_111437408886332_8077696_n.jpg","datePublished":"2015-08-31T13:09:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#primaryimage","url":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/26872_111437408886332_8077696_n.jpg","contentUrl":"https:\/\/comunicacity.net\/galverla\/wp-content\/uploads\/sites\/19\/2015\/08\/26872_111437408886332_8077696_n.jpg","width":357,"height":309},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/galverla\/2015\/08\/31\/la-voce-delle-associazioni-associazione-fiorini-quando-la-memoria-diventa-cultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/galverla\/"},{"@type":"ListItem","position":2,"name":"La voce delle Associazioni: Associazione Fiorini, quando la memoria diventa cultura"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/galverla\/#website","url":"https:\/\/comunicacity.net\/galverla\/","name":"GALVERLA","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/galverla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/galverla\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/galverla\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/80\/revisions"}],"predecessor-version":[{"id":82,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/posts\/80\/revisions\/82"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media\/81"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/media?parent=80"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/categories?post=80"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/galverla\/wp-json\/wp\/v2\/tags?post=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}