{"id":470,"date":"2025-08-13T11:31:21","date_gmt":"2025-08-13T09:31:21","guid":{"rendered":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/"},"modified":"2025-08-13T11:31:59","modified_gmt":"2025-08-13T09:31:59","slug":"raccolta-differenziata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/","title":{"rendered":"Raccolta differenziata"},"content":{"rendered":"<p><em>Calendario della Raccolta differenziata<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Per chi ne fosse sprovvisto qui in allegato pu\u00f2 trovare il calendario, sia in formato immagine che in PDF, della raccolta differenziata, sia per il centro urbano che per le campagne.&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.giulianodiroma.fr.it\/wp-content\/uploads\/2025\/08\/image130825111442-000.jpg' alt='image'><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_475\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/image-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/image-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>image<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Calendario della Raccolta differenziata&nbsp; Descrizione&nbsp; Per chi ne fosse sprovvisto qui in allegato pu\u00f2 trovare il calendario, sia in formato immagine che in PDF, della raccolta differenziata, sia per il [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raccolta differenziata - Giuliano di Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raccolta differenziata - Giuliano di Roma\" \/>\n<meta property=\"og:description\" content=\"Calendario della Raccolta differenziata&nbsp; Descrizione&nbsp; Per chi ne fosse sprovvisto qui in allegato pu\u00f2 trovare il calendario, sia in formato immagine che in PDF, della raccolta differenziata, sia per il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/\" \/>\n<meta property=\"og:site_name\" content=\"Giuliano di Roma\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-13T09:31:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T09:31:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/raccolta-differenziata-scaled-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Raccolta differenziata\",\"datePublished\":\"2025-08-13T09:31:21+00:00\",\"dateModified\":\"2025-08-13T09:31:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/\"},\"wordCount\":45,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/wp-content\\\/uploads\\\/sites\\\/230\\\/2025\\\/08\\\/raccolta-differenziata-scaled-2.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/\",\"name\":\"Raccolta differenziata - Giuliano di Roma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/wp-content\\\/uploads\\\/sites\\\/230\\\/2025\\\/08\\\/raccolta-differenziata-scaled-2.jpg\",\"datePublished\":\"2025-08-13T09:31:21+00:00\",\"dateModified\":\"2025-08-13T09:31:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/wp-content\\\/uploads\\\/sites\\\/230\\\/2025\\\/08\\\/raccolta-differenziata-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/wp-content\\\/uploads\\\/sites\\\/230\\\/2025\\\/08\\\/raccolta-differenziata-scaled-2.jpg\",\"width\":2560,\"height\":1337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/2025\\\/08\\\/13\\\/raccolta-differenziata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raccolta differenziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/giulianodiroma\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raccolta differenziata - Giuliano di Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/","og_locale":"it_IT","og_type":"article","og_title":"Raccolta differenziata - Giuliano di Roma","og_description":"Calendario della Raccolta differenziata&nbsp; Descrizione&nbsp; Per chi ne fosse sprovvisto qui in allegato pu\u00f2 trovare il calendario, sia in formato immagine che in PDF, della raccolta differenziata, sia per il [&hellip;]","og_url":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/","og_site_name":"Giuliano di Roma","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-08-13T09:31:21+00:00","article_modified_time":"2025-08-13T09:31:59+00:00","og_image":[{"width":2560,"height":1337,"url":"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/raccolta-differenziata-scaled-2.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/giulianodiroma\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Raccolta differenziata","datePublished":"2025-08-13T09:31:21+00:00","dateModified":"2025-08-13T09:31:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/"},"wordCount":45,"publisher":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/raccolta-differenziata-scaled-2.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/","url":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/","name":"Raccolta differenziata - Giuliano di Roma","isPartOf":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/raccolta-differenziata-scaled-2.jpg","datePublished":"2025-08-13T09:31:21+00:00","dateModified":"2025-08-13T09:31:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#primaryimage","url":"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/raccolta-differenziata-scaled-2.jpg","contentUrl":"https:\/\/comunicacity.net\/giulianodiroma\/wp-content\/uploads\/sites\/230\/2025\/08\/raccolta-differenziata-scaled-2.jpg","width":2560,"height":1337},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/giulianodiroma\/2025\/08\/13\/raccolta-differenziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/giulianodiroma\/"},{"@type":"ListItem","position":2,"name":"Raccolta differenziata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/giulianodiroma\/#website","url":"https:\/\/comunicacity.net\/giulianodiroma\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/giulianodiroma\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/giulianodiroma\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/giulianodiroma\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/giulianodiroma\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/giulianodiroma\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/giulianodiroma\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001603"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"predecessor-version":[{"id":473,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/posts\/470\/revisions\/473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/media\/474"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/giulianodiroma\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}