{"id":1033,"date":"2026-01-20T17:01:32","date_gmt":"2026-01-20T16:01:32","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/"},"modified":"2026-01-20T17:02:50","modified_gmt":"2026-01-20T16:02:50","slug":"consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/","title":{"rendered":"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero"},"content":{"rendered":"<p><em>Scadenza presentazione domande 24 gennaio 2026<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Per il referendum del 22 e 23 marzo 2026, gli elettori italiani residenti all\u2019estero, ai sensi della legge 27 dicembre 2001, n. 459 e del relativo regolamento di attuazione approvato con D.P.R. 2 aprile 2003, n. 104, votano per corrispondenza. La predetta normativa, nel prevedere la modalit\u00e0 di voto per corrispondenza da parte di tali elettori, i cui nominativi vengono inseriti d\u2019ufficio nell\u2019elenco degli elettori residenti all\u2019estero, fa comunque salva<strong> la possibilit\u00e0 di votare in Italia<\/strong>, previa apposita e tempestiva opzione, da esercitare in occasione di ogni consultazione popolare e valida limitatamente a essa.<\/p>\n<p>In particolare, nel caso di specie, il diritto di optare per il voto in Italia, ai sensi degli artt. 1, comma 3, e 4 della legge n. 459\/2001 nonch\u00e9 dell\u2019art. 4 del D.P.R. n. 104\/2003, deve essere esercitato entro il decimo giorno successivo all\u2019indizione del referendum (intendendo riferito tale termine alla data di pubblicazione nella Gazzetta Ufficiale del decreto di indizione) e cio\u00e8 <strong>entro il prossimo 24 gennaio 2026<\/strong>, preferibilmente utilizzando il modello allegato al presente avviso.<\/p>\n<p>L\u2019opzione dovr\u00e0 pervenire entro il termine sopraindicato all\u2019Ufficio consolare operante nella circoscrizione di residenza dell\u2019elettore e potr\u00e0 essere revocata con le medesime modalit\u00e0 ed entro gli stessi termini previsti per il suo esercizio. Qualora l\u2019opzione venga inviata per posta, l\u2019elettore ha l\u2019onere di accertarne la ricezione, da parte dell\u2019Ufficio consolare, entro il termine prescritto.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1038\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/circ-dait-001-servelet-16-01-2026-modulo-di-opzione-referendum-2026-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/circ-dait-001-servelet-16-01-2026-modulo-di-opzione-referendum-2026-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>circ-dait-001-servelet-16-01-2026-modulo-di-opzione-referendum-2026<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Scadenza presentazione domande 24 gennaio 2026&nbsp; Descrizione&nbsp; Per il referendum del 22 e 23 marzo 2026, gli elettori italiani residenti all\u2019estero, ai sensi della legge 27 dicembre 2001, n. 459 [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":1037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Scadenza presentazione domande 24 gennaio 2026&nbsp; Descrizione&nbsp; Per il referendum del 22 e 23 marzo 2026, gli elettori italiani residenti all\u2019estero, ai sensi della legge 27 dicembre 2001, n. 459 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T16:01:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T16:02:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/IMMAGINE-REFERENDUM-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero\",\"datePublished\":\"2026-01-20T16:01:32+00:00\",\"dateModified\":\"2026-01-20T16:02:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/\"},\"wordCount\":243,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/01\\\/IMMAGINE-REFERENDUM-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/\",\"name\":\"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/01\\\/IMMAGINE-REFERENDUM-1.jpg\",\"datePublished\":\"2026-01-20T16:01:32+00:00\",\"dateModified\":\"2026-01-20T16:02:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/01\\\/IMMAGINE-REFERENDUM-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/01\\\/IMMAGINE-REFERENDUM-1.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2026\\\/01\\\/20\\\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/","og_locale":"it_IT","og_type":"article","og_title":"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero - Lucoli","og_description":"Scadenza presentazione domande 24 gennaio 2026&nbsp; Descrizione&nbsp; Per il referendum del 22 e 23 marzo 2026, gli elettori italiani residenti all\u2019estero, ai sensi della legge 27 dicembre 2001, n. 459 [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-20T16:01:32+00:00","article_modified_time":"2026-01-20T16:02:50+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/IMMAGINE-REFERENDUM-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero","datePublished":"2026-01-20T16:01:32+00:00","dateModified":"2026-01-20T16:02:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/"},"wordCount":243,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/IMMAGINE-REFERENDUM-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/","url":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/","name":"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/IMMAGINE-REFERENDUM-1.jpg","datePublished":"2026-01-20T16:01:32+00:00","dateModified":"2026-01-20T16:02:50+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/IMMAGINE-REFERENDUM-1.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/01\/IMMAGINE-REFERENDUM-1.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2026\/01\/20\/consultazioni-referendarie-del-22-e-23-marzo-2026_voto-degli-italiani-residenti-allestero-iscritti-nellaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Consultazioni Referendarie del 22 e 23 marzo 2026. Voto degli Italiani residenti all\u2019estero"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001066"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/1033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=1033"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/1033\/revisions"}],"predecessor-version":[{"id":1036,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/1033\/revisions\/1036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/1037"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=1033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=1033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=1033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}