{"id":1343,"date":"2023-07-03T18:19:08","date_gmt":"2023-07-03T16:19:08","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/"},"modified":"2026-04-27T18:25:35","modified_gmt":"2026-04-27T16:25:35","slug":"strada-di-collegamento-lucoli-roio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/","title":{"rendered":"Strada di collegamento Lucoli &#8211; Roio"},"content":{"rendered":"<p><em>Lavori per la riqualificazione della strada di collegamento tra la frazione aquilana di Roio e il Comune di Lucoli<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Inizieranno luned\u00ec 8 maggio i lavori per la riqualificazione della strada di collegamento tra la frazione aquilana di Roio e il Comune di Lucoli, denominata \u201cvia Collecigliu\u201d. L\u2019intervento, finanziato con 400mila euro dal Comune dell\u2019Aquila sugli oltre tre chilometri di percorso, avr\u00e0 una durata di circa un mese e consisteranno nel rifacimento e messa in sicurezza del manto stradale, sistemazione delle scarpate, installazione di guard rail, realizzazione della segnaletica verticale e orizzontale e predisposizione delle condotte per futuri impianti di illuminazione e fibra ottica.<\/p>\n<p>\u201cUn\u2019opera fondamentale per il collegamento tra il nostro Comune e quello di Lucoli che agevoler\u00e0 lavoratori, studenti e quanti quotidianamente frequentano quella tratta, consentendo di accorciare notevolmente i tempi di percorrenza. \u00c8 il frutto di una significativa collaborazione attivata con l\u2019amministrazione comunale di Lucoli nell\u2019interesse delle nostre comunit\u00e0\u201d hanno commentato il sindaco dell\u2019Aquila,\u00a0<b>Pierluigi Biondi<\/b>,\u00a0e l\u2019assessore alle Opere pubbliche,\u00a0<b>Vito Colonna<\/b>.<\/p>\n<p>\u201cPer anni abbiamo atteso la sistemazione di questa strada, che storicamente collega Lucoli all\u2019Aquila attraversando il territorio di Roio. \u2013 hanno aggiunto il sindaco di Lucoli,\u00a0<b>Valter Chiappini<\/b>, e il vice sindaco\u00a0<b>Michelangelo Peretti<\/b>\u00a0\u2013 La sinergia con il Comune dell\u2019Aquila, che ringraziamo per aver mostrato sensibilit\u00e0 nei confronti di una problematica cos\u00ec sentita da parte dei cittadini, ha consentito di raggiungere questo importante risultato\u201d.<\/p>\n<p>Articolo di Abruzzo Web&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2023\/07\/Lavori-strada-Roio-Lucoli4.jpeg' alt='image'><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2023\/07\/Cartello-strada-Roio-Lucoli.jpeg' alt='image'><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2023\/07\/Lavori-strada-Roio-Lucoli1.jpeg' alt='image'><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2023\/07\/Lavori-strada-Roio-Lucoli2.jpeg' alt='image'><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2023\/07\/Lavori-strada-Roio-Lucoli3.jpeg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lavori per la riqualificazione della strada di collegamento tra la frazione aquilana di Roio e il Comune di Lucoli&nbsp; Descrizione&nbsp; Inizieranno luned\u00ec 8 maggio i lavori per la riqualificazione della [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":1345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strada di collegamento Lucoli - Roio - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strada di collegamento Lucoli - Roio - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Lavori per la riqualificazione della strada di collegamento tra la frazione aquilana di Roio e il Comune di Lucoli&nbsp; Descrizione&nbsp; Inizieranno luned\u00ec 8 maggio i lavori per la riqualificazione della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-03T16:19:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T16:25:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/04\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"657\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Strada di collegamento Lucoli &#8211; Roio\",\"datePublished\":\"2023-07-03T16:19:08+00:00\",\"dateModified\":\"2026-04-27T16:25:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/\"},\"wordCount\":253,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/04\\\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/\",\"name\":\"Strada di collegamento Lucoli - Roio - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/04\\\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg\",\"datePublished\":\"2023-07-03T16:19:08+00:00\",\"dateModified\":\"2026-04-27T16:25:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/04\\\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2026\\\/04\\\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg\",\"width\":920,\"height\":657},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2023\\\/07\\\/03\\\/strada-di-collegamento-lucoli-roio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strada di collegamento Lucoli &#8211; Roio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strada di collegamento Lucoli - Roio - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/","og_locale":"it_IT","og_type":"article","og_title":"Strada di collegamento Lucoli - Roio - Lucoli","og_description":"Lavori per la riqualificazione della strada di collegamento tra la frazione aquilana di Roio e il Comune di Lucoli&nbsp; Descrizione&nbsp; Inizieranno luned\u00ec 8 maggio i lavori per la riqualificazione della [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-07-03T16:19:08+00:00","article_modified_time":"2026-04-27T16:25:35+00:00","og_image":[{"width":920,"height":657,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/04\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Strada di collegamento Lucoli &#8211; Roio","datePublished":"2023-07-03T16:19:08+00:00","dateModified":"2026-04-27T16:25:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/"},"wordCount":253,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/04\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/","url":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/","name":"Strada di collegamento Lucoli - Roio - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/04\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg","datePublished":"2023-07-03T16:19:08+00:00","dateModified":"2026-04-27T16:25:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/04\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2026\/04\/Strada-Vado-Lucoli-Lucoli-Alto-copertina.jpg","width":920,"height":657},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2023\/07\/03\/strada-di-collegamento-lucoli-roio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Strada di collegamento Lucoli &#8211; Roio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001231"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"predecessor-version":[{"id":1344,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/1343\/revisions\/1344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/1345"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}