{"id":198,"date":"2024-08-14T17:46:58","date_gmt":"2024-08-14T15:46:58","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/?p=198"},"modified":"2024-08-18T07:54:31","modified_gmt":"2024-08-18T05:54:31","slug":"camminando-lucoli","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/","title":{"rendered":"RINVIATA Camminando Lucoli"},"content":{"rendered":"<p><em>RINVIATA A DATA DA DESTINARSI<br \/>\nDomenica 18 agosto ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale 584 km 11+700 alle ore 9.00, sosta nella frazione di Lucoli Alto, con degustazione dei prodotti tipici del Caseificio Campo Felice e arrivo presso l&#8217;Abbazia di San Giovanni Battista.<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Il percorso \u00e8 lungo circa 4,5 km, sviluppato principalmente lungo sentieri di montagna, che congiungono le diverse destinazioni da visitare<\/span><\/li>\n<li><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Per chi arriva in macchina: le auto verranno lasciate al punto di partenza e al temine della passaggiata verrete riaccompagnati a riprenderle<\/span><\/li>\n<li><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Si prega di indossare abbigliamento comodo, scarpe da ginnastica o da trekking, cappello e munirsi di acqua<\/span><\/li>\n<\/ul>\n<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\u00a0<\/span>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2024\/08\/Camminando-Lucoli.png' alt='image'><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>RINVIATA A DATA DA DESTINARSI Domenica 18 agosto ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;&nbsp; Descrizione&nbsp; Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RINVIATA Camminando Lucoli - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RINVIATA Camminando Lucoli - Lucoli\" \/>\n<meta property=\"og:description\" content=\"RINVIATA A DATA DA DESTINARSI Domenica 18 agosto ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;&nbsp; Descrizione&nbsp; Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-14T15:46:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-18T05:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/08\/Copertina-camminando-Lucoli-1-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2298\" \/>\n\t<meta property=\"og:image:height\" content=\"1523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"RINVIATA Camminando Lucoli\",\"datePublished\":\"2024-08-14T15:46:58+00:00\",\"dateModified\":\"2024-08-18T05:54:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/\"},\"wordCount\":123,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/08\\\/Copertina-camminando-Lucoli-1-1.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/\",\"name\":\"RINVIATA Camminando Lucoli - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/08\\\/Copertina-camminando-Lucoli-1-1.png\",\"datePublished\":\"2024-08-14T15:46:58+00:00\",\"dateModified\":\"2024-08-18T05:54:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/08\\\/Copertina-camminando-Lucoli-1-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/08\\\/Copertina-camminando-Lucoli-1-1.png\",\"width\":2298,\"height\":1523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/08\\\/14\\\/camminando-lucoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camminando Lucoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RINVIATA Camminando Lucoli - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/","og_locale":"it_IT","og_type":"article","og_title":"RINVIATA Camminando Lucoli - Lucoli","og_description":"RINVIATA A DATA DA DESTINARSI Domenica 18 agosto ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;&nbsp; Descrizione&nbsp; Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-08-14T15:46:58+00:00","article_modified_time":"2024-08-18T05:54:31+00:00","og_image":[{"width":2298,"height":1523,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/08\/Copertina-camminando-Lucoli-1-1-1.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"RINVIATA Camminando Lucoli","datePublished":"2024-08-14T15:46:58+00:00","dateModified":"2024-08-18T05:54:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/"},"wordCount":123,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/08\/Copertina-camminando-Lucoli-1-1.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/","url":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/","name":"RINVIATA Camminando Lucoli - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/08\/Copertina-camminando-Lucoli-1-1.png","datePublished":"2024-08-14T15:46:58+00:00","dateModified":"2024-08-18T05:54:31+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/08\/Copertina-camminando-Lucoli-1-1.png","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/08\/Copertina-camminando-Lucoli-1-1.png","width":2298,"height":1523},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/08\/14\/camminando-lucoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Camminando Lucoli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000617"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=198"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/198\/revisions"}],"predecessor-version":[{"id":202,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/198\/revisions\/202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/204"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}