{"id":222,"date":"2024-09-14T10:01:58","date_gmt":"2024-09-14T08:01:58","guid":{"rendered":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/"},"modified":"2024-09-14T10:01:58","modified_gmt":"2024-09-14T08:01:58","slug":"camminando-lucoli-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/","title":{"rendered":"Camminando Lucoli"},"content":{"rendered":"<p><em>Domenica 15 settembre ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale 584 km 11+700 alle ore 9.00, sosta nella frazione di Lucoli Alto, con degustazione dei prodotti tipici del Caseificio Campo Felice e arrivo presso l&#8217;Abbazia di San Giovanni Battista.<\/span><\/p>\n<ul>\n<li><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Il percorso \u00e8 lungo circa 4,5 km, sviluppato principalmente lungo sentieri di montagna, che congiungono le diverse destinazioni da visitare<\/span><\/li>\n<li><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Per chi arriva in macchina: le auto verranno lasciate al punto di partenza e al temine della passaggiata verrete riaccompagnati a riprenderle<\/span><\/li>\n<li><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Si prega di indossare abbigliamento comodo, scarpe da ginnastica o da trekking, cappello e munirsi di acqua<\/span><\/li>\n<\/ul>\n<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">La partecipazione \u00e8 libera e gratuita. \u00c8 gradita la prenotazione al numero +39 340 669 8639 CulturAquila<\/p>\n<p><\/span>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='http:\/\/comune.lucoli.aq.it\/wp-content\/uploads\/2024\/09\/Camminando-Lucoli-15-settembre.png' alt='image'><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Domenica 15 settembre ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;&nbsp; Descrizione&nbsp; Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale 584 km 11+700 alle ore [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camminando Lucoli - Lucoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camminando Lucoli - Lucoli\" \/>\n<meta property=\"og:description\" content=\"Domenica 15 settembre ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;&nbsp; Descrizione&nbsp; Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale 584 km 11+700 alle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lucoli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-14T08:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/09\/Copertina-camminando-Lucoli-15-settembre-1024x656.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Camminando Lucoli\",\"datePublished\":\"2024-09-14T08:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/09\\\/Copertina-camminando-Lucoli-15-settembre.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/\",\"name\":\"Camminando Lucoli - Lucoli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/09\\\/Copertina-camminando-Lucoli-15-settembre.png\",\"datePublished\":\"2024-09-14T08:01:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/09\\\/Copertina-camminando-Lucoli-15-settembre.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/wp-content\\\/uploads\\\/sites\\\/233\\\/2024\\\/09\\\/Copertina-camminando-Lucoli-15-settembre.png\",\"width\":3005,\"height\":1926},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/2024\\\/09\\\/14\\\/camminando-lucoli-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camminando Lucoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/lucoli\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camminando Lucoli - Lucoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/","og_locale":"it_IT","og_type":"article","og_title":"Camminando Lucoli - Lucoli","og_description":"Domenica 15 settembre ore 9.00 passeggiata storico-naturalistica alla scoperta del territorio con l&#8217;associazione &#8220;CulturAquila&#8221;&nbsp; Descrizione&nbsp; Partenza dal parcheggio adiacente alla Chiesa di Sant\u2019Antonio, strada statale 584 km 11+700 alle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/","og_site_name":"Lucoli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-09-14T08:01:58+00:00","og_image":[{"width":1024,"height":656,"url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/09\/Copertina-camminando-Lucoli-15-settembre-1024x656.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Camminando Lucoli","datePublished":"2024-09-14T08:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/09\/Copertina-camminando-Lucoli-15-settembre.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/","url":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/","name":"Camminando Lucoli - Lucoli","isPartOf":{"@id":"https:\/\/comunicacity.net\/lucoli\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/09\/Copertina-camminando-Lucoli-15-settembre.png","datePublished":"2024-09-14T08:01:58+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#primaryimage","url":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/09\/Copertina-camminando-Lucoli-15-settembre.png","contentUrl":"https:\/\/comunicacity.net\/lucoli\/wp-content\/uploads\/sites\/233\/2024\/09\/Copertina-camminando-Lucoli-15-settembre.png","width":3005,"height":1926},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/lucoli\/2024\/09\/14\/camminando-lucoli-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/lucoli\/"},{"@type":"ListItem","position":2,"name":"Camminando Lucoli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/lucoli\/#website","url":"https:\/\/comunicacity.net\/lucoli\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/lucoli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/lucoli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/lucoli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/lucoli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/lucoli\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000640"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/posts\/222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/categories?post=222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/lucoli\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}